{"id":42536,"date":"2024-10-17T10:07:43","date_gmt":"2024-10-17T09:07:43","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=42536"},"modified":"2024-10-18T15:07:27","modified_gmt":"2024-10-18T14:07:27","slug":"amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias","status":"publish","type":"post","link":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/","title":{"rendered":"Amparo Bella: \u00abLas muestras de cine realizado por mujeres a\u00fan son necesarias\u00bb"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La 27 edici\u00f3n de la Muestra Internacional de Cine Realizado por Mujeres se desarrolla en Zaragoza del 18 al 27 de octubre. MIZ entrevista a una de sus art\u00edfices<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>La <a href=\"https:\/\/www.muestracinemujereszgz.org\/\">Muestra Internacional de Cine Realizado por Mujeres<\/a> es un <strong>peque\u00f1o cl\u00e1sico de la oferta cultural de Zaragoza<\/strong>. <a href=\"https:\/\/madeinzaragoza.es\/\">MIZ<\/a> entrevista a Amparo Bella, una de las integrantes de su equipo organizador con motivo de la entrada en escena de su <strong>27 edici\u00f3n<\/strong>. Se desarrolla <strong>del 18 al 27 de octubre<\/strong> en sesiones con entrada libre en la Filmoteca, el Centro de Historias y la Casa de la Mujer.<\/p>\n\n\n\n<p><strong>Que una peque\u00f1a muestra cinematogr\u00e1fica se vaya acercando al 30 aniversario resulta meritorio.<\/strong><\/p>\n\n\n\n<p>Las claves quiz\u00e1 sean la persistencia y la maleabilidad en cuanto a que el equipo se va renovando y va cambiando y se mantiene la ilusi\u00f3n por ofrecer un producto cultural que visibilice la cultura cinematogr\u00e1fica realizada por mujeres. Todo ello a pesar de las dificultades, ya que no es f\u00e1cil sacar adelante un producto cultural como este en la ciudad. Ah\u00ed seguimos, ah\u00ed estamos y esperamos seguir muchos m\u00e1s a\u00f1os.<\/p>\n\n\n\n<p><strong>Detr\u00e1s de todo sigue presente la Asociaci\u00f3n Cultural Odeonia.<\/strong><\/p>\n\n\n\n<p>De la organizaci\u00f3n de la Muestra Internacional de Cine Realizado por Mujeres nos encargamos el equipo de Odeonia, asociaci\u00f3n que siempre ha estado integrada en el Seminario Interdisciplinar de Estudios de la Mujer (SIEM) de la Universidad de Zaragoza. Como colaboradores y patrocinadores principales contamos con el Ayuntamiento, el Gobierno de Arag\u00f3n y el Instituto Aragon\u00e9s de la Mujer. Y colaboran de manera importante Ara Film Fest, la Red de Festivales y Muestras de Cine de Arag\u00f3n, TRAMA (Coordinadora de Muestras de festivales de cine, v\u00eddeo y multimedia realizados por mujeres). Tambi\u00e9n quiero mencionar la colaboraci\u00f3n en una de las sesiones con el Centro de Inserci\u00f3n Sociolaboral para Mujeres Tramalena, perteneciente a la Fundaci\u00f3n el Tranv\u00eda y que ha abierto una campa\u00f1a de &#8216;crowdfunding&#8217;.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"696\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/programacion-27-muestra-mujeres-1024x696.jpg\" alt=\"Programaci\u00f3n de la 27 Muestra Internacional de Cine Realizado por Mujeres\" class=\"wp-image-42540\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/programacion-27-muestra-mujeres-1024x696.jpg 1024w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/programacion-27-muestra-mujeres-450x306.jpg 450w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/programacion-27-muestra-mujeres-768x522.jpg 768w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/programacion-27-muestra-mujeres.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Programaci\u00f3n de la 27 Muestra Internacional de Cine Realizado por Mujeres<\/figcaption><\/figure><\/div>\n\n\n<p><strong>Cada a\u00f1o, con peque\u00f1os retoques, la muestra mantiene su esencia reconocible.<\/strong><\/p>\n\n\n\n<p>En esta edici\u00f3n mantenemos nuestras secciones habituales, con Panorama de ficci\u00f3n, con nueve pel\u00edculas, y Documenta, con cinco t\u00edtulos, al frente. El cine realizado por mujeres ha dado un salto cualitativo en cuanto a que ahora, en el marco de la mayor visibilidad y de los premios, no solo podemos ver obras que aluden a problemas sociales y conflictos existenciales o que tratan aspectos de memoria historia o nos descubren figuras, sino que tienen que ver con lo que podemos decir que es el empoderamiento de las mujeres, plasmado desde diferentes v\u00edas. La selecci\u00f3n de la Muestra refleja esa realidad y se ve por ejemplo en las comedias <em>Iris<\/em>, elegida para la inauguraci\u00f3n y que expone el deseo sexual femenino a trav\u00e9s de una mujer de mediana edad que no tiene las expectativas cumplidas y empieza un camino para experimentar, y <em>What a Feeling<\/em>, sobre el encuentro y la relaci\u00f3n que se establece entre dos mujeres de distintas culturas.<\/p>\n\n\n\n<p><strong>Mia Hansen-Love (<em>Una bonita ma\u00f1ana<\/em>), Alice Rohrwacher (<em>La quimera<\/em>), Jessica Hausner (<em>Club Zero<\/em>)\u2026 La secci\u00f3n Panorama es de las m\u00e1s potentes de los \u00faltimos a\u00f1os.<\/strong><\/p>\n\n\n\n<p>Desde el origen de la Muestra Internacional de Cine Realizado por Mujeres los distintos equipos se han esforzado por tener una programaci\u00f3n, sobre todo en Panorama, potente. De esta secci\u00f3n, adem\u00e1s de esos t\u00edtulos, de la pel\u00edcula inaugural de Caroline Vignal y de <em>What a Feeling<\/em> tambi\u00e9n destacar\u00eda <em>La bicicleta verde<\/em>, de Haifaa Al-Mansour, pionera en Arabia Saud\u00ed. Aparte, en Documenta est\u00e1 <em>Reas<\/em>, documental argentino que habla de mujeres trans en una c\u00e1rcel y del producto cultural que desarrollan. Y, sobre lo que hemos comentado de los cambios en el cine realizado por mujeres, hay que mencionar, de la secci\u00f3n Aragonesas, <em>Dec\u00edan que era bruja<\/em>, de Judith Prat, y <em>Aconcagua en femenino<\/em>, sobre unas mujeres monta\u00f1eras e impulsado por Astrid Garc\u00eda Graells.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"900\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/cartel-27-muestra-mujeres.jpg\" alt=\"Cartel de la 27 Muestra Internacional de Cine Realizado por Mujeres, obra de Amor P\u00e9rez Bea\" class=\"wp-image-42545\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/cartel-27-muestra-mujeres.jpg 636w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/cartel-27-muestra-mujeres-318x450.jpg 318w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption class=\"wp-element-caption\">Cartel de la 27 Muestra Internacional de Cine Realizado por Mujeres (Amor P\u00e9rez Bea)<\/figcaption><\/figure><\/div>\n\n\n<p><strong>\u00bfC\u00f3mo es la organizaci\u00f3n interna en muestras cinematogr\u00e1ficas de este tama\u00f1o?<\/strong><\/p>\n\n\n\n<p>Es un trabajo continuado a lo largo del a\u00f1o. En enero se abre la convocatoria de Cortos en femenino, en la que participamos siete muestras que despu\u00e9s exhibimos los t\u00edtulos m\u00e1s votados. En marzo tenemos que realizar los proyectos para solicitar las subvenciones as\u00ed como mirar la programaci\u00f3n para que al menos una parte est\u00e9 cerrada antes del verano. Para la selecci\u00f3n escribimos a las distribuidoras y estamos atentas a lo que se ha proyectado en a\u00f1os anteriores en festivales de Espa\u00f1a y tambi\u00e9n de Francia. Aparece la dificultad de que, si no han pasado por Espa\u00f1a, muchas veces tenemos que encargarnos del subtitulado. Por otro lado, tambi\u00e9n est\u00e1n los trabajos de dise\u00f1o, este a\u00f1o obra (el cartel y el v\u00eddeo cortinilla) de Amor P\u00e9rez Bea, una dise\u00f1adora espectacular.<\/p>\n\n\n\n<p><strong>La mirada creativa femenina por fin ha ganado, con merecimiento, consideraci\u00f3n en la ficci\u00f3n audiovisual. No obstante, parece que los espacios de difusi\u00f3n siguen siendo necesarios.<\/strong><\/p>\n\n\n\n<p>Estamos viviendo una \u00e9poca dorada en la que se visibilizan mujeres directoras de una categor\u00eda inmensa y que creo que marca un antes y un despu\u00e9s. En Espa\u00f1a la vemos por ejemplo en cartelera con las aragonesas Paula Ortiz (<em>La virgen roja<\/em>) y Pilar Palomero (<em>Los destellos<\/em>) y con Ic\u00edar Bolla\u00edn (<em>Soy Nevenka<\/em>) y Arantxa Echevarr\u00eda (<em>La infiltrada<\/em>). Cuando empezamos hace 27 a\u00f1os el cine realizado por mujeres se ve\u00eda como cine de mujeres, como algo sectorial, con esa etiqueta. Los tiempos han cambiado y hay m\u00e1s circuitos y plataformas y las brechas de g\u00e9nero se han roto, aunque a su manera siguen existiendo. A veces nos dicen que ahora con el \u00e9xito de las mujeres directoras nos preguntan si todav\u00eda son necesarias las muestras de cine realizado por mujeres, y nosotras decimos que s\u00ed porque sigue habiendo mucho cine fuera de los circuitos que de otro modo no se ver\u00eda y que incluso en las plataformas no es objeto de suficiente difusi\u00f3n.<\/p>\n\n\n\n<p><strong>La Zaragoza cinematogr\u00e1fica presenta la singularidad de que cuenta varias opciones y muestras. La oferta es diversa pero a la vez todo est\u00e1 muy atomizado. \u00bfCu\u00e1l ser\u00eda el camino a seguir? <\/strong><\/p>\n\n\n\n<p>Varias muestras llevamos muchos a\u00f1os, caso de Zinentiendo, Ecozine o La Mirada Tab\u00fa, y tambi\u00e9n el Festival de Cine de Zaragoza. El camino, en lugar de querer inventarse cosas nuevas, tendr\u00eda que ir hacia un mayor respaldo institucional y econ\u00f3mico a estas muestras que han demostrado sobradamente que saben traer buen cine, que contribuyen a dar visibilidad y que exhiben productos culturales que en su mayor parte no se pueden ver de otra manera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 27 edici\u00f3n de la Muestra Internacional de Cine Realizado por Mujeres se desarrolla en Zaragoza del 18 al 27 de octubre. MIZ entrevista a una de sus art\u00edfices La Muestra Internacional de Cine Realizado por Mujeres es un peque\u00f1o cl\u00e1sico de la oferta cultural de Zaragoza. MIZ entrevista a Amparo Bella, una de las &hellip; <a href=\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAmparo Bella: \u00abLas muestras de cine realizado por mujeres a\u00fan son necesarias\u00bb\u00bb<\/span><\/a><\/p>\n","protected":false},"author":59,"featured_media":42537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[829],"tags":[2384,2819,2378],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Las muestras de cine realizado por mujeres a\u00fan son necesarias&quot;<\/title>\n<meta name=\"description\" content=\"MIZ entrevista a Amparo Bella, miembro de la 27 Muestra Internacional de Cine Realizado por Mujeres, en Zaragoza hasta el 27 de octubre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Las muestras de cine realizado por mujeres a\u00fan son necesarias&quot;\" \/>\n<meta property=\"og:description\" content=\"MIZ entrevista a Amparo Bella, miembro de la 27 Muestra Internacional de Cine Realizado por Mujeres, en Zaragoza hasta el 27 de octubre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T09:07:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T14:07:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/Amparo-Bella-Muestra-mujeres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"904\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enrique Abenia\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@Enrique_Abenia\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enrique Abenia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\"},\"author\":{\"name\":\"Enrique Abenia\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523\"},\"headline\":\"Amparo Bella: \u00abLas muestras de cine realizado por mujeres a\u00fan son necesarias\u00bb\",\"datePublished\":\"2024-10-17T09:07:43+00:00\",\"dateModified\":\"2024-10-18T14:07:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\"},\"wordCount\":1192,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"Cine realizado por mujeres\",\"cine Zaragoza\",\"festivales de cine Zaragoza\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\",\"name\":\"\\\"Las muestras de cine realizado por mujeres a\u00fan son necesarias\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2024-10-17T09:07:43+00:00\",\"dateModified\":\"2024-10-18T14:07:27+00:00\",\"description\":\"MIZ entrevista a Amparo Bella, miembro de la 27 Muestra Internacional de Cine Realizado por Mujeres, en Zaragoza hasta el 27 de octubre\",\"breadcrumb\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amparo Bella: \u00abLas muestras de cine realizado por mujeres a\u00fan son necesarias\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523\",\"name\":\"Enrique Abenia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g\",\"caption\":\"Enrique Abenia\"},\"description\":\"Periodista aut\u00f3nomo. Cr\u00edtico de \u2018Heraldo de Arag\u00f3n\u2019, tambi\u00e9n escribe en 'Cineman\u00eda' y en 20bits, donde analiza smartphones.\",\"sameAs\":[\"https:\/\/twitter.com\/Enrique_Abenia\"],\"url\":\"https:\/\/madeinzaragoza.es\/blog\/author\/enriqueabenia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Las muestras de cine realizado por mujeres a\u00fan son necesarias\"","description":"MIZ entrevista a Amparo Bella, miembro de la 27 Muestra Internacional de Cine Realizado por Mujeres, en Zaragoza hasta el 27 de octubre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/","og_locale":"es_ES","og_type":"article","og_title":"\"Las muestras de cine realizado por mujeres a\u00fan son necesarias\"","og_description":"MIZ entrevista a Amparo Bella, miembro de la 27 Muestra Internacional de Cine Realizado por Mujeres, en Zaragoza hasta el 27 de octubre","og_url":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2024-10-17T09:07:43+00:00","article_modified_time":"2024-10-18T14:07:27+00:00","og_image":[{"width":1200,"height":904,"url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/10\/Amparo-Bella-Muestra-mujeres.jpg","type":"image\/jpeg"}],"author":"Enrique Abenia","twitter_card":"summary","twitter_creator":"@Enrique_Abenia","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Enrique Abenia","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#article","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/"},"author":{"name":"Enrique Abenia","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523"},"headline":"Amparo Bella: \u00abLas muestras de cine realizado por mujeres a\u00fan son necesarias\u00bb","datePublished":"2024-10-17T09:07:43+00:00","dateModified":"2024-10-18T14:07:27+00:00","mainEntityOfPage":{"@id":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/"},"wordCount":1192,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["Cine realizado por mujeres","cine Zaragoza","festivales de cine Zaragoza"],"articleSection":["Cultura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/","url":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/","name":"\"Las muestras de cine realizado por mujeres a\u00fan son necesarias\"","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2024-10-17T09:07:43+00:00","dateModified":"2024-10-18T14:07:27+00:00","description":"MIZ entrevista a Amparo Bella, miembro de la 27 Muestra Internacional de Cine Realizado por Mujeres, en Zaragoza hasta el 27 de octubre","breadcrumb":{"@id":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/madeinzaragoza.es\/blog\/amparo-bella-muestras-cine-realizado-por-mujeres-todavia-son-necesarias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Amparo Bella: \u00abLas muestras de cine realizado por mujeres a\u00fan son necesarias\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523","name":"Enrique Abenia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g","caption":"Enrique Abenia"},"description":"Periodista aut\u00f3nomo. Cr\u00edtico de \u2018Heraldo de Arag\u00f3n\u2019, tambi\u00e9n escribe en 'Cineman\u00eda' y en 20bits, donde analiza smartphones.","sameAs":["https:\/\/twitter.com\/Enrique_Abenia"],"url":"https:\/\/madeinzaragoza.es\/blog\/author\/enriqueabenia\/"}]}},"_links":{"self":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/42536"}],"collection":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=42536"}],"version-history":[{"count":7,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/42536\/revisions"}],"predecessor-version":[{"id":42550,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/42536\/revisions\/42550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/42537"}],"wp:attachment":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=42536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=42536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=42536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}