{"id":24138,"date":"2019-04-08T20:57:05","date_gmt":"2019-04-08T19:57:05","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=24138"},"modified":"2019-04-09T20:58:47","modified_gmt":"2019-04-09T19:58:47","slug":"isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias","status":"publish","type":"post","link":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/","title":{"rendered":"Isabel Pe\u00f1a: \u00abLa sociedad ya demanda otro tipo de historias\u00bb"},"content":{"rendered":"<h2>La guionista zaragozana habla en esta entrevista de su oficio, de la visi\u00f3n femenina, de su evoluci\u00f3n profesional, del Goya por \u2018El reino\u2019, de lo que el cin\u00e9filo puede esperar de \u2018Madre\u2019 y del audiovisual aragon\u00e9s<\/h2>\n<p>&nbsp;<\/p>\n<p>Al igual que otros t\u00edtulos recientes, <strong>\u2018Que Dios nos perdone\u2019 <\/strong>(2016)<strong> y \u2018El reino\u2019 <\/strong>(2018) escenifican el nivel alcanzado por el cine espa\u00f1ol en el terreno del \u2018thriller\u2019. <strong>Los dos notables y estimulantes filmes tienen parte de autor\u00eda aragonesa, la de la guionista Isabel Pe\u00f1a<\/strong>, socia creativa del director Rodrigo Sorogoyen. Licenciada en Comunicaci\u00f3n Audiovisual por la Universidad de Navarra y especializada en gui\u00f3n por la ECAM, la zaragozana comenz\u00f3 en el oficio en las series \u2018Impares\u2019 (2008), \u2018La pecera de Eva\u2019 (2010) y \u2018Fr\u00e1giles\u2019 (2012). <strong>Despunt\u00f3 con \u2018Stockholm\u2019<\/strong> (2013), pel\u00edcula con la que empezaron a llegar unos premios y nominaciones que se intensificar\u00edan en sus dos trabajos sucesivos. <strong>El Goya ganado por su retrato de la corrupci\u00f3n en \u2018El reino\u2019 y el reconocimiento del Festival de Huesca simbolizan su gran momento profesional<\/strong> y le sirven de impulso en una actividad que ha seguido con la versi\u00f3n en largometraje de <strong>\u2018Madre\u2019, cuyo estreno est\u00e1 previsto en oto\u00f1o<\/strong>. <a href=\"http:\/\/madeinzaragoza.es\/blog\/teresa-azcona-el-feminismo-forma-de-estar-en-el-mundo-y-una-actitud\/\">En unas semanas enfocadas a visibilizar a mujeres de distintos \u00e1mbitos, Made in Zaragoza acerca su figura en esta entrevista.<\/a><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_24140\" aria-describedby=\"caption-attachment-24140\" style=\"width: 840px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24140\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/Isabel-Pe\u00f1a-con-Goya-1024x732.jpg\" alt=\"Isabel Pe\u00f1a, con el Goya obtenido por el gui\u00f3n de 'El reino' (autor: Miguel C\u00f3rdoba)\" width=\"840\" height=\"600\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/Isabel-Pe\u00f1a-con-Goya.jpg 1024w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/Isabel-Pe\u00f1a-con-Goya-300x214.jpg 300w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/Isabel-Pe\u00f1a-con-Goya-768x549.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption id=\"caption-attachment-24140\" class=\"wp-caption-text\">Isabel Pe\u00f1a, junto a Rodrigo Sorogoyen, con el Goya ganado por el gui\u00f3n de &#8216;El reino&#8217; (autor: Miguel C\u00f3rdoba)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>En cuanto a visibilidad, el trabajo del guionista suele quedar en segundo t\u00e9rmino debido a que la autor\u00eda se focaliza en la figura del director. \u00bfEl condicionante se ha empezado a rebajar? \u00bfC\u00f3mo ve la situaci\u00f3n del oficio en Espa\u00f1a?<\/strong><\/p>\n<p>S\u00ed, est\u00e1 cambiando. En parte gracias a las series, donde la figura del creador o \u2018showrunner\u2019 se est\u00e1 haciendo fuerte. La situaci\u00f3n sigue siendo la de un oficio poco respetado. Por poner un ejemplo: conozco pocos oficios en los que se d\u00e9 por hecho que trabajas gratis. Como si nuestro tiempo y esfuerzo creativo no tuviesen valor.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El presente de reivindicaci\u00f3n femenina se canaliza en el cine y empieza a prestarse m\u00e1s atenci\u00f3n a la visi\u00f3n de las mujeres. \u00bfEse cambio ha llegado tambi\u00e9n al \u00e1mbito del gui\u00f3n?<\/strong><\/p>\n<p>S\u00ed. Hay m\u00e1s mujeres guionistas. Pero tambi\u00e9n m\u00e1s productoras y m\u00e1s directoras. Pero sobre todo es que la sociedad ya demanda otro tipo de historias.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfC\u00f3mo afronta una guionista la identificaci\u00f3n con el momento social y el compromiso con la defensa de la igualdad al construir las historias?<\/strong><\/p>\n<p>Siendo quien eres e introduciendo en las historias tus propios sistemas de pensamiento. Al menos en mi caso. No es algo premeditado, es algo que es o no.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Dentro de la l\u00f3gica satisfacci\u00f3n, qu\u00e9 emociona m\u00e1s, \u00bfla primera nominaci\u00f3n al Goya o el premio cosechado en la segunda oportunidad?<\/strong><\/p>\n<p>Esto es un poco a qui\u00e9n quieres m\u00e1s, si a mam\u00e1 o a pap\u00e1\u2026 Dir\u00eda que la nominaci\u00f3n. Era nuestra segunda peli y adem\u00e1s coincidi\u00f3 con un a\u00f1o con candidaturas muy potentes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfEl Goya y el reconocimiento en festivales allanan el camino de los proyectos futuros?<\/strong><\/p>\n<p>No es algo radical, pero s\u00ed se nota. Yo lo estoy viendo con los actores. Ese \u2018casting\u2019 ideal que imaginas mientras trabajas, de pronto es m\u00e1s f\u00e1cil de conseguir porque esos actores ya nos conocen y tambi\u00e9n quieren trabajar con nosotros.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_24141\" aria-describedby=\"caption-attachment-24141\" style=\"width: 626px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24141\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/Isabel-Pe\u00f1a-3.jpg\" alt=\"Isabel Pe\u00f1a posa con motivo de la presentaci\u00f3n de 'El reino' el a\u00f1o pasado en San Sebasti\u00e1n (autor: Gari Garaialde)\" width=\"626\" height=\"396\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/Isabel-Pe\u00f1a-3.jpg 626w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/Isabel-Pe\u00f1a-3-300x190.jpg 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption id=\"caption-attachment-24141\" class=\"wp-caption-text\">Isabel Pe\u00f1a posa con motivo de la presentaci\u00f3n de &#8216;El reino&#8217; el a\u00f1o pasado en San Sebasti\u00e1n (autor: Gari Garaialde)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 siente al analizar su recorrido profesional desde que despunt\u00f3 con \u2018Stockholm\u2019?<\/strong><\/p>\n<p>Muchas cosas\u2026 Creo que soy muy afortunada, pero tambi\u00e9n siento que las decisiones m\u00e1s importantes fueron las adecuadas.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00bfC\u00f3mo es el proceso de trabajo conjunto con Rodrigo Sorogoyen?<\/strong><\/p>\n<p>Emocionante, exigente, adictivo\u2026 Tengo mucha suerte.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 puede esperar el cin\u00e9filo de la versi\u00f3n en largometraje de \u2018Madre\u2019?<\/strong><\/p>\n<p>Me gusta la apreciaci\u00f3n de \u2018cin\u00e9filo\u2019. Por nuestra trayectoria y por la naturaleza del cortometraje, supongo que espera un \u2018thriller\u2019, pero se va a encontrar algo muy distinto. \u2018Madre\u2019 es una pel\u00edcula peque\u00f1a y extra\u00f1a donde son m\u00e1s importantes los personajes o las atm\u00f3sferas que la trama.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Desde hace a\u00f1os vive en Madrid pero mantiene el v\u00ednculo con Arag\u00f3n. \u00bfC\u00f3mo valora la evoluci\u00f3n del audiovisual aragon\u00e9s? \u00bfLe ilusionar\u00eda desarrollar alg\u00fan proyecto en su tierra?<\/strong><\/p>\n<p>Estando en Madrid he conocido a gente aragonesa que est\u00e1 haciendo cortos y documentales muy interesantes. En cuanto a la segunda pregunta, si el proyecto es bueno, claro que me gustar\u00eda desarrollarlo en Arag\u00f3n.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>M\u00e1s de un zaragocista le habr\u00e1 agradecido el homenaje a los h\u00e9roes de Par\u00eds en \u2018El reino\u2019. \u00bfQu\u00e9 le anim\u00f3 a establecer ese gui\u00f1o?<\/strong><\/p>\n<p>Fue algo muy espont\u00e1neo. Est\u00e1bamos buscando un marco para esa escena en la que un personaje tiene que hablar, decir cualquier cosa para comprobar el funcionamiento de la grabadora. Y me sali\u00f3. Se lo propuse a Rodrigo y le encant\u00f3.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guionista zaragozana habla en esta entrevista de su oficio, de la visi\u00f3n femenina, de su evoluci\u00f3n profesional, del Goya por \u2018El reino\u2019, de lo que el cin\u00e9filo puede esperar de \u2018Madre\u2019 y del audiovisual aragon\u00e9s &nbsp; Al igual que otros t\u00edtulos recientes, \u2018Que Dios nos perdone\u2019 (2016) y \u2018El reino\u2019 (2018) escenifican el nivel &hellip; <a href=\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abIsabel Pe\u00f1a: \u00abLa sociedad ya demanda otro tipo de historias\u00bb\u00bb<\/span><\/a><\/p>\n","protected":false},"author":59,"featured_media":24139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[829,6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Isabel Pe\u00f1a: \u201cLa sociedad ya demanda otro tipo de historias\u201d<\/title>\n<meta name=\"description\" content=\"Made in Zaragoza entrevista a la guionista aragonesa Isabel Pe\u00f1a, en un gran momento profesional tras el Goya ganado por la notable &#039;El reino&#039;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isabel Pe\u00f1a: \u201cLa sociedad ya demanda otro tipo de historias\u201d\" \/>\n<meta property=\"og:description\" content=\"Made in Zaragoza entrevista a la guionista aragonesa Isabel Pe\u00f1a, en un gran momento profesional tras el Goya ganado por la notable &#039;El reino&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-08T19:57:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-09T19:58:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/foto-Isabel-Pen\u0303a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enrique Abenia\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@Enrique_Abenia\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enrique Abenia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\"},\"author\":{\"name\":\"Enrique Abenia\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523\"},\"headline\":\"Isabel Pe\u00f1a: \u00abLa sociedad ya demanda otro tipo de historias\u00bb\",\"datePublished\":\"2019-04-08T19:57:05+00:00\",\"dateModified\":\"2019-04-09T19:58:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\"},\"wordCount\":906,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"articleSection\":[\"Cultura\",\"Gente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\",\"name\":\"Isabel Pe\u00f1a: \u201cLa sociedad ya demanda otro tipo de historias\u201d\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2019-04-08T19:57:05+00:00\",\"dateModified\":\"2019-04-09T19:58:47+00:00\",\"description\":\"Made in Zaragoza entrevista a la guionista aragonesa Isabel Pe\u00f1a, en un gran momento profesional tras el Goya ganado por la notable 'El reino'\",\"breadcrumb\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isabel Pe\u00f1a: \u00abLa sociedad ya demanda otro tipo de historias\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523\",\"name\":\"Enrique Abenia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g\",\"caption\":\"Enrique Abenia\"},\"description\":\"Periodista aut\u00f3nomo. Cr\u00edtico de \u2018Heraldo de Arag\u00f3n\u2019, tambi\u00e9n escribe en 'Cineman\u00eda' y en 20bits, donde analiza smartphones.\",\"sameAs\":[\"https:\/\/twitter.com\/Enrique_Abenia\"],\"url\":\"https:\/\/madeinzaragoza.es\/blog\/author\/enriqueabenia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isabel Pe\u00f1a: \u201cLa sociedad ya demanda otro tipo de historias\u201d","description":"Made in Zaragoza entrevista a la guionista aragonesa Isabel Pe\u00f1a, en un gran momento profesional tras el Goya ganado por la notable 'El reino'","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/","og_locale":"es_ES","og_type":"article","og_title":"Isabel Pe\u00f1a: \u201cLa sociedad ya demanda otro tipo de historias\u201d","og_description":"Made in Zaragoza entrevista a la guionista aragonesa Isabel Pe\u00f1a, en un gran momento profesional tras el Goya ganado por la notable 'El reino'","og_url":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2019-04-08T19:57:05+00:00","article_modified_time":"2019-04-09T19:58:47+00:00","og_image":[{"width":992,"height":1000,"url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/03\/foto-Isabel-Pen\u0303a.jpg","type":"image\/jpeg"}],"author":"Enrique Abenia","twitter_card":"summary","twitter_creator":"@Enrique_Abenia","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Enrique Abenia","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#article","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/"},"author":{"name":"Enrique Abenia","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523"},"headline":"Isabel Pe\u00f1a: \u00abLa sociedad ya demanda otro tipo de historias\u00bb","datePublished":"2019-04-08T19:57:05+00:00","dateModified":"2019-04-09T19:58:47+00:00","mainEntityOfPage":{"@id":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/"},"wordCount":906,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"articleSection":["Cultura","Gente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/","url":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/","name":"Isabel Pe\u00f1a: \u201cLa sociedad ya demanda otro tipo de historias\u201d","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2019-04-08T19:57:05+00:00","dateModified":"2019-04-09T19:58:47+00:00","description":"Made in Zaragoza entrevista a la guionista aragonesa Isabel Pe\u00f1a, en un gran momento profesional tras el Goya ganado por la notable 'El reino'","breadcrumb":{"@id":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/madeinzaragoza.es\/blog\/isabel-pena-la-sociedad-ya-demanda-otro-tipo-de-historias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Isabel Pe\u00f1a: \u00abLa sociedad ya demanda otro tipo de historias\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b4cf98cbc61a51fb48dbdab258a8c523","name":"Enrique Abenia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a747099e3518ccf440789a57b07dd884?s=96&d=mm&r=g","caption":"Enrique Abenia"},"description":"Periodista aut\u00f3nomo. Cr\u00edtico de \u2018Heraldo de Arag\u00f3n\u2019, tambi\u00e9n escribe en 'Cineman\u00eda' y en 20bits, donde analiza smartphones.","sameAs":["https:\/\/twitter.com\/Enrique_Abenia"],"url":"https:\/\/madeinzaragoza.es\/blog\/author\/enriqueabenia\/"}]}},"_links":{"self":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/24138"}],"collection":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=24138"}],"version-history":[{"count":5,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/24138\/revisions"}],"predecessor-version":[{"id":24144,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/24138\/revisions\/24144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/24139"}],"wp:attachment":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=24138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=24138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=24138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}