{"id":23153,"date":"2019-01-04T20:46:43","date_gmt":"2019-01-04T19:46:43","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=23153"},"modified":"2019-01-07T14:04:00","modified_gmt":"2019-01-07T13:04:00","slug":"entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo","status":"publish","type":"post","link":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/","title":{"rendered":"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo"},"content":{"rendered":"<p><a href=\"http:\/\/madeinzaragoza.es\/colaboradores\/autor.php?id=4\" target=\"_blank\" rel=\"noopener\"><strong>Enrique Abenia<\/strong><\/a> es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual e<strong>s Licenciado en Periodismo<\/strong> por la <strong>Universidad de Navarra<\/strong> y cuenta ya con <strong>m\u00e1s de doce a\u00f1os<\/strong> de experiencia profesional en prensa.<\/p>\n<p>Podemos leer sus cr\u00edticas cinematogr\u00e1ficas en la edici\u00f3n impresa de &#8216;<strong>Heraldo de Arag\u00f3n<\/strong>&#8216; desde 2012. Heraldo es un medio al que siempre ha estado vinculado ya que antes y durante cinco a\u00f1os trabaj\u00f3 como <strong>redactor<\/strong> en varias secciones del peri\u00f3dico.<\/p>\n<p>Tambi\u00e9n ha colabora en temas de cine con diversos programas de radio. Actualmente habla de cine en &#8216;<strong>Micr\u00f3fono Abierto<\/strong>&#8216;, en <strong>La 8 Zaragoza<\/strong>.<br \/>\nAnteriormente se encarg\u00f3 de la prensa de los <strong>Premios Sim\u00f3n<\/strong> y ha colaborado tambi\u00e9n con el <strong>Festival de Cine de Zaragoza.<\/strong><\/p>\n<p>Por si no fuera poco tambi\u00e9n crea contenidos de otros temas, faceta en la que se sigue desarrollando.<\/p>\n<p>Zaragocista sufridor, es tambi\u00e9n tertuliano habitual de los partidos del <strong>Real Zaragoza<\/strong> en <strong>Onda Aragonesa.\u00a0<\/strong><\/p>\n<p>Con este curr\u00edculum tan impresionante, vamos a conocer un poco m\u00e1s a Enrique.<\/p>\n<p><strong>Qu\u00e9 fue primero, \u00bfla vocaci\u00f3n de periodista o el cin\u00e9filo?<\/strong><\/p>\n<p>De ni\u00f1o y adolescente ya ve\u00eda bastante cine y me encantaba conocer los nombres de los actores de las pel\u00edculas que me gustaban, tanto protagonistas como secundarios, y memorizar sus filmograf\u00edas. A su manera, era una enciclopedia cin\u00e9fila. A su vez, mostraba habilidad para la redacci\u00f3n y en los trabajos en grupo anhelaba encargarme de esa parte. Siempre me ha cautivado el proceso creativo vinculado a la escritura y sentir esa m\u00e1gica sensaci\u00f3n del momento en el que el texto fluye y coge forma. Ambas facetas, el cine y la escritura, se unieron de manera natural, a lo que contribuy\u00f3 mucho que la intensidad cin\u00e9fila se incrementara durante mi etapa universitaria en Pamplona. Las salas de exhibici\u00f3n y el videoclub eran mi ocio central.<\/p>\n<p><strong><br \/>\n\u00bfY c\u00f3mo decide un periodista especializarse\u00a0en cine?<\/strong><\/p>\n<p>Tendemos a dedicarnos a los que nos gusta y nos da vida, y en el trabajo siempre he perseguido eso aunque pueda estrechar tus opciones profesionales. He escrito de pol\u00edtica nacional, asuntos regionales, provinciales, municipales, comarcales, de temas sociales, de econom\u00eda y de mi amado Real Zaragoza, pero estos \u00e1mbitos no me llenaban e incluso algunos de ellos me ahogaban. Los art\u00edculos cinematogr\u00e1ficos de los que me encargaba en paralelo eran un cauce de satisfacci\u00f3n, y a ra\u00edz de la confianza que en el momento clave depositaron en m\u00ed personas a las que estoy muy agradecido, tuve la suerte de asentarme en este terreno.<\/p>\n<p><strong>\u00bfLas cr\u00edticas pueden ser objetivas? Cuando un medio te encarga una cr\u00edtica, \u00bfte facilitan el que sean totalmente independientes?<\/strong><\/p>\n<p>El oficio cr\u00edtico es por definici\u00f3n subjetivo, si bien quien lo ejerce debe procurar trascender ese \u2018yo\u2019 y analizar la pel\u00edcula de manera que las reflexiones respecto a los detalles, las ideas detectadas y las sensaciones evocadas puedan orientar al lector interesado. En ese sentido, el buen cr\u00edtico destierra los prejuicios relativos a tem\u00e1ticas que en principio le seducen menos y valora cada obra en su propio contexto. Nunca, ni en el medio al que estoy vinculado ni en los que colabor\u00e9 en su momento, me han sugerido o indicado nada respecto a calificaciones y valoraciones, y esa una libertad que se agradece.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-23154\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-dentro-texto-684x1024.jpg\" alt=\"Enrique Abenia\" width=\"684\" height=\"1024\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-dentro-texto-684x1024.jpg 684w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-dentro-texto-200x300.jpg 200w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-dentro-texto-768x1151.jpg 768w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-dentro-texto-1200x1798.jpg 1200w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-dentro-texto.jpg 1367w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p><strong>Trabajas como \u2018freelance\u2019. El periodismo ha sido siempre un sector que se ha prestado mucho a los profesionales independientes, \u00bfqu\u00e9 ventajas y qu\u00e9 dificultades encuentras al trabajar por libre?<\/strong><\/p>\n<p>He estado en los dos lados, por cuenta ajena y como aut\u00f3nomo, y prefiero la etapa profesional de estos \u00faltimos a\u00f1os. Valoro mucho organizarme a mi manera y marcarme pautas de trabajo dentro de que por supuesto te gu\u00edas por los compromisos adquiridos con las empresas y proyectos con los que colaboras. La flexibilidad horaria resulta asimismo un bien preciado, sobre todo para poder disfrutar m\u00e1s de mi hijo y coordinarme mejor con mi mujer. Puedes abstraerte un poco del agobio inherente al periodismo, si bien no escapas de sus sinsabores, que en el terreno \u2018freelance\u2019 se manifiestan en que a\u00fan tienes menos asegurado el empleo y que siempre debes ver c\u00f3mo ampliar tu marco de acci\u00f3n para mantener la estabilidad. La crisis permanente del gremio, con la incertidumbre que conlleva, la sientes en cualquier vertiente.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Zaragoza es una ciudad con mucha historia en el cine. \u00bfC\u00f3mo ves el panorama actual? <\/strong><\/p>\n<p>Respecto a im\u00e1genes fijas anteriores, el panorama se ha diversificado y fortalecido tanto en Zaragoza como en Arag\u00f3n. De la coyuntura, lo m\u00e1s relevante es que existe una mayor concienciaci\u00f3n de las instituciones en lo referente al apoyo a la cultura audiovisual, as\u00ed como que el p\u00fablico se interesa por las obras de los autores de la tierra. Tenemos unos nombres reconocibles y empiezan a salir otros, pero queda camino por recorrer.<br \/>\n<strong>\u00bfHay futuro aqu\u00ed para alguien que quiera dedicarse profesionalmente al audiovisual (en cualquiera de sus disciplinas)?<\/strong><\/p>\n<p>S\u00ed, dentro de que el sector audiovisual est\u00e1 atomizado y no siempre genera un volumen suficiente de trabajo. Quiero pensar que, como en cualquier dedicaci\u00f3n, con esfuerzo e ilusi\u00f3n uno puede encontrar su sitio. No obstante, en el caso concreto del cine, para consolidarse y tener futuro resulta fundamental que directores y productores logren que sus pel\u00edculas se vean sobre todo a nivel nacional as\u00ed como conseguir proyectos fuera, reto en el que la dificultad de los factores que intervienen se multiplica.<br \/>\n<strong>Adem\u00e1s de cine en salas se consume much\u00edsimo en plataformas bajo demanda, donde parece que las series tienen preferencia. \u00bfVes a menudo series? \u00bfLa cr\u00edtica de cine est\u00e1 re\u00f1ida con la de series ? O incluso webseries, otro formato que est\u00e1 en un aparente <em>boom<\/em>. La sensaci\u00f3n es que la cr\u00edtica se especializa en una o en otra, cu\u00e9ntanos.<\/strong><\/p>\n<p>Soy suscriptor de varias plataformas y un fiel serieadicto, aunque veo menos de las que me gustar\u00eda, a lo que se suma el inabarcable volumen de producciones. Por la noche puedo perder casi una hora sopesando qu\u00e9 poner en la televisi\u00f3n o en la tableta para que despu\u00e9s irrumpa el cansancio acumulado en la jornada y al final no ver nada. Al margen de los visionados por trabajo, tengo tantas series y pel\u00edculas pendientes\u2026 Como comento con compa\u00f1eros y amigos, necesitar\u00eda varias vidas dedicadas en exclusiva al ocio audiovisual. El an\u00e1lisis cr\u00edtico de una serie se gu\u00eda por lo mismo que al escribir de cine, si bien como indicas se tiende a la especializaci\u00f3n.<br \/>\n<strong>Eres pap\u00e1 reciente, aunque a\u00fan no vay\u00e1is juntos al cine, \u00bfves ahora con otra mirada las pel\u00edculas dirigidas a la infancia?<\/strong><\/p>\n<p>Siempre me ha atra\u00eddo fijarme en el aspecto visual y los discursos de las pel\u00edculas y series animadas, y ahora con la paternidad les encuentro a\u00fan m\u00e1s simpat\u00eda y encanto. Tengo ganas de verle disfrutar con el cine infantil y compartir momentos en ese aspecto.<br \/>\nPod\u00e9is conocer m\u00e1s a Enrique a trav\u00e9s de <a href=\"http:\/\/madeinzaragoza.es\/colaboradores\/autor.php?id=4\" target=\"_blank\" rel=\"noopener\">sus art\u00edculos en Made in Zaragoza<\/a>, o tambi\u00e9n <a href=\"https:\/\/twitter.com\/Enrique_Abenia\" target=\"_blank\" rel=\"noopener\">sigui\u00e9ndole en twitter:\u00a0@Enrique_Abenia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enrique Abenia es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual es Licenciado en Periodismo por la Universidad de Navarra y cuenta ya con m\u00e1s de doce a\u00f1os de experiencia profesional en prensa. Podemos leer sus cr\u00edticas cinematogr\u00e1ficas en la edici\u00f3n impresa de &#8216;Heraldo de Arag\u00f3n&#8216; &hellip; <a href=\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEntrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":55,"featured_media":23155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[1334],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Enrique Abenia es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual es Licenciado en Periodismo por la Universidad de Navarra y cuenta ya con m\u00e1s de doce a\u00f1os de experiencia profesional en prensa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Enrique Abenia es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual es Licenciado en Periodismo por la Universidad de Navarra y cuenta ya con m\u00e1s de doce a\u00f1os de experiencia profesional en prensa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-04T19:46:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-07T13:04:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-Abenia-portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1785\" \/>\n\t<meta property=\"og:image:height\" content=\"1488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00f3nica Anchelergues\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00f3nica Anchelergues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\"},\"author\":{\"name\":\"M\u00f3nica Anchelergues\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/d2a02be2248a3b9c7d4f508ee7173884\"},\"headline\":\"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo\",\"datePublished\":\"2019-01-04T19:46:43+00:00\",\"dateModified\":\"2019-01-07T13:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\"},\"wordCount\":1248,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"Entrevistas\"],\"articleSection\":[\"Gente\",\"Red MIZ\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\",\"name\":\"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2019-01-04T19:46:43+00:00\",\"dateModified\":\"2019-01-07T13:04:00+00:00\",\"description\":\"Enrique Abenia es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual es Licenciado en Periodismo por la Universidad de Navarra y cuenta ya con m\u00e1s de doce a\u00f1os de experiencia profesional en prensa.\",\"breadcrumb\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/d2a02be2248a3b9c7d4f508ee7173884\",\"name\":\"M\u00f3nica Anchelergues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/81ac539568d0b9bf93ce83cff1bc0345?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/81ac539568d0b9bf93ce83cff1bc0345?s=96&d=mm&r=g\",\"caption\":\"M\u00f3nica Anchelergues\"},\"description\":\"Estudi\u00e9 Publicidad porque mi vocaci\u00f3n es la creatividad, la comunicaci\u00f3n, lo visual y adem\u00e1s adoro escribir. Complet\u00e9 mi formaci\u00f3n con estudios de fotograf\u00eda, de arte, dise\u00f1o, web y de programaci\u00f3n lo que me permiti\u00f3 trabajar en agencias de publicidad madrile\u00f1as en los nacientes departamentos online del siglo pasado. M\u00e1s tarde quise centrarme en el Marketing Online, curs\u00e9 un M\u00e1ster, y trabaj\u00e9 como Marketing Manager en la divisi\u00f3n online de Cond\u00e9Nast. Aunque me apasionaba mi trabajo volv\u00ed a mi ciudad, y aqu\u00ed sigo, ahora como freelance, inmersa en varios proyectos, como la web ConpequesenZgz.com de la que soy directora, y otros proyectos creativos: de imagen, publicidad, web, o fotograf\u00eda...\",\"sameAs\":[\"http:\/\/conpequesenzgz.com\/\"],\"url\":\"https:\/\/madeinzaragoza.es\/blog\/author\/monica-anchelergues\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo - Made in Zaragoza","description":"Enrique Abenia es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual es Licenciado en Periodismo por la Universidad de Navarra y cuenta ya con m\u00e1s de doce a\u00f1os de experiencia profesional en prensa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo - Made in Zaragoza","og_description":"Enrique Abenia es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual es Licenciado en Periodismo por la Universidad de Navarra y cuenta ya con m\u00e1s de doce a\u00f1os de experiencia profesional en prensa.","og_url":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2019-01-04T19:46:43+00:00","article_modified_time":"2019-01-07T13:04:00+00:00","og_image":[{"width":1785,"height":1488,"url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2019\/01\/Enrique-Abenia-portada.jpg","type":"image\/jpeg"}],"author":"M\u00f3nica Anchelergues","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"M\u00f3nica Anchelergues","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#article","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/"},"author":{"name":"M\u00f3nica Anchelergues","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/d2a02be2248a3b9c7d4f508ee7173884"},"headline":"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo","datePublished":"2019-01-04T19:46:43+00:00","dateModified":"2019-01-07T13:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/"},"wordCount":1248,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["Entrevistas"],"articleSection":["Gente","Red MIZ"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/","url":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/","name":"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2019-01-04T19:46:43+00:00","dateModified":"2019-01-07T13:04:00+00:00","description":"Enrique Abenia es nuestro colaborador que m\u00e1s sabe de cine, entre otras cosas. Apasionado de la cultura, sobre todo audiovisual es Licenciado en Periodismo por la Universidad de Navarra y cuenta ya con m\u00e1s de doce a\u00f1os de experiencia profesional en prensa.","breadcrumb":{"@id":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/madeinzaragoza.es\/blog\/entrevistas-miz-enrique-abenia-periodista-critico-y-comunicador-cinefilo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Entrevistas MIZ: Enrique Abenia, periodista, cr\u00edtico y comunicador cin\u00e9filo"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/d2a02be2248a3b9c7d4f508ee7173884","name":"M\u00f3nica Anchelergues","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/81ac539568d0b9bf93ce83cff1bc0345?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81ac539568d0b9bf93ce83cff1bc0345?s=96&d=mm&r=g","caption":"M\u00f3nica Anchelergues"},"description":"Estudi\u00e9 Publicidad porque mi vocaci\u00f3n es la creatividad, la comunicaci\u00f3n, lo visual y adem\u00e1s adoro escribir. Complet\u00e9 mi formaci\u00f3n con estudios de fotograf\u00eda, de arte, dise\u00f1o, web y de programaci\u00f3n lo que me permiti\u00f3 trabajar en agencias de publicidad madrile\u00f1as en los nacientes departamentos online del siglo pasado. M\u00e1s tarde quise centrarme en el Marketing Online, curs\u00e9 un M\u00e1ster, y trabaj\u00e9 como Marketing Manager en la divisi\u00f3n online de Cond\u00e9Nast. Aunque me apasionaba mi trabajo volv\u00ed a mi ciudad, y aqu\u00ed sigo, ahora como freelance, inmersa en varios proyectos, como la web ConpequesenZgz.com de la que soy directora, y otros proyectos creativos: de imagen, publicidad, web, o fotograf\u00eda...","sameAs":["http:\/\/conpequesenzgz.com\/"],"url":"https:\/\/madeinzaragoza.es\/blog\/author\/monica-anchelergues\/"}]}},"_links":{"self":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/23153"}],"collection":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=23153"}],"version-history":[{"count":7,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/23153\/revisions"}],"predecessor-version":[{"id":23169,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/23153\/revisions\/23169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/23155"}],"wp:attachment":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=23153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=23153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=23153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}