{"id":19232,"date":"2018-03-15T12:31:50","date_gmt":"2018-03-15T11:31:50","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=19232"},"modified":"2018-03-18T22:05:18","modified_gmt":"2018-03-18T21:05:18","slug":"paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/","title":{"rendered":"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero"},"content":{"rendered":"<p>Esta treinta\u00f1era argentina llamada Paz Olaciregui es una n\u00f3mada de nacimiento que <strong>escogi\u00f3 Zaragoza para vivir por voluntad propia<\/strong> cuando se dio cuenta de que de tanto viajar y desprenderse de todo y de todos se hab\u00eda olvidado de tener un hogar, un lugar en el que encontrar el equilibrio y la paz, una almohada c\u00f3moda donde reposar su cabeza pensante.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19246\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/lapiz.jpg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/lapiz.jpg 640w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/lapiz-150x150.jpg 150w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/lapiz-300x300.jpg 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Y est\u00e1 enamorada de nuestra ciudad porque, desde que empez\u00f3 a acudir, all\u00e1 por 2006, a visitar a su hermana, que vino a estudiar veterinaria y se afinc\u00f3 definitivamente, <strong>ha notado muchos cambios positivos<\/strong>. Seg\u00fan su teor\u00eda, \u00abporque todos los j\u00f3venes que se marcharon a viajar y a vivir a otras ciudades y se vieron superados por el estr\u00e9s, la vor\u00e1gine, el desempleo o la competitividad, las distancias de casa al trabajo, etc. regresaron a su ciudad natal con muchas ideas innovadoras y las est\u00e1n poniendo en pr\u00e1ctica, lo cual nos enriquece a todos como sociedad\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>Que es el mismo fin que pretende conseguir ella, pues, desde que empez\u00f3 a estudiar un m\u00e1ster en Sociolog\u00eda y Pol\u00edticas en la Universidad de Zaragoza y la becaron y contrataron como profesora investigadora para hacer <strong>una tesis sobre violencia de g\u00e9nero, est\u00e1 sacando interesant\u00edsimas conclusiones que nos van a ser \u00fatiles a posteriori<\/strong> para evaluar la implementaci\u00f3n de la Ley contra la violencia de g\u00e9nero, y, en concreto, con sus investigaciones, para mejorar los protocolos de evaluaci\u00f3n de riesgo que sirven para decidir si las v\u00edctimas necesitan protecci\u00f3n o no.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u201cEl caso es que cuando una mujer va a denunciar se le aplica un cuestionario (adoptado de uno gen\u00e9rico de Canad\u00e1 que ha sido adaptado aqu\u00ed a la violencia de g\u00e9nero), y se introducen sus respuestas en el ordenador -a pesar de tratarse de detalles muy sensibles-, y \u00e9ste dicta si su riesgo es alto, medio o bajo\u201d.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>As\u00ed pues, la intenci\u00f3n de esta investigadora es \u201cver qui\u00e9n pens\u00f3 esos protocolos, c\u00f3mo se han dise\u00f1ado, c\u00f3mo se est\u00e1n aplicando, si est\u00e1n pensados desde la \u00f3ptica de la mujer o del hombre, si sirven o no&#8230;\u201d. La idea es conseguir \u201cencontrar unos m\u00ednimos en com\u00fan sobre conceptos b\u00e1sicos como el de violencia, o riesgo o seguridad, que hoy en d\u00eda cada polic\u00eda, cada juez, cada trabajadora social y cada mujer entienden de diferente manera\u00bb. M\u00e1s que nada para que no act\u00fae cada cual seg\u00fan sus propios criterios y<strong> que no suceda m\u00e1s lo m\u00e1s terrible que puedes o\u00edrle decir a una mujer, a saber: \u2018Si hubiese sabido lo que iba a suponer, no habr\u00eda denunciado\u2019<\/strong>.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19247\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/179-1024x682.jpg\" alt=\"\" width=\"840\" height=\"559\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/179-1024x682.jpg 1024w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/179-300x200.jpg 300w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/179-768x512.jpg 768w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/179-1200x799.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>O para que no volvamos a leer esos titulares tipo &#8216;Asesinada una mujer a la que se le hab\u00eda detectado riesgo bajo&#8217;. A este respecto, aclara Paz, \u00abla mayor\u00eda de las veces el protocolo y la protecci\u00f3n funcionan, lo que pasa es que s\u00f3lo es noticia cuando falla, pero hay millones de mujeres que est\u00e1n siendo eficazmente protegidas. En Zaragoza, hace 6 meses, hab\u00eda casi mil mujeres que hab\u00edan denunciado y requer\u00edan protecci\u00f3n\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><b>\u00bfSe puede contar con un guardaespaldas por mujer maltratada?<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Al empezar a indagar Paz tuvo que trabajar con las Fuerzas de Seguridad del Estado (FSE), encontr\u00e1ndose \u00abcon la curiosidad de que la Ertzaintza tiene muchos m\u00e1s recursos para poner pr\u00e1cticamente un guardaespaldas a cada mujer amenazada, mientras que en otras regiones del pa\u00eds donde opera la Polic\u00eda Nacional no dan abasto y necesitan ayuda de otros cuerpos\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Por ejemplo, en Zaragoza, donde no hay efectivos suficientes, cada agente Nacional destinado a violencia de g\u00e9nero tiene a su cargo la protecci\u00f3n de unas 90 o 100 v\u00edctimas, y la Local asegura que no tiene agentes para cubrirles, de manera que no se acaba de firmar el convenio que resulta tan necesario.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Otra diferencia es que a nivel estatal se trabaja de forma hol\u00edstica compartiendo el Vio G\u00e9n (el Sistema de Seguimiento Integral en los casos de Violencia de G\u00e9nero, de la Secretar\u00eda de Estado de Seguridad del Ministerio del Interior) entre todos los cuerpos de Seguridad del Estado y la Seguridad Social, los trabajadores sociales, las psic\u00f3logas de la Casa de la Mujer, etc. De tal forma que <strong>el archivo con todos los detalles de la amenazada est\u00e1 disponible para que puedan seguir mejor su caso y tratarla en consecuencia<\/strong>, mientras que los Mossos o la Ertzaintza no aplican el Vio G\u00e9n ni comparten esa informaci\u00f3n con los dem\u00e1s agentes sociales implicados. La parte positiva es que todas las FSE tienen una valoraci\u00f3n extraordinaria por parte de las v\u00edctimas as\u00ed como de otros muchos pa\u00edses donde ni siquiera se contabilizan las v\u00edctimas de la violencia de g\u00e9nero.<\/p>\n<p>&nbsp;<\/p>\n<p>A todas luces, la apuesta se ha de hacer antes de tener que poner el parche, \u201ccon la prevenci\u00f3n a trav\u00e9s de la educaci\u00f3n y la socializaci\u00f3n en la igualdad, el respeto y la no violencia, y siendo siempre did\u00e1cticas desde el cari\u00f1o y el buen rollo\u201d. Pero aparte de eso, adem\u00e1s, a la mujer hay que ense\u00f1arle a detectar las se\u00f1ales de alarma tempranamente, para que no llegue a estos extremos.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00abYo apuesto por que la mujer se empodere y se defienda, pacte con el otro el tipo de relaci\u00f3n que quieren tener y nunca permita que nadie propase sus l\u00edmites en ning\u00fan momento, ni en pareja ni en la calle ni en el trabajo\u201d.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_19244\" aria-describedby=\"caption-attachment-19244\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19244 size-medium\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/alas-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/alas-300x300.jpg 300w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/alas-150x150.jpg 150w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/alas.jpg 640w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><figcaption id=\"caption-attachment-19244\" class=\"wp-caption-text\">Olaciregui apuesta por dar alas a las mujeres.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Como soci\u00f3loga, a fin de aumentar la eficacia de los protocolos, pone siempre el foco en la mujer, le interesa saber \u00abc\u00f3mo se siente ella, c\u00f3mo est\u00e1 de empoderada, qu\u00e9 recursos tiene, qu\u00e9 entiende ella por sentirse protegida y segura, para plantear unos protocolos desde la perspectiva de g\u00e9nero, no desde la \u00f3ptica del hombre\u00bb. <strong>A los cuales, por cierto, les recuerda que \u201csi son maltratados, que los hay, que vayan a denunciar aunque les averg\u00fcence por culpa del machismo del que ellos mismos son v\u00edctimas<\/strong>, ya que la violencia siempre es violencia y se les va a tratar de la misma manera, aplic\u00e1ndoles los protocolos y la protecci\u00f3n que les correspondan\u201d. Aplaude por supuesto a \u201cHombres por la Igualdad, porque es un colectivo muy implicado con el que da gusto trabajar y que entienden que esto lo hicimos mal entre todos\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La realidad aplicada a su imaginaci\u00f3n en Una y mil <del>veces<\/del>\u00a0voces<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19235 aligncenter\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/lado.jpg\" alt=\"\" width=\"416\" height=\"575\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/lado.jpg 416w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/lado-217x300.jpg 217w\" sizes=\"(max-width: 416px) 85vw, 416px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Con todo lo que est\u00e1 investigando, m\u00e1s lo que vive y observa en primera persona, intuye que alg\u00fan d\u00eda todo esto saldr\u00e1 de su cerebro en forma de libro literario con tono muy divertido, al igual que le ha brotado de su imparable imaginaci\u00f3n este Una y mil <span style=\"text-decoration: line-through;\">veces<\/span> voces, un curios\u00edsimo compendio de diarios extra\u00eddos de su blog, <a href=\"http:\/\/dominiquerosseau.blogspot.com.es\/\">DiariaMente Dominique<\/a>, que sorprende por su estilo fresco, directo, \u00e1gil y diferente para ser una autora novel. Para ella fue una sorpresa que la <a href=\"http:\/\/www.sibirana.com\/colec\/insulas\/dominique.html\">editorial Sibirana<\/a> se lo propusiera, y se dispuso a descartar relatos y a ordenar los escogidos por tres cap\u00edtulos: Silencios, susurros, gritos. <strong>Las voces que recoge son de lo m\u00e1s variopinto y original, lo cual permite que la mayor\u00eda nos sintamos identificados con algunas, sino con varias.<\/strong> Paz cuenta que todos estos diarios est\u00e1n inspirados en las vidas que ha ido conociendo en sus viajes y a su alrededor, pues observa y luego se evade totalmente de la realidad para escribir y describir lo experimentado desde su subjetivo y peculiar modo de contarlo. Esperamos con ansias esas nuevas voces sobre la violencia de g\u00e9nero que de momento estudia acad\u00e9micamente.<\/p>\n<p>&nbsp;<\/p>\n<p>El libro <strong>se presentar\u00e1 el 20 de marzo en la librer\u00eda C\u00e1lamo <\/strong>(Plaza San Francisco, 4).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta treinta\u00f1era argentina llamada Paz Olaciregui es una n\u00f3mada de nacimiento que escogi\u00f3 Zaragoza para vivir por voluntad propia cuando se dio cuenta de que de tanto viajar y desprenderse de todo y de todos se hab\u00eda olvidado de tener un hogar, un lugar en el que encontrar el equilibrio y la paz, una almohada &hellip; <a href=\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPaz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero\u00bb<\/span><\/a><\/p>\n","protected":false},"author":60,"featured_media":19234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[829,6],"tags":[1717,838],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero - Made in Zaragoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Esta treinta\u00f1era argentina llamada Paz Olaciregui es una n\u00f3mada de nacimiento que escogi\u00f3 Zaragoza para vivir por voluntad propia cuando se dio cuenta de que de tanto viajar y desprenderse de todo y de todos se hab\u00eda olvidado de tener un hogar, un lugar en el que encontrar el equilibrio y la paz, una almohada &hellip; Continuar leyendo &quot;Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-15T11:31:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-18T21:05:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/PORTADA-una-y-mil-veces.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"524\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisabeth G Iborra\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisabeth G Iborra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\"},\"author\":{\"name\":\"Elisabeth G Iborra\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c\"},\"headline\":\"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero\",\"datePublished\":\"2018-03-15T11:31:50+00:00\",\"dateModified\":\"2018-03-18T21:05:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\"},\"wordCount\":1393,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"igualdad\",\"mujeres\"],\"articleSection\":[\"Cultura\",\"Gente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\",\"name\":\"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2018-03-15T11:31:50+00:00\",\"dateModified\":\"2018-03-18T21:05:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c\",\"name\":\"Elisabeth G Iborra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g\",\"caption\":\"Elisabeth G Iborra\"},\"url\":\"https:\/\/madeinzaragoza.es\/blog\/author\/elisabethgiborra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero - Made in Zaragoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/","og_locale":"es_ES","og_type":"article","og_title":"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero - Made in Zaragoza","og_description":"Esta treinta\u00f1era argentina llamada Paz Olaciregui es una n\u00f3mada de nacimiento que escogi\u00f3 Zaragoza para vivir por voluntad propia cuando se dio cuenta de que de tanto viajar y desprenderse de todo y de todos se hab\u00eda olvidado de tener un hogar, un lugar en el que encontrar el equilibrio y la paz, una almohada &hellip; Continuar leyendo \"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero\"","og_url":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2018-03-15T11:31:50+00:00","article_modified_time":"2018-03-18T21:05:18+00:00","og_image":[{"width":524,"height":749,"url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/PORTADA-una-y-mil-veces.jpg","type":"image\/jpeg"}],"author":"Elisabeth G Iborra","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Elisabeth G Iborra","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#article","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/"},"author":{"name":"Elisabeth G Iborra","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c"},"headline":"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero","datePublished":"2018-03-15T11:31:50+00:00","dateModified":"2018-03-18T21:05:18+00:00","mainEntityOfPage":{"@id":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/"},"wordCount":1393,"commentCount":1,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["igualdad","mujeres"],"articleSection":["Cultura","Gente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/","url":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/","name":"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2018-03-15T11:31:50+00:00","dateModified":"2018-03-18T21:05:18+00:00","breadcrumb":{"@id":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/madeinzaragoza.es\/blog\/paz-olaciregui-da-voz-a-sus-otras-voces-y-a-las-victimas-de-violencia-de-genero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Paz Olaciregui da voz a sus otras voces y a las v\u00edctimas de violencia de g\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c","name":"Elisabeth G Iborra","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g","caption":"Elisabeth G Iborra"},"url":"https:\/\/madeinzaragoza.es\/blog\/author\/elisabethgiborra\/"}]}},"_links":{"self":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/19232"}],"collection":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=19232"}],"version-history":[{"count":10,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/19232\/revisions"}],"predecessor-version":[{"id":19626,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/19232\/revisions\/19626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/19234"}],"wp:attachment":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=19232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=19232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=19232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}