{"id":16096,"date":"2017-07-24T15:58:09","date_gmt":"2017-07-24T14:58:09","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=16096"},"modified":"2017-07-24T15:58:09","modified_gmt":"2017-07-24T14:58:09","slug":"4-denominaciones-origen-aragonesas-pidiendo-riojita","status":"publish","type":"post","link":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/","title":{"rendered":"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita"},"content":{"rendered":"<p>Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d. A lo que alg\u00fan seguidor que no me conoc\u00eda de nada me aconsej\u00f3: \u201cT\u00f3mate un buen Ribera del Duero\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Es dif\u00edcil describir, y probablemente comprender, la ira que inund\u00f3 todo mi ser. Por supuesto, se la transmit\u00ed con toda mi mala baba: \u201c<strong>Yo, en Arag\u00f3n, s\u00f3lo bebo vinos de Arag\u00f3n.<\/strong> Cuando vaya a Valladolid, ya tomar\u00e9 Ribera del Duero. Y en Zamora, Toro.\u201d Y siempre as\u00ed, en todos sitios. En Logro\u00f1o, tomo Rioja. En Alicante, pruebo vinos de Alicante, de Valencia si me apuras. En Murcia, Jumilla; en C\u00e1diz, vinos de Jerez; y en cada regi\u00f3n, pruebo sus denominaciones, que no en vano hay 69, por no alargarme e ir al grano.<\/p>\n<p>&nbsp;<\/p>\n<p>Y el grano es que <strong>en Arag\u00f3n tenemos cuatro denominaciones de origen oficiales, l\u00e9ase Somontano, Cari\u00f1ena, Calatayud y Campo de Borja<\/strong>, aparte de unas seis zonas m\u00e1s con Indicaci\u00f3n Geogr\u00e1fica, como los Vinos de la Tierra Ribera del Jiloca (Pru\u00e9bese Murero) y los Vinos de la Tierra Ribera del G\u00e1llego-Cinco Villas (Uva Nocturna, por ejemplo).<\/p>\n<p>&nbsp;<\/p>\n<h2>Lo vuestro es delicitivo<\/h2>\n<p>&nbsp;<\/p>\n<p>Sin embargo, la gente, y no me refiero a los turistas, sigue pidiendo un rioja o un ribera como sin\u00f3nimo de vino tinto, como si s\u00f3lo existiera su tempranillo y no tuvi\u00e9ramos aqu\u00ed decenas de varietales, desde la garnacha hasta el merlot, el syrah o cabernet sauvingon. Y piden un Rueda o verdejo (que no es lo mismo la Denominaci\u00f3n que la uva) en lugar de \u201cun blanco\u201d, con las uvas chardonnay, malvas\u00eda, macabeo o garnacha blanca, por mencionar algunas, que nos permiten vinos menos secos aqu\u00ed. Y piden un rosado de Navarra, sin tener en cuenta delicias como el Alquezar rosado, que es de Somontano (y hay decenas m\u00e1s bien refrescantes).<\/p>\n<p>&nbsp;<\/p>\n<p>En definitiva,<strong> con los magn\u00edficos vinos que salen de nuestras 36.470 hect\u00e1reas de vi\u00f1edos de uva no de mesa, ya es delito que nuestros cientos de bodegueros vendan m\u00e1s exportando al resto del mundo que en tierra propia.<\/strong> Porque a nuestro complejo de inferioridad lo aragon\u00e9s le parece siempre poco.<\/p>\n<p>&nbsp;<\/p>\n<p>Si algo he hecho en cada visita durante 20 a\u00f1os, y sobre todo, desde que me instal\u00e9, que no s\u00e9 ni c\u00f3mo tengo ri\u00f1\u00f3n todav\u00eda, es probar vinos de Arag\u00f3n. Empezando por los bares, mi pol\u00edtica es invariable:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Tomo \u00fanica y exclusivamente vinos aragoneses.<\/li>\n<li>Siempre que tienen uno diferente, lo pruebo.<\/li>\n<li>\u00a0Voy a descubrir bares donde tienen muchos vinos diferentes por copas.<\/li>\n<li>A cada copa que me bebo, pido uno distinto para catar m\u00e1s.<\/li>\n<li>Si tienen muchos, le propongo a mis amigos una cata para degustar m\u00e1s sin emborracharnos.<\/li>\n<li>Si no tienen variedad por copas, convenzo a mis amigas para compartir botella, de Arag\u00f3n.<\/li>\n<li>Cuando los vinos que tienen son flojitos, hablo con los due\u00f1os para coment\u00e1rselo y recomendarles otros, o por lo menos, que oferten m\u00e1s para elegir.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16098\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2017\/07\/imagendocevinos_45dd740c.jpg\" alt=\"\" width=\"800\" height=\"240\" srcset=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2017\/07\/imagendocevinos_45dd740c.jpg 800w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2017\/07\/imagendocevinos_45dd740c-300x90.jpg 300w, https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2017\/07\/imagendocevinos_45dd740c-768x230.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Los vinos que no te puedes perder<\/h2>\n<p>En este sentido, aplaudo much\u00edsimo la bodega que tienen en El Broquel, Almau, Palomeque, el F\u00fatbol, Los Victorinos, San Siro, El Bandido, etc. que tienen en su vinoteca una muy extensa representaci\u00f3n de Denominaciones y marcas para catar por copa. No s\u00f3lo los t\u00edpicos (y cojonudos) Tres Picos, Vi\u00f1as del Vero, Garnacha Centenaria, Enate, Nietro, Heredad, Gl\u00e1rima, Matarile, etc. que est\u00e1n al alcance de cualquiera en todos los bares. Sino otras muchas que s\u00f3lo algunos se permiten porque tienen un tr\u00e1nsito de clientes suficiente como para que no se les avinagren en dos d\u00edas. Entre estos, destacan Samitier, Rom\u00e1n, Trashumante, Secastilla, Edra, El Alquez, Ayles, Laus, Anay\u00f3n u Honoro Vera, (que se hizo famoso porque fue elegido para maridar una cena de los Oscar cuando aqu\u00ed no lo conoc\u00eda nadie)&#8230;<\/p>\n<p>&nbsp;<\/p>\n<h2>Gracias a los bares peque\u00f1os por arriesgar<\/h2>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n es muy de alabar el gusto de los bares peque\u00f1os que, pasando de las ofertas de los distribuidores de grandes marcas, apuestan por vinos selectos de bodegas menos renombradas pero con referencias muy recomendables a una relaci\u00f3n de calidad-precio bien ajustada. De tal forma que pagas 2-2\u201950 por tastar un vino sorprendente. <strong>L\u2019 Albada Tabierna<\/strong>, con toda la gama de Sargas de Id\u00faes y 108 Noches, su nuevo malvas\u00eda 100%; el <strong>Meli Mel\u00f3<\/strong>, que ofrece el Sed y el Duna, de Vinos del Desierto; el <strong>Morris<\/strong>, que dispone de todos los Langa; el <strong>Peque\u00f1o Cascanueces<\/strong>, con su Alodia Syrah; la Taskeria, con una selecci\u00f3n muy digna\u2026<\/p>\n<p>&nbsp;<\/p>\n<h2>Las vinacotecas son museos<\/h2>\n<p>&nbsp;<\/p>\n<p>Y cuando me aburro de beber siempre los mismos, que mira que es complicado, pero una tiene una curiosidad insaciable, <strong>me voy a la Bodega San Pablo, o a la B\u00f3tica, o a Tomevinos<\/strong>, y les requiero su consejo para que me sorprendan con sus escogidos a precios m\u00e1s que asequibles. Porque en Arag\u00f3n no hace falta gastarse un dineral para quedarse satisfecho. En ellas he descubierto, respectivamente, el blanco R de Ruberte, el Pizarra Blanca 2013, o el Cosos y los Vinos del Viento, de Michael Cooper, por poner algunos que repetir\u00eda sin dudar. Ah, espectacular la bodega que se esconde en el palacete de Montal, que no s\u00f3lo es una tienda de delicatessen con servicio en mesa, no.<\/p>\n<p>&nbsp;<\/p>\n<h2>Atentos a los eventos p\u00fablicos<\/h2>\n<p>Otros eventos en los que se puede aprender mucho son las ferias de productores regionales, que se celebran cada dos por tres y son abiertas al p\u00fablico, como el <strong>Slowfood Zgz<\/strong>, donde entrevist\u00e9 a cantidad de bodegueros empe\u00f1ados en recuperar variedades aut\u00f3ctonas, como alca\u00f1\u00f3n, mazuela, bobal o moscatel de Alejandr\u00eda. Otro evento es <strong>La Semana de la Garnacha<\/strong>, donde prob\u00e9 m\u00e1s de 12 maravillas en una tarde, como el Alto Moncayo o el Fagus, nivel\u00f3n. Y el encuentro m\u00e1s popular es el del Vino en la Calle, que saca sus puestos en el Gancho cada mayo y cada septiembre.<\/p>\n<p>&nbsp;<\/p>\n<p>En todos ellos, te dan una copa con la entrada y puedes ir conociendo a todos los bodegueros y en\u00f3logos, que te cuentan sus curiosidades sobre cada una de sus propuestas mientras te las dan a degustar. Eso no tiene precio, en serio, en una tarde conoces vinos que, de otro modo, no probar\u00edas en tu vida. Y si te gustan y te quedas el contacto, puedes pedirle las botellas directamente a las bodegas e incluso ir a visitarlas. Que, por cierto, hay rutas de enoturismo por cada una de las denominaciones de origen, con facilidades para ir sin coche, por aquello de poder catar sin escupir y sin cortapisas.<\/p>\n<p>&nbsp;<\/p>\n<p>Pero de cada una de las denominaciones ir\u00e9 escribiendo diferentes art\u00edculos, para que las conozc\u00e1is m\u00e1s a fondo, y con todas las posibilidades que ofrecen para hacer excursiones a sus bodegas y probar cada uno de sus vinazos.<\/p>\n<p>&nbsp;<\/p>\n<p>Como vuelva a escuchar a alguien en un bar pedir un Rioja o un verdejo y luego quejarse de que Arag\u00f3n no pinta nada en Espa\u00f1a, le obligo a aprenderse este art\u00edculo de carrerilla.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Este art\u00edculo pertenece a la serie\u00a0<a href=\"http:\/\/madeinzaragoza.es\/blog\/a-contracorriente-zaragoza-cambiante\/\">\u2018A contracorriente: reencuentros con una\u00a0Zaragoza cambiante\u2019<\/a>\u00a0en la que mostramos la visi\u00f3n de zaragozanos que han vuelto a la ciudad tras haber estado viviendo fuera durante a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d. A lo que alg\u00fan seguidor que no me conoc\u00eda de nada me aconsej\u00f3: \u201cT\u00f3mate un buen Ribera del Duero\u201d. &nbsp; Es dif\u00edcil describir, y probablemente &hellip; <a href=\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita\u00bb<\/span><\/a><\/p>\n","protected":false},"author":60,"featured_media":16097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-24T14:58:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2017\/07\/OIW3D90.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisabeth G Iborra\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisabeth G Iborra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\"},\"author\":{\"name\":\"Elisabeth G Iborra\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c\"},\"headline\":\"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita\",\"datePublished\":\"2017-07-24T14:58:09+00:00\",\"dateModified\":\"2017-07-24T14:58:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\"},\"wordCount\":1298,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"articleSection\":[\"Econom\u00eda Creativa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\",\"name\":\"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2017-07-24T14:58:09+00:00\",\"dateModified\":\"2017-07-24T14:58:09+00:00\",\"description\":\"Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d.\",\"breadcrumb\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c\",\"name\":\"Elisabeth G Iborra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g\",\"caption\":\"Elisabeth G Iborra\"},\"url\":\"https:\/\/madeinzaragoza.es\/blog\/author\/elisabethgiborra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita - Made in Zaragoza","description":"Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/","og_locale":"es_ES","og_type":"article","og_title":"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita - Made in Zaragoza","og_description":"Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d.","og_url":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2017-07-24T14:58:09+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2017\/07\/OIW3D90.jpg","type":"image\/jpeg"}],"author":"Elisabeth G Iborra","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Elisabeth G Iborra","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#article","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/"},"author":{"name":"Elisabeth G Iborra","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c"},"headline":"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita","datePublished":"2017-07-24T14:58:09+00:00","dateModified":"2017-07-24T14:58:09+00:00","mainEntityOfPage":{"@id":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/"},"wordCount":1298,"commentCount":7,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"articleSection":["Econom\u00eda Creativa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/","url":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/","name":"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2017-07-24T14:58:09+00:00","dateModified":"2017-07-24T14:58:09+00:00","description":"Hace ya unos a\u00f1os, viniendo para Zaragoza de visita en el AVE, puse un tweet que dec\u00eda algo as\u00ed como: \u201cEstoy llegando a Zaragoza y muero por tomarme un vino\u201d.","breadcrumb":{"@id":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/madeinzaragoza.es\/blog\/4-denominaciones-origen-aragonesas-pidiendo-riojita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"4 denominaciones de origen aragonesas y t\u00fa pidiendo un riojita"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c","name":"Elisabeth G Iborra","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g","caption":"Elisabeth G Iborra"},"url":"https:\/\/madeinzaragoza.es\/blog\/author\/elisabethgiborra\/"}]}},"_links":{"self":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/16096"}],"collection":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=16096"}],"version-history":[{"count":1,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/16096\/revisions"}],"predecessor-version":[{"id":16100,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/16096\/revisions\/16100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/16097"}],"wp:attachment":[{"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=16096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=16096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=16096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}