{"id":1894,"count":2,"description":"","link":"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/","name":"xilografia japonesa","slug":"xilografia-japonesa","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>xilografia japonesa - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Art\u00edculos sobre xilografia japonesa en el blog de Made in Zaragoza, la red de emprendedores creativos de Zaragoza Activa. Emprendimiento, cultura, creatividad y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"xilografia japonesa - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculos sobre xilografia japonesa en el blog de Made in Zaragoza, la red de emprendedores creativos de Zaragoza Activa. Emprendimiento, cultura, creatividad y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/\",\"name\":\"xilografia japonesa - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"description\":\"Art\u00edculos sobre xilografia japonesa en el blog de Made in Zaragoza, la red de emprendedores creativos de Zaragoza Activa. Emprendimiento, cultura, creatividad y m\u00e1s.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"xilografia japonesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"xilografia japonesa - Made in Zaragoza","description":"Art\u00edculos sobre xilografia japonesa en el blog de Made in Zaragoza, la red de emprendedores creativos de Zaragoza Activa. Emprendimiento, cultura, creatividad y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/","og_locale":"es_ES","og_type":"article","og_title":"xilografia japonesa - Made in Zaragoza","og_description":"Art\u00edculos sobre xilografia japonesa en el blog de Made in Zaragoza, la red de emprendedores creativos de Zaragoza Activa. Emprendimiento, cultura, creatividad y m\u00e1s.","og_url":"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/","og_site_name":"Made in Zaragoza","twitter_card":"summary","twitter_site":"@madeinzaragoza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/","url":"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/","name":"xilografia japonesa - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"description":"Art\u00edculos sobre xilografia japonesa en el blog de Made in Zaragoza, la red de emprendedores creativos de Zaragoza Activa. Emprendimiento, cultura, creatividad y m\u00e1s.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/tag\/xilografia-japonesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"xilografia japonesa"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags\/1894"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts?tags=1894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}