{"id":9797,"date":"2015-08-25T21:18:52","date_gmt":"2015-08-25T20:18:52","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=9797"},"modified":"2015-08-25T21:36:45","modified_gmt":"2015-08-25T20:36:45","slug":"charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/","title":{"rendered":"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9799 size-full\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-1.jpg\" alt=\"helena-1\" width=\"504\" height=\"378\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-1.jpg 504w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-1-300x225.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-1-180x135.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-1-350x262.jpg 350w\" sizes=\"(max-width: 504px) 85vw, 504px\" \/><\/p>\n<p>La idea \u00abEncuentros de azoteas\u00bb naci\u00f3 en 2012 en Sevilla de la mano de <a href=\"http:\/\/redetejas.org\/\">Redetejas<\/a>,\u00a0la primera comunidad\u00a0de micro espacios culturales en azoteas privadas.<\/p>\n<p>Redetejas es un proyecto sin \u00e1nimo de lucro cuyo objetivo es generar una red abierta de nuevos lugares\u00a0para la cultura en los que los ciudadanos tengan la oportunidad de programar, gestionar y decidir los contenidos culturales del proyecto, dentro de sus propios espacios.<\/p>\n<p>En Zaragoza el proyecto est\u00e1 impulsado por\u00a0<strong>Helena Mill\u00e1n<\/strong><strong>\u00a0<\/strong>de\u00a0<a href=\"https:\/\/www.facebook.com\/dembaproduccionescreativas?fref=ts\">Demba Producciones<\/a>\u00a0y <strong>Carmina Gustr\u00e1n <\/strong>de <a href=\"https:\/\/www.facebook.com\/Enlatamus?fref=ts\">Enlatamus<\/a>.<\/p>\n<p>Llevan todo el mes de agosto\u00a0buscando a particulares dispuestos a prestar su azotea para organizar actividades art\u00edsticas y culturales y ya han fijado fecha en el calendario: <strong>el 19 de septiembre<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9802\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena2.jpg\" alt=\"helena2\" width=\"558\" height=\"419\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena2.jpg 558w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena2-300x225.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena2-180x135.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena2-350x262.jpg 350w\" sizes=\"(max-width: 558px) 85vw, 558px\" \/><\/p>\n<p>El primer encuentro\u00a0de\u00a0azoteas en Zaragoza consistir\u00e1 en una ruta de micro actividades culturales que\u00a0<strong>se desarrollar\u00e1 de forma simult\u00e1nea en tres azoteas<\/strong>.<\/p>\n<p>El p\u00fablico (previa inscripci\u00f3n) podr\u00e1 desplazarse de una a otra a lo largo de la tarde y disfrutar de las distintas actuaciones (y como no de las vistas).<\/p>\n<p>En Zaragoza, Demba quiere <strong>mantener el secreto hasta el\u00a0\u00faltimo momento<\/strong>,\u00a0pero s\u00ed ha adelantado que cada azotea albergar\u00e1 una disciplina art\u00edstica diferente.<\/p>\n<p>En otras ciudades, estos encuentros\u00a0han permitido disfrutar de\u00a0<strong>espect\u00e1culos teatrales, musicales, magia, poes\u00eda e incluso de circo<\/strong> en un mismo d\u00eda.<\/p>\n<p>Quien desee participar como p\u00fablico <a href=\"https:\/\/www.facebook.com\/dembaproduccionescreativas?fref=ts\">tendr\u00e1 que estar atento<\/a> porque la inscripci\u00f3n se lanzar\u00e1 la primera semana de septiembre y habr\u00e1 plazas limitadas.<\/p>\n<p>Se organizar\u00e1n tres grupos (su volumen depender\u00e1 del aforo de las azoteas) y\u00a0la velada tendr\u00e1 un precio que todav\u00eda no ha sido desvelado. Con la recaudaci\u00f3n se\u00a0har\u00e1 frente a los costes\u00a0de los artistas y la\u00a0promoci\u00f3n.<\/p>\n<p>Hablamos con Helena Mill\u00e1n\u00a0para que nos explique toda esta pasi\u00f3n por la cultura y las azoteas\u00a0con m\u00e1s detalle:<\/p>\n<p><strong>\u00bfQu\u00e9 es \u00abEncuentros de azoteas\u00bb?<\/strong><\/p>\n<p>Una iniciativa que\u00a0promueve que\u00a0espacios de uso particular se abran al\u00a0uso com\u00fan, acogiendo actuaciones y artistas.<\/p>\n<p>Son terrazas y azoteas que normalmente albergan eventos gastron\u00f3micos y que ahora queremos abrir al consumo cultural.<\/p>\n<p><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9807\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4.jpg\" alt=\"helena-millan-ilu4\" width=\"557\" height=\"370\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4.jpg 620w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4-300x199.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4-163x109.jpg 163w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4-105x70.jpg 105w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4-180x119.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu4-350x232.jpg 350w\" sizes=\"(max-width: 557px) 85vw, 557px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9806\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu2.jpg\" alt=\"helena-millan-ilu2\" width=\"557\" height=\"370\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu2.jpg 620w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu2-300x199.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu2-163x109.jpg 163w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu2-105x70.jpg 105w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu2-180x119.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-millan-ilu2-350x232.jpg 350w\" sizes=\"(max-width: 557px) 85vw, 557px\" \/><\/p>\n<p><strong>\u00bfA que p\u00fablico vais dirigidos?<\/strong><\/p>\n<p>Mayores de 18 a\u00f1os o acompa\u00f1ados de un adulto. A partir de ah\u00ed, sin ning\u00fan limite, buscamos el p\u00fablico mas amplio posible.<\/p>\n<p>Al llevar el espect\u00e1culo a una casa, pensamos que lo haremos mas accesible. Hay gente a la que todav\u00eda le cuesta acercarse a ciertos espacios, y con esta\u00a0forma de mostrar la cultura, queremos eliminar cualquier barrera.<\/p>\n<p>El evento es una especie de teatro de calle, un espect\u00e1culo de cercan\u00eda, ya que desplazamos a los artistas a un lugar\u00a0diferente.\u00a0Adem\u00e1s,\u00a0sumamos el\u00a0atractivo de estar en una azotea con buenas vistas.<\/p>\n<p><strong>H\u00e1blanos sobre ti<\/strong><\/p>\n<p>Soy Helena Mill\u00e1n y me form\u00e9 en producci\u00f3n cinematogr\u00e1fica. Mi familia ha estado siempre vinculada a las artes esc\u00e9nicas, a trav\u00e9s de la iluminaci\u00f3n y el sonido.<\/p>\n<p>Aunque me hice cargo de la empresa familiar, mi\u00a0parte creativa siempre estaba all\u00ed, con \u00abLa Hora Bruja\u00bb (2013), que fusionaba\u00a0los atardeceres de\u00a0la terraza del <a href=\"http:\/\/zaragozaguia.com\/museo-pablo-serrano-iaacc\/\">Pablo Serrano<\/a> con flamenco o con\u00a0\u00abCocktail Party\u00bb (2014), una noche en blanco interactiva en la que a trav\u00e9s de una gramola 2.0 relacion\u00e1bamos la m\u00fasica de los 60 con la obra de Antonio Saura.<\/p>\n<p>En 2014 me\u00a0explicaron en que consist\u00eda \u00abEncuentros de azoteas\u00bb. Fue\u00a0un proyecto que estuve\u00a0madurando m\u00e1s de un a\u00f1o, hasta que en el verano de 2015\u00a0sent\u00ed\u00a0que hab\u00eda llegado el momento de hacerlo.<\/p>\n<p>Tambi\u00e9n colaboro con\u00a0la <a href=\"http:\/\/zaragozaguia.com\/la-antigua-harinera-san-jose\/\">Harinera<\/a>, un proyecto social y cultural muy potente del barrio de San Jos\u00e9 que estar\u00e1 activo antes de que acabe 2015.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/yKTNJaVwarM\" width=\"620\" height=\"340\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong>Poes\u00eda, m\u00fasica\u2026 \u00bfQu\u00e9 se puede esperar el que acuda a \u00abEncuentros de azoteas\u00bb?<\/strong><\/p>\n<p>A gente que se le va la pinza. El evento en s\u00ed es <strong>un alegato a la locura<\/strong>. El decir, nos subios a la azotea, a la casa de la loca (risas).<\/p>\n<p>Es una iniciativa en la que buscamos que los artistas transmitan a trav\u00e9s de lo diferente, poniendo\u00a0al p\u00fablico y al artista a un mismo nivel, en un\u00a0espacio intimo.<\/p>\n<p><strong>Encuentros con los artistas, pero \u00bftambi\u00e9n encuentro entre la gente?<\/strong><\/p>\n<p>Si, porque en realidad, los anfitriones son personas que est\u00e1n dispuestas a abrir su casa a gente que no conocen de nada.<\/p>\n<p>Estamos en la casa de alguien, lo que\u00a0genera una serie de situaciones que dan valor a\u00f1adido al proyecto. Entre el anfitri\u00f3n, el artista y los invitados no hay barreras y eso transmite emociones. Es un proyecto amable,\u00a0a pie de calle y muy cercano.<\/p>\n<p><strong>\u00bfCu\u00e1ndo puede inscribirse la gente?<\/strong><\/p>\n<p>Lo lanzaremos el<strong> jueves 10 de septiembre<\/strong>, a trav\u00e9s de\u00a0la p\u00e1gina de Facebook de <a href=\"https:\/\/www.facebook.com\/Redetejas?fref=ts\">Redetejas<\/a>.<\/p>\n<p><strong>La primera cita ser\u00e1 el 19 de Septiembre, \u00bfCu\u00e1ndo ser\u00e1n los pr\u00f3ximos encuentros?<\/strong><\/p>\n<p>El primer encuentro ser\u00e1\u00a0multidisciplinar y esperamos que los pr\u00f3ximos puedan ser especializados en una disciplina art\u00edstica. Las fechas est\u00e1n todav\u00eda por confirmar.<\/p>\n<p>El pr\u00f3ximo\u00a0\u00abEncuentro de azoteas\u00bb en Zaragoza se celebrar\u00e1\u00a0el 19 de Septiembre, as\u00ed que estad atentos a su p\u00e1gina de <a href=\"https:\/\/www.facebook.com\/Redetejas?fref=ts\">Facebook<\/a> y a <a href=\"http:\/\/www.redetejas.org\/\">su Web<\/a>.<\/p>\n<p>\u00bfTe animas a asistir?<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/yY__41AZnH8\" width=\"620\" height=\"340\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La idea \u00abEncuentros de azoteas\u00bb naci\u00f3 en 2012 en Sevilla de la mano de Redetejas,\u00a0la primera comunidad\u00a0de micro espacios culturales en azoteas privadas. Redetejas es un proyecto sin \u00e1nimo de lucro cuyo objetivo es generar una red abierta de nuevos lugares\u00a0para la cultura en los que los ciudadanos tengan la oportunidad de programar, gestionar y &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCharlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":9799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"La idea &quot;Encuentros de azoteas&quot; naci\u00f3 en 2012 en Sevilla de la mano de Redetejas, la primera comunidad de micro espacios culturales en azoteas privadas. En Zaragoza el proyecto est\u00e1 impulsado por Helena Mill\u00e1n de Demba Producciones y Carmina Gustr\u00e1n de Enlatamus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"La idea &quot;Encuentros de azoteas&quot; naci\u00f3 en 2012 en Sevilla de la mano de Redetejas, la primera comunidad de micro espacios culturales en azoteas privadas. En Zaragoza el proyecto est\u00e1 impulsado por Helena Mill\u00e1n de Demba Producciones y Carmina Gustr\u00e1n de Enlatamus.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"zaragoza.guia.2\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-25T20:18:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-08-25T20:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"504\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Gimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@zgzguia\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Gimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\"},\"author\":{\"name\":\"David Gimenez\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48\"},\"headline\":\"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares\",\"datePublished\":\"2015-08-25T20:18:52+00:00\",\"dateModified\":\"2015-08-25T20:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\"},\"wordCount\":899,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"articleSection\":[\"Gente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\",\"name\":\"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2015-08-25T20:18:52+00:00\",\"dateModified\":\"2015-08-25T20:36:45+00:00\",\"description\":\"La idea \\\"Encuentros de azoteas\\\" naci\u00f3 en 2012 en Sevilla de la mano de Redetejas, la primera comunidad de micro espacios culturales en azoteas privadas. En Zaragoza el proyecto est\u00e1 impulsado por Helena Mill\u00e1n de Demba Producciones y Carmina Gustr\u00e1n de Enlatamus.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48\",\"name\":\"David Gimenez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g\",\"caption\":\"David Gimenez\"},\"description\":\"Apasionado de internet y de los geniales rincones que ofrece la ciudad de Zaragoza. Mi objetivo es compartir con vosotros mi inquietud por descubrir lugares, personas y eventos especiales.\",\"sameAs\":[\"http:\/\/zaragozaguia.com\",\"zaragoza.guia.2\",\"https:\/\/twitter.com\/zgzguia\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/david\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares - Made in Zaragoza","description":"La idea \"Encuentros de azoteas\" naci\u00f3 en 2012 en Sevilla de la mano de Redetejas, la primera comunidad de micro espacios culturales en azoteas privadas. En Zaragoza el proyecto est\u00e1 impulsado por Helena Mill\u00e1n de Demba Producciones y Carmina Gustr\u00e1n de Enlatamus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/","og_locale":"es_ES","og_type":"article","og_title":"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares - Made in Zaragoza","og_description":"La idea \"Encuentros de azoteas\" naci\u00f3 en 2012 en Sevilla de la mano de Redetejas, la primera comunidad de micro espacios culturales en azoteas privadas. En Zaragoza el proyecto est\u00e1 impulsado por Helena Mill\u00e1n de Demba Producciones y Carmina Gustr\u00e1n de Enlatamus.","og_url":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"zaragoza.guia.2","article_published_time":"2015-08-25T20:18:52+00:00","article_modified_time":"2015-08-25T20:36:45+00:00","og_image":[{"width":504,"height":378,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/08\/helena-1.jpg","type":"image\/jpeg"}],"author":"David Gimenez","twitter_card":"summary","twitter_creator":"@zgzguia","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"David Gimenez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/"},"author":{"name":"David Gimenez","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48"},"headline":"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares","datePublished":"2015-08-25T20:18:52+00:00","dateModified":"2015-08-25T20:36:45+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/"},"wordCount":899,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"articleSection":["Gente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/","url":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/","name":"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2015-08-25T20:18:52+00:00","dateModified":"2015-08-25T20:36:45+00:00","description":"La idea \"Encuentros de azoteas\" naci\u00f3 en 2012 en Sevilla de la mano de Redetejas, la primera comunidad de micro espacios culturales en azoteas privadas. En Zaragoza el proyecto est\u00e1 impulsado por Helena Mill\u00e1n de Demba Producciones y Carmina Gustr\u00e1n de Enlatamus.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/charlamos-con-helena-millan-impulsora-en-zaragoza-de-redetejas-la-primera-ruta-de-actividades-culturales-por-azoteas-particulares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Charlamos con Helena Mill\u00e1n, impulsora en Zaragoza de Redetejas, la primera ruta de actividades culturales por azoteas particulares"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48","name":"David Gimenez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g","caption":"David Gimenez"},"description":"Apasionado de internet y de los geniales rincones que ofrece la ciudad de Zaragoza. Mi objetivo es compartir con vosotros mi inquietud por descubrir lugares, personas y eventos especiales.","sameAs":["http:\/\/zaragozaguia.com","zaragoza.guia.2","https:\/\/twitter.com\/zgzguia"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/david\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/9797"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=9797"}],"version-history":[{"count":9,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/9797\/revisions"}],"predecessor-version":[{"id":9810,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/9797\/revisions\/9810"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/9799"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=9797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=9797"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=9797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}