{"id":8839,"date":"2015-03-17T16:02:16","date_gmt":"2015-03-17T15:02:16","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=8839"},"modified":"2017-11-20T19:34:18","modified_gmt":"2017-11-20T18:34:18","slug":"san-pepe-la-fiesta-universitaria-por-excelencia","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/","title":{"rendered":"San Pepe, la fiesta universitaria por excelencia"},"content":{"rendered":"<p>Desde hace muchos a\u00f1os se celebra\u00a0el d\u00eda de San Jos\u00e9, m\u00e1s conocido como San Pepe, por ser el patr\u00f3n de los ingenieros en la Universidad de Zaragoza.<\/p>\n<h2>Historia de San Pepe<\/h2>\n<p>Aunque esta festividad sea reconocida \u00fanicamente por la fiesta que se celebra bajo el nombre de<strong> San Pepe<\/strong>, en el campus de ingenier\u00eda y arquitectura se celebran diversas actividades, como charlas formativas impartidas por ponentes de distintas especialidades, torneos, concursos, macro paella&#8230;<\/p>\n<p>Al principio la fiesta de San Pepe se hac\u00eda en el propio centro, en el antiguo CPS (Centro Polit\u00e9cnico Superior) ahora denominado EINA (Escuela de Ingenier\u00eda y Arquitectura). Des\bpu\u00e9s paso a ser en el exterior, en los jardines, debido a incidencias varias que se produjeron en el centro.<\/p>\n<p>Posteriormente pas\u00f3 a celebrarse enfrente del campus, en el parking que hay delante de los campos de la Federaci\u00f3n Aragonesa de F\u00fatbol, donde durante unos a\u00f1os de transici\u00f3n los estudiantes pasaban el d\u00eda compartiendo risas y botellas, en una explanada sin m\u00fasica ni actividades paralelas.<\/p>\n<h2>En la actualidad<\/h2>\n<p>Pero todo eso cambi\u00f3. Desde hace unos a\u00f1os la fiesta de <strong>San Pepe<\/strong> se celebra en el Parque de Atracciones de Zaragoza, donde se realizan m\u00faltiples actividades, empezando con\u00a0torneos por la ma\u00f1ana, y acabando con conciertos por la noche. La fiesta universitaria por excelencia, comienza a las 12 de la ma\u00f1ana y se prolonga hasta las 2 de la madrugada.<\/p>\n<p>Desde las 12 de la ma\u00f1ana los universitarios que hayan comprado su entrada, acceden al recinto y pueden disfrutar de las distintas atracciones, torneos de poker, gui\u00f1ote, futbol\u00edn, retos Hunteet, concurso de disfraces, karaoke, zumba, photocall&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8854\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/atraccion.jpg\" alt=\"Fiesta universitaria San Pepe en el Parque de Atracciones de Zaragoza\" width=\"650\" height=\"271\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/atraccion.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/atraccion-300x125.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/atraccion-625x260.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/atraccion-180x75.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/atraccion-350x145.jpg 350w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>Este a\u00f1o las actividades se completan con los conciertos. Como teloneros estar\u00e1n los grupos ganadores del concurso de bandas que se celebr\u00f3 en el C.M.U.Pedro Cerbuna el pasado 27 de Febrero. Los bandas, que deslumbraron al jurado y forman parte del cartel son \u00a0\u00a0Ducks, Ultravioleta y BlueBerry.<\/p>\n<p>El cartel de grupos lo completan Team D\u00b4Luxe, Oscar Mart\u00ednez DJ y los m\u00edticos Gandules que ya son tradici\u00f3n, pues han actuado en las \u00faltimas 3 ediciones de San Pepe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8855\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/concierto.jpg\" alt=\"En San Pepe siempre hay conciertos para acabar la fiesta de la mejor forma posible\" width=\"650\" height=\"271\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/concierto.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/concierto-300x125.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/concierto-625x260.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/concierto-180x75.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/concierto-350x145.jpg 350w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>Fu\u00e9 en San Pepe, hace 2 a\u00f1os, donde <a href=\"http:\/\/hunteet.com\"><strong>Hunteet<\/strong><\/a> realiz\u00f3 su primer reto. Desde entonces han pasado muchos retos, muchas fotos, muchos premios y cada vez m\u00e1s hunteers con la aplicaci\u00f3n instalada en su m\u00f3vil.<\/p>\n<p>Ya est\u00e1 en marcha la<strong><a href=\"http:\/\/hunteet.com\/liga\/san-pepe-lo-peta\"> liga de retos #SanPepeLoPeta<\/a><\/strong>, donde proponemos varios retos desde el d\u00eda 9 de marzo hasta despu\u00e9s de la fiesta del d\u00eda 20, y un mont\u00f3n de premios para los ganadores de cada reto y los 3 primeros clasificados\u00a0de la liga.<\/p>\n<p><a href=\"http:\/\/hunteet.com\/liga\/san-pepe-lo-peta\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8843\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/Banner-web-SanPepe-2015.jpg\" alt=\"Liga en Hunteet San Pepe 2015\" width=\"650\" height=\"271\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/Banner-web-SanPepe-2015.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/Banner-web-SanPepe-2015-300x125.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/Banner-web-SanPepe-2015-625x260.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/Banner-web-SanPepe-2015-180x75.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/Banner-web-SanPepe-2015-350x145.jpg 350w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p>Por todo esto y mucho m\u00e1s, si ten\u00e9is libre el d\u00eda 20 de Marzo, o pod\u00e9is tenerlo, marcad el d\u00eda en el calendario y animaros a pasar un viernes diferente en el el parque de atracciones de Zaragoza, en la fiesta universitaria m\u00e1s famosa de Arag\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde hace muchos a\u00f1os se celebra\u00a0el d\u00eda de San Jos\u00e9, m\u00e1s conocido como San Pepe, por ser el patr\u00f3n de los ingenieros en la Universidad de Zaragoza. Historia de San Pepe Aunque esta festividad sea reconocida \u00fanicamente por la fiesta que se celebra bajo el nombre de San Pepe, en el campus de ingenier\u00eda y &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSan Pepe, la fiesta universitaria por excelencia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":22,"featured_media":8866,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[74,1119],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>San Pepe, la fiesta universitaria por excelencia - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"El pr\u00f3ximo 20 de Marzo, tendr\u00e1 lugar San Pepe, la fiesta universitaria por excelencia, patr\u00f3n de los ingenieros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Pepe, la fiesta universitaria por excelencia - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 20 de Marzo, tendr\u00e1 lugar San Pepe, la fiesta universitaria por excelencia, patr\u00f3n de los ingenieros.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"LasArmasZAC\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-17T15:02:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-20T18:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/imagen-articulo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MadeinZGZ\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MadeinZGZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\"},\"author\":{\"name\":\"MadeinZGZ\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\"},\"headline\":\"San Pepe, la fiesta universitaria por excelencia\",\"datePublished\":\"2015-03-17T15:02:16+00:00\",\"dateModified\":\"2017-11-20T18:34:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"Conciertos\",\"ingenieros\"],\"articleSection\":[\"Qu\u00e9 hacer\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\",\"name\":\"San Pepe, la fiesta universitaria por excelencia - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2015-03-17T15:02:16+00:00\",\"dateModified\":\"2017-11-20T18:34:18+00:00\",\"description\":\"El pr\u00f3ximo 20 de Marzo, tendr\u00e1 lugar San Pepe, la fiesta universitaria por excelencia, patr\u00f3n de los ingenieros.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Pepe, la fiesta universitaria por excelencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\",\"name\":\"MadeinZGZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"caption\":\"MadeinZGZ\"},\"description\":\"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.\",\"sameAs\":[\"LasArmasZAC\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Pepe, la fiesta universitaria por excelencia - Made in Zaragoza","description":"El pr\u00f3ximo 20 de Marzo, tendr\u00e1 lugar San Pepe, la fiesta universitaria por excelencia, patr\u00f3n de los ingenieros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/","og_locale":"es_ES","og_type":"article","og_title":"San Pepe, la fiesta universitaria por excelencia - Made in Zaragoza","og_description":"El pr\u00f3ximo 20 de Marzo, tendr\u00e1 lugar San Pepe, la fiesta universitaria por excelencia, patr\u00f3n de los ingenieros.","og_url":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"LasArmasZAC","article_published_time":"2015-03-17T15:02:16+00:00","article_modified_time":"2017-11-20T18:34:18+00:00","og_image":[{"width":650,"height":650,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/03\/imagen-articulo.jpeg","type":"image\/jpeg"}],"author":"MadeinZGZ","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"MadeinZGZ","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/"},"author":{"name":"MadeinZGZ","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32"},"headline":"San Pepe, la fiesta universitaria por excelencia","datePublished":"2015-03-17T15:02:16+00:00","dateModified":"2017-11-20T18:34:18+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["Conciertos","ingenieros"],"articleSection":["Qu\u00e9 hacer"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/","url":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/","name":"San Pepe, la fiesta universitaria por excelencia - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2015-03-17T15:02:16+00:00","dateModified":"2017-11-20T18:34:18+00:00","description":"El pr\u00f3ximo 20 de Marzo, tendr\u00e1 lugar San Pepe, la fiesta universitaria por excelencia, patr\u00f3n de los ingenieros.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/san-pepe-la-fiesta-universitaria-por-excelencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"San Pepe, la fiesta universitaria por excelencia"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32","name":"MadeinZGZ","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","caption":"MadeinZGZ"},"description":"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.","sameAs":["LasArmasZAC","https:\/\/twitter.com\/madeinzaragoza"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/8839"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=8839"}],"version-history":[{"count":22,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/8839\/revisions"}],"predecessor-version":[{"id":17892,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/8839\/revisions\/17892"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/8866"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=8839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=8839"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=8839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}