{"id":8566,"date":"2015-02-15T17:32:54","date_gmt":"2015-02-15T16:32:54","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=8566"},"modified":"2015-02-15T17:41:57","modified_gmt":"2015-02-15T16:41:57","slug":"lab2034-economia-del-ocio-en-la-zaragoza-de-2034","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/","title":{"rendered":"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8567\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/02\/lab9-1024x724.jpg\" alt=\"lab9\" width=\"662\" height=\"468\" \/><\/p>\n<p>A modo de prefacio\u2026<\/p>\n<p>Caracter\u00edsticas b\u00e1sicas del turista que visita Zaragoza (2014):<\/p>\n<ul>\n<li>Menor de 50 a\u00f1os<\/li>\n<li>Nivel cultural medio-alto<\/li>\n<li>Gasto medio por persona y d\u00eda: 30-60\u20ac, sin incluir alojamiento<\/li>\n<li>Viaja en coche propio<\/li>\n<li>Viaja en pareja y familia con hijos<\/li>\n<li>Organizaci\u00f3n propia del viaje<\/li>\n<li>Nivel global de satisfacci\u00f3n muy alto<\/li>\n<li>Estancia media: 1,7 d\u00edas<\/li>\n<\/ul>\n<p>Cuestiones estrat\u00e9gicas de la planificaci\u00f3n de la actividad tur\u00edstica en la ciudad de Zaragoza (2014):<\/p>\n<ol>\n<li>Consolidaci\u00f3n de Zaragoza como Destino Tur\u00edstico Internacional: 750.000 viajeros<\/li>\n<li>Promoci\u00f3n nacional e internacional<\/li>\n<li>Presencia activa mediante las tecnolog\u00edas de la informaci\u00f3n<\/li>\n<li>Servicios tur\u00edsticos b\u00e1sicos<\/li>\n<li>Gastronom\u00eda<\/li>\n<li>Regala Zaragoza<\/li>\n<li>Zaragoza, Ciudad de Congresos<\/li>\n<\/ol>\n<p>Es temerario anticipar en qu\u00e9 escenario nos encontraremos en 2034 y creo que es m\u00e1s prudente reflexionar sobre lo que ahora mismo somos capaces de discernir. Y hacerlo desde la humildad intelectual y un m\u00ednimo de escepticismo porque todav\u00eda no sabemos con exactitud lo que nos est\u00e1 pasando ni ad\u00f3nde nos conducir\u00e1 la actualidad.<br \/>\n[\u2026] Contexto general<\/p>\n<p>Las ciudades existen para y por la gente, y no hay duda que los veinte a\u00f1os hasta 2034 es una significativa cantidad de tiempo donde el tama\u00f1o, seguramente menor, y la estructura de la poblaci\u00f3n, seguramente mucho m\u00e1s envejecida, de Zaragoza ser\u00e1n cuestiones fundamentales en la toma de decisiones municipal y oferta de la imagen hacia el exterior.<\/p>\n<p>No hay una f\u00f3rmula sencilla para caracterizar a una \u2018ciudad atractiva\u2019 para el turismo y el bienestar ciudadano general, pero entiendo que los factores primordiales deber\u00edan incluir una adecuada mezcla de: importantes oportunidades de empleo; educaci\u00f3n y ocio\/entretenimiento de calidad; integraci\u00f3n de diferentes culturas y estilos de vida; espacios p\u00fablicos amplios, de calidad y gratuitos; adem\u00e1s de unos servicios de transporte adecuados al ingente reto que el cambio clim\u00e1tico planetario impone.<\/p>\n<p>La econom\u00eda urbana zaragozana actual presenta<strong> fen\u00f3menos emergentes<\/strong> (econom\u00eda colaborativa, P2P, emprendedores individuales o\u00a0colectivos innovadores, centros de innovaci\u00f3n y emprendimiento, etc.) que ponen en entredicho, a modo de ejemplo, hasta qu\u00e9 punto las econom\u00edas de las ciudades son realmente ciudadanas o bien pertenecen todav\u00eda a determinados grupos de inter\u00e9s. Me parecer\u00eda razonable apostar por una nueva econom\u00eda urbana zaragozana que obligatoriamente deber\u00eda ser ciudadana:\u00a0creada por ella, gestionada por ella y orientada ineludiblemente hacia el bienestar y mejora de vida de sus habitantes \/visitantes.<\/p>\n<p>Ser\u00eda no s\u00f3lo deseable sino necesario que Zaragoza y su entorno inmediato supramunicipal se dotase para ello de un\u00a0proyecto\u00a0de ciudad\/territorio de futuro a partir de las din\u00e1micas ciudadanas presentes, las positivas y las negativas, con definici\u00f3n de compromisos e instrumentos a d\u00e9cadas vista. En este sentido, lo que actualmente entendemos por urbanismo (y urbanistas) deber\u00eda\/mos volver a dirigirse\/nos hacia uno de sus objetivos principales de su quehacer: <strong>garantizar el acceso por igual a todos los ciudadanos de los bienes y servicios que ofrece la ciudad, residentes y turistas.<\/strong><\/p>\n<p>Igualmente se deber\u00eda reconsiderar la competitividad global real de Zaragoza en el contexto tur\u00edstico glocal, que condujera a explorar unas necesarias colaboraciones con otras regiones y ciudades, en la actualidad tan escasas. Reconsiderar el concepto de competitividad de la ciudad requerir\u00e1 reflexionar sobre su gobernanza, cuesti\u00f3n que seguro conducir\u00eda a un radical cambio de atenci\u00f3n desde la competencia a la colaboraci\u00f3n (que asegure muy buenas competencias municipales, un entorno empresarial heterog\u00e9neo y unas infraestructuras adecuadas para el futuro).<\/p>\n<p>[\u2026] Contexto tur\u00edstico\/ocio<\/p>\n<p>Algunas sugerencias, sin orden de importancia, sobre las cualidades de una pr\u00f3xima estrategia tur\u00edstica y de ocio de Zaragoza en base al contexto general m\u00e1s arriba apuntado podr\u00edan ser las siguientes:<\/p>\n<p>El futuro del turismo, tambi\u00e9n en Zaragoza, <strong>girar\u00e1 en torno a la emoci\u00f3n a la experiencia, al tipo de cambio (moneda) y al precio del petr\u00f3leo<\/strong><\/p>\n<p><strong>Turismo, cultura, deporte, industrias y tecnolog\u00eda creativas<\/strong> ser\u00edan los deseables servicios de la \u2018nueva econom\u00eda\u2019 zaragozana para 2034<\/p>\n<p>Identidad e Imagen. Una obviedad: la creaci\u00f3n de una imagen positiva requiere fomentar un sentido de identidad<\/p>\n<p>Necesidad de adaptaci\u00f3n con rapidez a los nuevos modelos de organizaci\u00f3n de la tur\u00edstica nacional y global, a los cambios en la comunicaci\u00f3n y a los cambios en el concepto de valor<\/p>\n<p>El<strong> cambio clim\u00e1tico<\/strong> ya est\u00e1 teniendo un profundo impacto en el turismo y en los destinos donde el turista se siente c\u00f3modo en visitar. Zaragoza deber\u00e1 variar su oferta respecto a la actual, centrada en \u00e9poca estival, maximizando a su vez la sostenibilidad ambiental de sus actividades (oportunidad empresarial)<\/p>\n<p>Convertir a los medios y plataformas digitales como los canales de conocimiento, comercializaci\u00f3n, opini\u00f3n, etc., de la marca Zaragoza<\/p>\n<p>Atracci\u00f3n y destino. Disponer de un programa de actividades atractivo y continuo ofrece a la gente una raz\u00f3n para venir a un lugar y volver<\/p>\n<p>Regular adecuadamente y reforzar la oferta de productos y servicios tur\u00edsticos no oficiales<\/p>\n<p>Fomento de actividades comerciales en espacios urbanos seguros. El urbanismo debe propiciar la generaci\u00f3n de espacios seguros, dedicados al ciudadano, al paseo y al encuentro. Deber\u00edan ejecutarse amplios programas de peatonalizaci\u00f3n de calles y entornos principales de la ciudad, con una modificaci\u00f3n sustancial del modelo de transporte actual<\/p>\n<p>Gesti\u00f3n.<strong> Entidades ciudadanas activas<\/strong>, no pol\u00edticas, que gestionen sus espacios podr\u00edan ser claves para el \u00e9xito de una determinada calle y\/o barrio. El \u00e9xito tur\u00edstico vendr\u00e1 posterior al \u00e9xito ciudadano local<\/p>\n<p>Huir de sistemas de ordenaci\u00f3n de la oferta tur\u00edstica ins\u00edpidos y unidimensionales hacia otros menos formales, pero igualmente \u201cplanificados\u201d, creando una mayor densidad y complejidad en la experiencia cotidiana y del visitante<\/p>\n<p><strong>Especializaci\u00f3n de la oferta tur\u00edstica y de ocio<\/strong>. Particularismo cultural local (p.e. turismo sefard\u00ed, Goya, medioambiental, etc.) y de grupos glocales (milenials, singles, mimals, gamers, geocatching, etc.)<\/p>\n<p>Apreciar y proteger las especificidades locales, la idiosincrasia y el detalle, las cosas que pueden hacen a Zaragoza un lugar \u00fanico<\/p>\n<p>Apuesta clara y decidida por el turista local, nacional y europeo, (dependiendo de los condicionantes econ\u00f3micos y medioambientales del sistema energ\u00e9tico global)<\/p>\n<p>Reforzar las <strong>cadenas hoteleras h\u00edper-locales<\/strong> (\u00bfHoteles 10 kil\u00f3metros?), que se distinguen por conseguir todos sus servicios, productos, empleados, etc., en un radio muy cercano a Zaragoza<\/p>\n<p>Retroalimentar el cuidado del medio ambiente con la actividad tur\u00edstica. Por ejemplo: hoteles \u2018inteligentes\u2019 donde el menor gasto de agua, luz, etc., redunde en una reducci\u00f3n de la factura final del visitante<\/p>\n<p>Posicionar claramente la marca \u2018Zaragoza\u2019 hacia los movimientos slow: slow-food, slow-movement, slow-museums, etc.<\/p>\n<p>A modo de epitafio\u2026<\/p>\n<p>Supuestas caracter\u00edsticas b\u00e1sicas del turista que visita Zaragoza (2034)<\/p>\n<ul>\n<li>Edad mental: 40 a\u00f1os; edad f\u00edsica: 50 a\u00f1os; edad real: &gt; 60 a\u00f1os<\/li>\n<li>Nivel cultural: medio-bajo (nivel MOC)<\/li>\n<li>Gasto medio por persona y d\u00eda: 50 \u20ac, incluyendo alojamiento<\/li>\n<li>No viaja en coche propio (el precio del petr\u00f3leo y UBER III hacen que nadie disponga de coche propio)<\/li>\n<li>Viaje en familias con hijos, milenials, singles, mimals, gamers, estancias digitales no presenciales<\/li>\n<li>Sin organizaci\u00f3n previa del viaje y compra instant\u00e1nea<\/li>\n<li>Nivel global de satisfacci\u00f3n: par\u00e1metro no estudiado<\/li>\n<li>Estancia media: 1 d\u00eda<\/li>\n<\/ul>\n<p>La resilencia de la econom\u00eda de Zaragoza en estos pr\u00f3ximos lustros depender\u00e1 de su capacidad para adaptarse a las cambiantes demandas y requisitos de sus ciudadanos diarios o temporales, e industrias, manteniendo al mismo tiempo una fuerte capacidad para hacer frente a eventos impactantes y condiciones de incertidumbre que est\u00e1n fuera de las medidas razonables de control.<\/p>\n<p style=\"color: #666666;\"><strong>Relato por\u00a0Javier Albisu Iribe<\/strong><\/p>\n<p style=\"color: #666666;\"><strong>Ilustraci\u00f3n por David Guirao<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A modo de prefacio\u2026 Caracter\u00edsticas b\u00e1sicas del turista que visita Zaragoza (2014): Menor de 50 a\u00f1os Nivel cultural medio-alto Gasto medio por persona y d\u00eda: 30-60\u20ac, sin incluir alojamiento Viaja en coche propio Viaja en pareja y familia con hijos Organizaci\u00f3n propia del viaje Nivel global de satisfacci\u00f3n muy alto Estancia media: 1,7 d\u00edas Cuestiones &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034\u00bb<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":8567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1047],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034 - Made in Zaragoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034 - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"A modo de prefacio\u2026 Caracter\u00edsticas b\u00e1sicas del turista que visita Zaragoza (2014): Menor de 50 a\u00f1os Nivel cultural medio-alto Gasto medio por persona y d\u00eda: 30-60\u20ac, sin incluir alojamiento Viaja en coche propio Viaja en pareja y familia con hijos Organizaci\u00f3n propia del viaje Nivel global de satisfacci\u00f3n muy alto Estancia media: 1,7 d\u00edas Cuestiones &hellip; Continuar leyendo &quot;LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-15T16:32:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-15T16:41:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/02\/lab9-e1424017654554.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"802\" \/>\n\t<meta property=\"og:image:height\" content=\"494\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Zaragoza Activa\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zaragoza Activa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\"},\"author\":{\"name\":\"Zaragoza Activa\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b983916b11d48551cab263fa5b95293d\"},\"headline\":\"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034\",\"datePublished\":\"2015-02-15T16:32:54+00:00\",\"dateModified\":\"2015-02-15T16:41:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\"},\"wordCount\":1297,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"lab2034\"],\"articleSection\":[\"Tendencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\",\"name\":\"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034 - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2015-02-15T16:32:54+00:00\",\"dateModified\":\"2015-02-15T16:41:57+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b983916b11d48551cab263fa5b95293d\",\"name\":\"Zaragoza Activa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/a39361a4d4483d939a93c3eab27b32c9?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/a39361a4d4483d939a93c3eab27b32c9?s=96&d=mm&r=g\",\"caption\":\"Zaragoza Activa\"},\"description\":\"Somos un servicio p\u00fablico cuya misi\u00f3n es impulsar un ecosistema emprendedor, innovador, creativo y colaborativo en Zaragoza. Queremos apoyar aquellas iniciativas que generan actividad econ\u00f3mica, especialmente, aquellas capaces de crear empleo y un impacto social transformador. Nuestra sede principal se halla en La Azucarera, una F\u00e1brica de ideas, proyectos y conocimiento. Zaragoza Activa tambi\u00e9n cuenta con el Centro de Econom\u00eda Creativa de las Armas, polo creativo y cultural en la ciudad.\",\"sameAs\":[\"http:\/\/www.zaragoza.es\/activa\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/zaragoza-activa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034 - Made in Zaragoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/","og_locale":"es_ES","og_type":"article","og_title":"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034 - Made in Zaragoza","og_description":"A modo de prefacio\u2026 Caracter\u00edsticas b\u00e1sicas del turista que visita Zaragoza (2014): Menor de 50 a\u00f1os Nivel cultural medio-alto Gasto medio por persona y d\u00eda: 30-60\u20ac, sin incluir alojamiento Viaja en coche propio Viaja en pareja y familia con hijos Organizaci\u00f3n propia del viaje Nivel global de satisfacci\u00f3n muy alto Estancia media: 1,7 d\u00edas Cuestiones &hellip; Continuar leyendo \"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034\"","og_url":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2015-02-15T16:32:54+00:00","article_modified_time":"2015-02-15T16:41:57+00:00","og_image":[{"width":802,"height":494,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2015\/02\/lab9-e1424017654554.jpg","type":"image\/jpeg"}],"author":"Zaragoza Activa","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Zaragoza Activa","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/"},"author":{"name":"Zaragoza Activa","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b983916b11d48551cab263fa5b95293d"},"headline":"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034","datePublished":"2015-02-15T16:32:54+00:00","dateModified":"2015-02-15T16:41:57+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/"},"wordCount":1297,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["lab2034"],"articleSection":["Tendencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/","url":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/","name":"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034 - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2015-02-15T16:32:54+00:00","dateModified":"2015-02-15T16:41:57+00:00","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/lab2034-economia-del-ocio-en-la-zaragoza-de-2034\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"LAB2034 Econom\u00eda del Ocio en la Zaragoza de 2034"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/b983916b11d48551cab263fa5b95293d","name":"Zaragoza Activa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/a39361a4d4483d939a93c3eab27b32c9?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/a39361a4d4483d939a93c3eab27b32c9?s=96&d=mm&r=g","caption":"Zaragoza Activa"},"description":"Somos un servicio p\u00fablico cuya misi\u00f3n es impulsar un ecosistema emprendedor, innovador, creativo y colaborativo en Zaragoza. Queremos apoyar aquellas iniciativas que generan actividad econ\u00f3mica, especialmente, aquellas capaces de crear empleo y un impacto social transformador. Nuestra sede principal se halla en La Azucarera, una F\u00e1brica de ideas, proyectos y conocimiento. Zaragoza Activa tambi\u00e9n cuenta con el Centro de Econom\u00eda Creativa de las Armas, polo creativo y cultural en la ciudad.","sameAs":["http:\/\/www.zaragoza.es\/activa"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/zaragoza-activa\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/8566"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=8566"}],"version-history":[{"count":1,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/8566\/revisions"}],"predecessor-version":[{"id":8568,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/8566\/revisions\/8568"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/8567"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=8566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=8566"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=8566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}