{"id":5244,"date":"2013-05-28T18:16:10","date_gmt":"2013-05-28T17:16:10","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=5244"},"modified":"2013-05-29T11:07:58","modified_gmt":"2013-05-29T10:07:58","slug":"la-ruta-de-los-talleres-abiertos","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/","title":{"rendered":"La ruta de los talleres abiertos"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5270\" title=\"Ruta de los Talleres Abiertos\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n-1024x698.jpg\" alt=\"Ruta de los Talleres Abiertos\" width=\"717\" height=\"489\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n-1024x698.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n-300x204.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n-625x426.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n-180x122.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n-960x654.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n-350x238.jpg 350w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n.jpg 1088w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p>El d\u00eda 9 de junio prep\u00e1rate para salir de tu casa y disfrutar de la primavera creativa de Zaragoza en uno de sus barrios m\u00e1s hist\u00f3ricos de la Ciudad.<\/p>\n<p>La ruta de Los talleres abiertos es una jornada donde<strong> los peque\u00f1os comercios creativos del entorno de La Magdalena permanecer\u00e1n abiertos el domingo desde las 10 de la ma\u00f1ana hasta las 3 de la tarde<\/strong>, ofreciendo una experiencia de shopping \u00fanica: con compras, promociones y descuentos especiales, regalos, talleres creativos, caterings, m\u00fasica en vivo, shootings y diferentes sorpresas.<\/p>\n<p>Cada tienda y taller tendr\u00e1 una dinamizaci\u00f3n especifica, dando especial protagonismo a cada uno de sus comercios. Nosotros te proponemos una ruta de comercios y talleres en el coraz\u00f3n de Zaragoza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5254 aligncenter\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/SEHAHECHOTRIZAS-225x300.jpg\" alt=\"\" width=\"180\" height=\"240\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/SEHAHECHOTRIZAS-225x300.jpg 225w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/SEHAHECHOTRIZAS-300x400.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/SEHAHECHOTRIZAS-180x240.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/SEHAHECHOTRIZAS-350x466.jpg 350w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/SEHAHECHOTRIZAS.jpg 450w\" sizes=\"(max-width: 180px) 85vw, 180px\" \/><\/p>\n<p><strong>Sehahechotrizas,<\/strong> uno de los locales de la C\/San Agustin propone un taller llamado \u201cgirando el torno\u201d. \u201cGirando el torno\u201d es un taller demostrativo y participativo para todos los ni\u00f1os y mayores que quieran probar a mancharse de barro y probar el torno.<\/p>\n<p>En este comercio podr\u00e1s encontrar cer\u00e1mica, joyer\u00eda y artesan\u00eda contempor\u00e1ne<br \/>\nHorario: de 11:30 h a 14 h<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5255 aligncenter\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/canalla2-300x184.jpg\" alt=\"\" width=\"300\" height=\"184\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/canalla2-300x184.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/canalla2-625x384.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/canalla2-180x110.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/canalla2-350x215.jpg 350w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/canalla2.jpg 960w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/p>\n<div>\n<p>En<strong> Canalla<\/strong> podr\u00e1s encontrar un <strong>\u201cVermut Party\u201d<\/strong>en donde durante la jornada tendremos a la DJ. lady funk pinchando en el escaparate de la tienda y con un altavoz en la calle. En este comercio del calzado urbano y dise\u00f1o industrial situado en la C\/Mayor tambi\u00e9n podr\u00e1s encontrar la peque\u00f1a sala de exposiciones denominada Canalla Gallery.Estas son algunas de las sorpresas que podr\u00e1s encontrar en Canalla:<\/p>\n<ul>\n<li><strong>Descuento especial del 20%<\/strong> en las marcas de zapatillas ONITSUKA_TIGER, ADIDAS y GOLA<\/li>\n<li><strong>Vermut<\/strong> para todos los asistentes a la tienda, y algo de picar. Vermut cedido por las bodegas Esteban Castej\u00f3n de Ibdes<\/li>\n<li><strong>Sorteos y regalos<\/strong> cedidos por algunas de las marcas<\/li>\n<\/ul>\n<p>Localizaci\u00f3n: calle Mayor 50.<br \/>\nHorario 11:00- 15:00<\/p>\n<p><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5258 aligncenter\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia-300x200.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia-163x109.jpg 163w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia-105x70.jpg 105w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia-625x416.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia-180x120.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia-350x233.jpg 350w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/esenzia.jpg 960w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n<p><strong>\u201cFoto aperitivo\u201d<\/strong> ser\u00e1 una de las muchas razones para visitar Esenzia en la C\/San Vicente de Pa\u00fal. En esta tienda podr\u00e1s encontrar la <strong>Exposici\u00f3n del trabajo de Momentos fotograf\u00eda<\/strong> tanto con beb\u00e9s, como con mascotas, ya que es su especialidad.<\/p>\n<p>Adem\u00e1s Esenzia en colaboraci\u00f3n con Momentos Fotografias propone un Fotomat\u00f3n de 4 fotos, preparando un peque\u00f1o espaci con prendas para disfrazarse ellos o incluso sus mascotas. Los clientes que compren o participen este d\u00eda en la tienda, obtendr\u00e1n una sesi\u00f3n de fotos del fotomat\u00f3n<\/p>\n<p><strong>Taller de haztelo tu mismo.<\/strong> El taller consistiera en hacerte unos pendientes, anillo o collar en formato bot\u00f3n.2 o 3 euros el taller o si compras ese d\u00eda el taller sera gratuito<\/p>\n<p>En resumen, Esenzia ofrece un peque\u00f1o taller una dinamizaci\u00f3n fotogr\u00e1fica, m\u00fasica y aperitivo<br \/>\n\u00a1Ah! y un <strong>descuento del 10%<\/strong> a todos que hagan sus compras ese d\u00eda.<\/p>\n<p><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5259 aligncenter\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade-300x200.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade-163x109.jpg 163w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade-105x70.jpg 105w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade-625x416.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade-180x120.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade-350x233.jpg 350w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/petulacosade.jpg 900w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n<p>Cosa de dos photo y Petula plas presentan <strong>\u201cMiradas entre dos\u201d.\u00a0<\/strong>El espacio lo comparten dos negocios, el estudio de <strong>fotograf\u00eda de Lara Albuixech<\/strong> y el centro de reciclaje creativo de <strong>P\u00e9tula Plas<\/strong>. El taller a\u00fana el trabajo de las dos partes de este espacio, demostrando que dos \u00e1reas tan diferentes pueden trabajar unidas y dar resultados sorprendentes.<\/p>\n<p>El taller estar\u00e1<strong> amenizado por la m\u00fasica de Doctor Gravedad<\/strong> y ofreceremos un verm\u00fa a todos los visitantes.<\/p>\n<p>Localizaci\u00f3n: Doctor Palomar 43, local.<br \/>\nHorario: 1\u00aa parte: 10-12,30 h. 2\u00ba parte de 12.30-14.30 h.<\/p>\n<p>El taller constar\u00e1 de dos partes, por un lado <strong>Lara Albuxech tomar\u00e1 unos retratos de los participantes<\/strong> y, posteriormente, har\u00e1 una edici\u00f3n en blanco y negro. El retrato ser\u00e1 enviado v\u00eda e-mail, en formato web, con firma, a todos los participantes y, a su vez, servir\u00e1n como base para la segunda parte del taller.<\/p>\n<p>La segunda parte la impartir\u00e1 P\u00e9tula Plas, que mostrar\u00e1 a los participantes <strong>c\u00f3mo hacer un anillo con su mirada<\/strong>, para lo cual utilizaremos materiales reciclados y el retrato tomado con anterioridad por Lara Albuixech.<\/p>\n<p>Los participantes al taller obtendr\u00e1n: Un retrato en blanco y negro, en formato web y con firma.\u00a0Un anillo con su mirada, fabricado con materiales reciclados.<\/p>\n<p>Precio: 20 \u20ac.\u00a0Plazas: 15<br \/>\nM\u00e1s info en: info@cosadedosphoto.com<\/p>\n<p><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/griselda.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5260 aligncenter\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/griselda-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/griselda-300x225.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/griselda-625x468.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/griselda-180x135.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/griselda-350x262.jpg 350w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/griselda.jpg 960w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><br \/>\nGRISSELDA es otro de los espacios creativos de la calle San Agust\u00edn en donde podemos encontrar una galer\u00eda-taller de escultura cer\u00e1mica. Para esta jornada Grisselda propone un taller titulado \u201cModela tu mismo, una pieza utilitaria en arcilla\u201d<\/p>\n<p>Horario: Grupo 1. 11:00 a 13:30 de ser necesario Grupo 2. 18:00 a 20:30<\/p>\n<p>Din\u00e1mica\/Taller Taller para adultos, grupo limitado a 5 personas. Coste por persona 15 euros, incluye materiales y horno.<\/p>\n<p>M\u00e1s info en info@grisselda.com<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 9 de junio prep\u00e1rate para salir de tu casa y disfrutar de la primavera creativa de Zaragoza en uno de sus barrios m\u00e1s hist\u00f3ricos de la Ciudad. La ruta de Los talleres abiertos es una jornada donde los peque\u00f1os comercios creativos del entorno de La Magdalena permanecer\u00e1n abiertos el domingo desde las 10 &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa ruta de los talleres abiertos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":22,"featured_media":5270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[296,30,637,696],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La ruta de los talleres abiertos - Made in Zaragoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ruta de los talleres abiertos - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"El d\u00eda 9 de junio prep\u00e1rate para salir de tu casa y disfrutar de la primavera creativa de Zaragoza en uno de sus barrios m\u00e1s hist\u00f3ricos de la Ciudad. La ruta de Los talleres abiertos es una jornada donde los peque\u00f1os comercios creativos del entorno de La Magdalena permanecer\u00e1n abiertos el domingo desde las 10 &hellip; Continuar leyendo &quot;La ruta de los talleres abiertos&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"LasArmasZAC\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-28T17:16:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-05-29T10:07:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1088\" \/>\n\t<meta property=\"og:image:height\" content=\"742\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MadeinZGZ\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MadeinZGZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\"},\"author\":{\"name\":\"MadeinZGZ\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\"},\"headline\":\"La ruta de los talleres abiertos\",\"datePublished\":\"2013-05-28T17:16:10+00:00\",\"dateModified\":\"2013-05-29T10:07:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\"},\"wordCount\":776,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"Esenzia\",\"fotografia\",\"p\u00e9tula plas\",\"ruta de los talleres abiertos\"],\"articleSection\":[\"Qu\u00e9 hacer\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\",\"name\":\"La ruta de los talleres abiertos - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2013-05-28T17:16:10+00:00\",\"dateModified\":\"2013-05-29T10:07:58+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ruta de los talleres abiertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\",\"name\":\"MadeinZGZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"caption\":\"MadeinZGZ\"},\"description\":\"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.\",\"sameAs\":[\"LasArmasZAC\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ruta de los talleres abiertos - Made in Zaragoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/","og_locale":"es_ES","og_type":"article","og_title":"La ruta de los talleres abiertos - Made in Zaragoza","og_description":"El d\u00eda 9 de junio prep\u00e1rate para salir de tu casa y disfrutar de la primavera creativa de Zaragoza en uno de sus barrios m\u00e1s hist\u00f3ricos de la Ciudad. La ruta de Los talleres abiertos es una jornada donde los peque\u00f1os comercios creativos del entorno de La Magdalena permanecer\u00e1n abiertos el domingo desde las 10 &hellip; Continuar leyendo \"La ruta de los talleres abiertos\"","og_url":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"LasArmasZAC","article_published_time":"2013-05-28T17:16:10+00:00","article_modified_time":"2013-05-29T10:07:58+00:00","og_image":[{"width":"1088","height":"742","url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/05\/936794_589951467704063_705905085_n.jpg","type":"image\/jpeg"}],"author":"MadeinZGZ","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"MadeinZGZ","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/"},"author":{"name":"MadeinZGZ","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32"},"headline":"La ruta de los talleres abiertos","datePublished":"2013-05-28T17:16:10+00:00","dateModified":"2013-05-29T10:07:58+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/"},"wordCount":776,"commentCount":2,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["Esenzia","fotografia","p\u00e9tula plas","ruta de los talleres abiertos"],"articleSection":["Qu\u00e9 hacer"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/","url":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/","name":"La ruta de los talleres abiertos - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2013-05-28T17:16:10+00:00","dateModified":"2013-05-29T10:07:58+00:00","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/la-ruta-de-los-talleres-abiertos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"La ruta de los talleres abiertos"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32","name":"MadeinZGZ","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","caption":"MadeinZGZ"},"description":"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.","sameAs":["LasArmasZAC","https:\/\/twitter.com\/madeinzaragoza"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/5244"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=5244"}],"version-history":[{"count":16,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/5244\/revisions"}],"predecessor-version":[{"id":5268,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/5244\/revisions\/5268"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/5270"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=5244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=5244"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=5244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}