{"id":4987,"date":"2013-04-25T10:00:43","date_gmt":"2013-04-25T09:00:43","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=4987"},"modified":"2017-11-20T19:28:59","modified_gmt":"2017-11-20T18:28:59","slug":"lo-viejo-mola","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/","title":{"rendered":"Lo viejo mola"},"content":{"rendered":"<p>Lo viejo est\u00e1 de moda y algunos objetos y prendas ya olvidadas son tendencia destacada para esta primavera-verano.<br \/>\nNada de piezas vintage, ni tesoros encontrados en mercadillos&#8230; es menos glamourosa, una tendencia m\u00e1s f\u00e1cil de seguir.<\/p>\n<p>Viene ocurriendo de unos a\u00f1os a esta parte, que una pieza olvidada renace cual ave f\u00e9nix, para colarse en los armarios de todo el mundo. Eso si, con un re-styling como dios manda. Se\u00f1oritas y se\u00f1oritos vayan guardando las camisetas fl\u00faor de los 90 que os veo venir&#8230;adem\u00e1s esa tendencia paso el verano pasado \ud83d\ude09<\/p>\n<p>Reaparecieron en su d\u00eda las zapatillas Victoria, tambi\u00e9n las Puma, pero este a\u00f1o, el a\u00f1o de las sneakers, las reinas sin duda son las <em><strong>new balance.<\/strong><\/em><\/p>\n<p><a href=\"http:\/\/www.canallazaragoza.com\/index.php\/calzado\/2012-03-29-12-34-06\"><strong>Canalla<\/strong> tiene disponibles varios modelos NB<\/a> y alguna joyita m\u00e1s en el mundo zapateril.<\/p>\n<p><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4990\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz.jpg\" alt=\"Zapatillas NewBalance\" width=\"650\" height=\"432\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz.jpg 650w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-300x199.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-163x109.jpg 163w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-105x70.jpg 105w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-625x415.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-180x119.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-350x232.jpg 350w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p>Este a\u00f1o tambi\u00e9n es el a\u00f1o de las <em><strong>gafas espejo<\/strong><\/em>. Si, esas que s\u00f3lo te pon\u00edas para esquiar.\u00a0Las\u00a0hay con cristales azules, verdes, naranjas&#8230; Un consejo, \u00a1abstenerse el modelo aviador con cristales plateados o dorados! Las de este a\u00f1o son m\u00e1s coloristas.<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-4994\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses.jpg\" alt=\"\" width=\"663\" height=\"424\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses.jpg 737w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-300x191.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-625x399.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-180x115.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-350x223.jpg 350w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-110x70.jpg 110w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">En este repaso a lo viejo, y entrando en tema ropa, no me puedo olvidar de los <strong><em>cropped tops<\/em> <\/strong>o &#8216;top ombliguero&#8217; de toda la vida. De nuevo, no tir\u00e9is los tops de los 90 que no nos valen.\u00a0La culpa de todo, la tuvo Alexander Wang que llego a Balenciaga, empez\u00f3 con la tonter\u00eda en su desfile de este a\u00f1o y mira&#8230; Son muy minimal, con cortes o l\u00edneas muy limpias y de colores neutros.<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5000\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top.jpg\" alt=\"\" width=\"614\" height=\"316\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-300x154.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-625x321.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-180x92.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-960x493.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-350x179.jpg 350w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">En esta misma l\u00ednea, la tendencia <em>sport chic<\/em>, \u00a1de nuevo que nadie se lance a por el chandal, no vale! Mejor os pas\u00e1is por <a href=\"https:\/\/www.facebook.com\/Shuaveshop?fref=ts\">Shuave<\/a> o por la web de Imascono, que sus camisetas y sudaderas si encajan con este s<em>port chic<\/em>.<\/p>\n<p style=\"text-align: left;\">Os dejo asimilando estas tres piezas clave de esta primavera verano y otro d\u00eda os cuento m\u00e1s sobre esta ultima tendencia y otras. \u00bfAlguna forma parte ya de vuestro armario?<\/p>\n<div id='gallery-1' class='gallery galleryid-4987 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Zapatillas NewBalance\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new-balance-shocking-pink.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new-balance-shocking-pink-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new-balance-shocking-pink-150x150.png 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new-balance-shocking-pink-160x160.png 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new-balance-shocking-pink-40x40.png 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new-balance-shocking-pink-70x70.png 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new_balance_bici.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new_balance_bici-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new_balance_bici-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new_balance_bici-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new_balance_bici-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/new_balance_bici-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/The-Sartorialist+new-balance.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/The-Sartorialist+new-balance-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/The-Sartorialist+new-balance-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/The-Sartorialist+new-balance-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/The-Sartorialist+new-balance-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/The-Sartorialist+new-balance-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-sunglasses-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Colored-Mirror-Sunglasses.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Colored-Mirror-Sunglasses-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Colored-Mirror-Sunglasses-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Colored-Mirror-Sunglasses-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Colored-Mirror-Sunglasses-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Colored-Mirror-Sunglasses-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirror-sunglasses-azules.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirror-sunglasses-azules-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirror-sunglasses-azules-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirror-sunglasses-azules-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirror-sunglasses-azules-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirror-sunglasses-azules-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-deloRusso.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-deloRusso-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-deloRusso-150x150.jpeg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-deloRusso-160x160.jpeg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-deloRusso-40x40.jpeg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-deloRusso-70x70.jpeg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-GBattaglia.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-GBattaglia-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-GBattaglia-150x150.jpeg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-GBattaglia-160x160.jpeg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-GBattaglia-40x40.jpeg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/mirrored-glasses-GBattaglia-70x70.jpeg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Tendencia-cropped-top.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Tendencia-cropped-top-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Tendencia-cropped-top-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Tendencia-cropped-top-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Tendencia-cropped-top-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Tendencia-cropped-top-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Balenciaga-cropped-top-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Crop-Top-Streetstyle-01.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Crop-Top-Streetstyle-01-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Crop-Top-Streetstyle-01-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Crop-Top-Streetstyle-01-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Crop-Top-Streetstyle-01-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/Crop-Top-Streetstyle-01-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/cropped-top-bloggers.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/cropped-top-bloggers-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/cropped-top-bloggers-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/cropped-top-bloggers-160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/cropped-top-bloggers-40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/cropped-top-bloggers-70x70.jpg 70w\" sizes=\"(max-width: 150px) 85vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Lo viejo est\u00e1 de moda y algunos objetos y prendas ya olvidadas son tendencia destacada para esta primavera-verano. Nada de piezas vintage, ni tesoros encontrados en mercadillos&#8230; es menos glamourosa, una tendencia m\u00e1s f\u00e1cil de seguir. Viene ocurriendo de unos a\u00f1os a esta parte, que una pieza olvidada renace cual ave f\u00e9nix, para colarse en &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLo viejo mola\u00bb<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":4990,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[181,39,180],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo viejo mola - Made in Zaragoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo viejo mola - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Lo viejo est\u00e1 de moda y algunos objetos y prendas ya olvidadas son tendencia destacada para esta primavera-verano. Nada de piezas vintage, ni tesoros encontrados en mercadillos&#8230; es menos glamourosa, una tendencia m\u00e1s f\u00e1cil de seguir. Viene ocurriendo de unos a\u00f1os a esta parte, que una pieza olvidada renace cual ave f\u00e9nix, para colarse en &hellip; Continuar leyendo &quot;Lo viejo mola&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/petit.comite.9\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-25T09:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-20T18:28:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vero Andres\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/PETITCOMITEzgz\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vero Andres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\"},\"author\":{\"name\":\"Vero Andres\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6aacbaa66ac527d9bb64f0a560b22171\"},\"headline\":\"Lo viejo mola\",\"datePublished\":\"2013-04-25T09:00:43+00:00\",\"dateModified\":\"2017-11-20T18:28:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\"},\"wordCount\":355,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"Calzado de dise\u00f1o\",\"moda\",\"zapatillas\"],\"articleSection\":[\"Tendencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\",\"name\":\"Lo viejo mola - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2013-04-25T09:00:43+00:00\",\"dateModified\":\"2017-11-20T18:28:59+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo viejo mola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6aacbaa66ac527d9bb64f0a560b22171\",\"name\":\"Vero Andres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/b25642b7533aa108f762bf8a0964326b?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/b25642b7533aa108f762bf8a0964326b?s=96&d=mm&r=g\",\"caption\":\"Vero Andres\"},\"description\":\"Inquieta, creativa. Siempre haciendo 1000 cosas a la vez y 2 cosas en la cabeza: ropa y estilismos\",\"sameAs\":[\"http:\/\/asesorasdeimagenenzgz.blogspot.com.es\/\",\"https:\/\/www.facebook.com\/petit.comite.9\",\"https:\/\/twitter.com\/http:\/\/twitter.com\/PETITCOMITEzgz\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/vero-andres\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo viejo mola - Made in Zaragoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/","og_locale":"es_ES","og_type":"article","og_title":"Lo viejo mola - Made in Zaragoza","og_description":"Lo viejo est\u00e1 de moda y algunos objetos y prendas ya olvidadas son tendencia destacada para esta primavera-verano. Nada de piezas vintage, ni tesoros encontrados en mercadillos&#8230; es menos glamourosa, una tendencia m\u00e1s f\u00e1cil de seguir. Viene ocurriendo de unos a\u00f1os a esta parte, que una pieza olvidada renace cual ave f\u00e9nix, para colarse en &hellip; Continuar leyendo \"Lo viejo mola\"","og_url":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"https:\/\/www.facebook.com\/petit.comite.9","article_published_time":"2013-04-25T09:00:43+00:00","article_modified_time":"2017-11-20T18:28:59+00:00","og_image":[{"width":"650","height":"432","url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2013\/04\/newbalance_zgz.jpg","type":"image\/jpeg"}],"author":"Vero Andres","twitter_card":"summary","twitter_creator":"@http:\/\/twitter.com\/PETITCOMITEzgz","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Vero Andres","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/"},"author":{"name":"Vero Andres","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6aacbaa66ac527d9bb64f0a560b22171"},"headline":"Lo viejo mola","datePublished":"2013-04-25T09:00:43+00:00","dateModified":"2017-11-20T18:28:59+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/"},"wordCount":355,"commentCount":2,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["Calzado de dise\u00f1o","moda","zapatillas"],"articleSection":["Tendencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/","url":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/","name":"Lo viejo mola - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2013-04-25T09:00:43+00:00","dateModified":"2017-11-20T18:28:59+00:00","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/lo-viejo-mola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Lo viejo mola"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6aacbaa66ac527d9bb64f0a560b22171","name":"Vero Andres","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/b25642b7533aa108f762bf8a0964326b?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/b25642b7533aa108f762bf8a0964326b?s=96&d=mm&r=g","caption":"Vero Andres"},"description":"Inquieta, creativa. Siempre haciendo 1000 cosas a la vez y 2 cosas en la cabeza: ropa y estilismos","sameAs":["http:\/\/asesorasdeimagenenzgz.blogspot.com.es\/","https:\/\/www.facebook.com\/petit.comite.9","https:\/\/twitter.com\/http:\/\/twitter.com\/PETITCOMITEzgz"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/vero-andres\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/4987"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=4987"}],"version-history":[{"count":27,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/4987\/revisions"}],"predecessor-version":[{"id":17614,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/4987\/revisions\/17614"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/4990"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=4987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=4987"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=4987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}