{"id":42754,"date":"2024-11-20T09:03:10","date_gmt":"2024-11-20T08:03:10","guid":{"rendered":"https:\/\/madeinzaragoza.es\/blog\/?p=42754"},"modified":"2024-11-22T10:48:46","modified_gmt":"2024-11-22T09:48:46","slug":"fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/","title":{"rendered":"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d"},"content":{"rendered":"\n<p><strong>\u201cSomos Zaragoza\u201d vuelve<\/strong>, pero en este caso son los vecinos, estudiantes, trabajadores y comercios de <strong>Valdespartera las caras protagonistas<\/strong> de esta <strong>acci\u00f3n fotogr\u00e1fica y sonora participativa<\/strong> \u00a1Una nueva mirada para conocer el barrio de Valdespartera!<\/p>\n\n\n\n<p>Se trata de una <strong>acci\u00f3n global creada<\/strong> por el estudio <a href=\"https:\/\/www.fotosynthesiscommunity.org\/es\/\">Fotosynthesis<\/a> e <a href=\"https:\/\/www.insideoutproject.net\/es\/photobooth\">Inside out<\/a>. Contar\u00e1 con <strong>2 exposiciones<\/strong> con al rededor de <strong>50 retratos en blanco y negro a gran escala con QRs de audio<\/strong> donde los habitantes del barrio comparten su d\u00eda a d\u00eda \u00bfQui\u00e9n mejor para mostrarte el encanto de la vida en Valdespartera?<\/p>\n\n\n\n<p>Ya pudimos disfrutar de esta acci\u00f3n art\u00edstica en el <strong><a href=\"https:\/\/madeinzaragoza.es\/blog\/exposicion-somos-zaragoza-retratos-y-voces-del-gancho\/\">barrio del Gancho<\/a><\/strong> y gracias a su <strong>gran aceptaci\u00f3n<\/strong>, <strong>durante noviembre y diciembre<\/strong> podemos disfrutar de la acci\u00f3n <a href=\"https:\/\/www.insideoutproject.net\/es\/explore\/group-action\/somos-zaragoza-voces-y-retratos-de-valdespartera-1\">\u201cSomos Valdespartera\u201d<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fotograf\u00eda, proyectos cinematogr\u00e1ficos y producci\u00f3n audiovisual participativa.<\/h2>\n\n\n\n<p>Esta empresa creativa <strong>fue creada en Londres<\/strong> (Reino Unido) en el a\u00f1o <strong>2009<\/strong> y en <strong>2023 lleg\u00f3 a Espa\u00f1a<\/strong> con la firme convicci\u00f3n de que las <strong>producciones fotogr\u00e1ficas y audiovisuales deben promover la convivencia, abrir puertas, crear puentes y di\u00e1logo, y dar visibilidad para crear nuevas narrativas con cuidado, \u00e9tica y participaci\u00f3n.<\/strong><\/p>\n\n\n\n<p>A trav\u00e9s de<strong> talleres, formaciones, colaboraciones y producciones art\u00edsticas<\/strong>, Fotosynthesis lleva <strong>15 a\u00f1os <\/strong>utilizando las <strong>im\u00e1genes y sonidos como herramientas<\/strong> inclusivas y creativas para conectar, comunicar, abogar, educar, dialogar, promover la participaci\u00f3n e inclusi\u00f3n y <strong>crear nuevas narrativas<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"42765\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297895524-1024x766.jpg\" alt=\"\" class=\"wp-image-42765\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297895524-1024x766.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297895524-450x337.jpg 450w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297895524-768x574.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297895524-1536x1149.jpg 1536w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297895524-2048x1532.jpg 2048w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297895524-1200x898.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Proceso grabaci\u00f3n de audios<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"657\" data-id=\"42767\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-valdespartera-Fotoshyntesis-made-in-zaragoza-1-1024x657.jpg\" alt=\"\" class=\"wp-image-42767\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-valdespartera-Fotoshyntesis-made-in-zaragoza-1-1024x657.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-valdespartera-Fotoshyntesis-made-in-zaragoza-1-450x289.jpg 450w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-valdespartera-Fotoshyntesis-made-in-zaragoza-1-768x493.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-valdespartera-Fotoshyntesis-made-in-zaragoza-1-1536x986.jpg 1536w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-valdespartera-Fotoshyntesis-made-in-zaragoza-1-2048x1314.jpg 2048w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-valdespartera-Fotoshyntesis-made-in-zaragoza-1-1200x770.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Alejandro grabando los relatos<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>\u00a1Conozcamos al<a href=\"https:\/\/www.fotosynthesiscommunity.org\/es\/equipo\/\"> equipo<\/a>!&nbsp; <strong>Ingrid y Alejandro<\/strong> <strong>se conocieron en Barcelona<\/strong> trabajando en un documental y ahora ambos viven en Zaragoza y <strong>son parte del <a href=\"https:\/\/clusterclada.es\/\">Cluster de Audiovisual de Arag\u00f3n<\/a><\/strong>.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ingridguyon.com\/\">Ingrid Guyon<\/a> (francesa) es <strong>fot\u00f3grafa, camar\u00f3grafa, editora, realizadora y facilitadora experta en medios audiovisuales participativos.<\/strong> La fundadora de Fotosynthesis naci\u00f3 en<a href=\"https:\/\/www.france-voyage.com\/francia-guia-turismo\/chalon-saone-1217.htm\"> Chal\u00f3n sur Saone<\/a>, donde Nic\u00e9phore Niepce <strong>tom\u00f3 la primera fotograf\u00eda de la historia<\/strong>, lo que produce que el amor y pasi\u00f3n por la fotograf\u00eda haya estado muy presente en su familia.<\/p>\n\n\n\n<p>Vivi\u00f3 casi 2 d\u00e9cadas en Londres y se gradu\u00f3 en <strong>Fotograf\u00eda Profesional y Fotograf\u00eda Anal\u00f3gica en University of the Arts, London College of Communication y Antropolog\u00eda Social y visual de Birbeck University<\/strong>.<\/p>\n\n\n\n<p>Ha <strong>dirigido<\/strong> varios <strong>cortometrajes y formaciones de fotograf\u00eda y video participativo<\/strong> para varias <strong>ONGS internacionales e instituciones<\/strong> y proyectos de <strong>investigaci\u00f3n participativa<\/strong> con colectivos vulnerables (migraci\u00f3n, derechos humanos, g\u00e9nero, paz y juventud).&nbsp;<\/p>\n\n\n\n<p>Dentro de sus <strong>\u00faltimos trabajos<\/strong> encontramos un <strong>manual de Fotograf\u00eda de paz <\/strong>y una<strong> investigaci\u00f3n<\/strong> del <a href=\"https:\/\/www.kcl.ac.uk\/\">King\u00b4s College de Londres<\/a> sobre el uso de la fotograf\u00eda participativa, comunitaria y colaborativa como herramienta para fomentar la paz.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, se declara una <strong>apasionada de la experimentaci\u00f3n y procesos tradicionales de la fotograf\u00eda anal\u00f3gica<\/strong>, <strong>hist\u00f3rica<\/strong> y de la<strong> impresi\u00f3n en diferentes soportes<\/strong> con material reciclable y luz solar. As\u00ed como crear laboratorios de cuartos oscuros o instalaciones itinerantes.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1006\" height=\"871\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-somos-zaragoza-made-in-zaragoza.jpg\" alt=\"\" class=\"wp-image-42757\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-somos-zaragoza-made-in-zaragoza.jpg 1006w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-somos-zaragoza-made-in-zaragoza-450x390.jpg 450w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-somos-zaragoza-made-in-zaragoza-768x665.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Ingrid Guyon<\/figcaption><\/figure>\n\n\n\n<p><strong>Alejandro Molano V\u00e1squez<\/strong> (Colombia) es un <strong>amante del cine, sonidista, camar\u00f3grafo, m\u00fasico, cantante y director de actores<\/strong>. <strong>Se form\u00f3<\/strong> para intervenir en diversos <strong>procesos creativos<\/strong> y se gradu\u00f3 en <strong>Licenciatura en Artes Visuales de la Universidad Pedag\u00f3gica Nacional<\/strong> y en<strong> Direcci\u00f3n de Actores<\/strong> por el Estudio Babel en Bogot\u00e1.&nbsp;<\/p>\n\n\n\n<p>Ahora imparte <strong>talleres de arte visual y esc\u00e9nicas<\/strong> en diferentes <strong>casas de juventud<\/strong>, como <strong>sonidista para productoras aragonesas<\/strong> y trabaja codo con codo, con Ingrid como<strong> cocreador de Fotosynthesis Espa\u00f1a<\/strong> . A su vez, se ha estrenado como <strong>director con su primer largometraje<\/strong> y ha escrito <strong>varios guiones para sus cortos<\/strong>. Gracias a su talento ha participado en <strong>varios documentales y ficciones<\/strong> junto a <a href=\"https:\/\/www.gusano.org\/\">Gusano Films <\/a><strong>nominados en diferentes festivales<\/strong> nacionales e internacionales (Los Goya en 2022 y 2023) y ha tenido la oportunidad de <strong>trabajar <\/strong>con el director espa\u00f1ol,<strong> El\u00edas Siminiani<\/strong> y el gran <strong>cineasta colombiano<\/strong>, <strong>Luis Ospina.<\/strong><\/p>\n\n\n\n<p>Tiene <strong>gran experiencia <\/strong>en la <strong>grabaci\u00f3n de sonidos en lugares remotos<\/strong> y en <strong>condiciones adversas<\/strong>. Tambi\u00e9n fue <strong>docente en el SENA<\/strong> (Colombia) y <strong>facilitador audiovisual<\/strong> y de guiones con<strong> j\u00f3venes, mujeres, comunidad LGBTQ <\/strong>en Colombia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"858\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Aljandro-somos-zaragoza-Made-in-Zaragoza-1024x858.jpg\" alt=\"\" class=\"wp-image-42759\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Aljandro-somos-zaragoza-Made-in-Zaragoza-1024x858.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Aljandro-somos-zaragoza-Made-in-Zaragoza-450x377.jpg 450w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Aljandro-somos-zaragoza-Made-in-Zaragoza-768x644.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Aljandro-somos-zaragoza-Made-in-Zaragoza-1200x1006.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Aljandro-somos-zaragoza-Made-in-Zaragoza.jpg 1280w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Alejandro Molano<\/figcaption><\/figure>\n\n\n\n<p>Aunque Fotosynthesis Espa\u00f1a fue fundado entre ambos creativos, han contado con la ayuda de <strong>Jorge Terrer<\/strong> para este proyecto. <\/p>\n\n\n\n<p><strong>Conoci\u00f3 a Ingrid durante un curso de fotograf\u00eda anal\u00f3gica<\/strong> en el <a href=\"https:\/\/cpaformacion.com\/conoce-cpa\/\">CPA<\/a> y pas\u00f3 a formar parte del equipo como <strong>ayudante de producci\u00f3n<\/strong> para esta acci\u00f3n y la anterior. Gracias a su talento, Jorge siempre ha estado muy relacionado con el mundo audiovisual y ha sido imprescindible para llevar a cabo esta acci\u00f3n.<\/p>\n\n\n\n<p>Adem\u00e1s, \u00bfC\u00f3mo no formar parte del proyecto si hasta tu madre participa? Deber\u00e1s buscar su retrato como trabajadora del Valdespartera durante la expo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Del barrio del Gancho a Valdespartera.<\/h2>\n\n\n\n<p>El proyecto Inside Out es un proyecto de arte participativo global que permite a todo el mundo compartir sus historias no contadas mediante la creaci\u00f3n de una obra de arte p\u00fablico. Los participantes comparten su mensaje con el mundo, exponiendo retratos en blanco y negro a gran escala en espacios p\u00fablicos.&nbsp;<\/p>\n\n\n\n<p>El objetivo es provocar un cambio global a nivel local. Desde 2011, cerca de 600.000 personas de 152 pa\u00edses y territorios han participado en el proyecto Inside Out. La primera acci\u00f3n de Inside Out y Fotoshyntesis en Espa\u00f1a y gracias al apoyo del Ayuntamiento de Zaragoza, Zaragoza Cultural y el PICH, fue en el barrio del Gancho al principio del 2024 \u00a1Una de las primeras acciones mundiales que incluy\u00f3 QR de audio acompa\u00f1ando los retratos!<\/p>\n\n\n\n<p>Ahora es el turno de Valdespartera \u00bfY por qu\u00e9 esta zona? Confiesan que como cineastas, les llam\u00f3 mucho la atenci\u00f3n que 89 calles de este barrio tuvieran nombres de pel\u00edculas. Sintieron curiosidad por su ubicaci\u00f3n. Un barrio alejado del centro, pero con sensaci\u00f3n de cercan\u00eda gracias a las conexiones del tranv\u00eda.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"1024\" data-id=\"42760\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-778x1024.jpg\" alt=\"\" class=\"wp-image-42760\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-778x1024.jpg 778w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-342x450.jpg 342w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-768x1011.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-1167x1536.jpg 1167w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-1556x2048.jpg 1556w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-1200x1579.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/ingrid-en-las-fotografias-de-somos-zaragoza-scaled.jpg 1945w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption class=\"wp-element-caption\">Ingrid realizando los retratos<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1024\" data-id=\"42761\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-750x1024.jpg\" alt=\"\" class=\"wp-image-42761\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-750x1024.jpg 750w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-330x450.jpg 330w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-768x1048.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-1126x1536.jpg 1126w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-1501x2048.jpg 1501w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-1200x1638.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/somos-valdedspartera-nueva-exposicion-scaled.jpg 1876w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption class=\"wp-element-caption\">Estudio montado Centro de Salud de Valdespartera<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>Adem\u00e1s, fue aqu\u00ed donde se rod\u00f3 una de las pel\u00edculas clave de la historia del cine y que hoy le da nombre a una de sus calles: Salom\u00f3n y la reina de Saba (1959).<\/p>\n\n\n\n<p>La idea de dar<strong> visibilidad, celebrar el barrio<\/strong> con <strong>arte callejero y<\/strong> l<strong>levar a Valdespartera al centro de Zaragoza.<\/strong> As\u00ed que surgieron muchas preguntas; \u00bfQui\u00e9n vive y trabaja en estas calles?\u00bfQu\u00e9 les gusta?\u00bfC\u00f3mo llegaron all\u00ed?\u00bfHabr\u00e1n visto las pel\u00edculas de sus calles? \u00bfQu\u00e9 relaci\u00f3n tienen los vecinos con el centro de la ciudad y viceversa?\u00bfQu\u00e9 tejido social y din\u00e1micas comunitarias existen en esa parte del Distrito Sur?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1ndo y d\u00f3nde puedo ver \u201cSomos Valdespartera\u201d?<\/h2>\n\n\n\n<p>Gracias al <a href=\"https:\/\/www.zaragoza.es\/sede\/servicio\/equipamiento\/9091\">Centro de Salud de Valdespartera<\/a>, una de sus salas se transform\u00f3 en <strong>estudio fotogr\u00e1fico y de grabaci\u00f3n<\/strong> <strong>durante varias semanas<\/strong> para conocer a los participantes; El jardinero m\u00e1s joven del huerto comunitario, la 1\u00ba poller\u00eda del mercado, un cantante ingl\u00e9s, el grupo de lactancia, fot\u00f3grafas, emprendedores\u2026 <strong>Despu\u00e9s del largo proceso<\/strong> de entrevistas, fotograf\u00eda, grabaci\u00f3n e impresi\u00f3n muy <strong>pronto<\/strong> podremos ver el <strong>resultado final<\/strong>.&nbsp;<\/p>\n\n\n\n<p>\u201cSomos Valdespartera\u201d consta de <strong>una primera acci\u00f3n<\/strong> de <strong>empapelar la fachada externa del Centro de Salud de Valdespartera<\/strong>. El <strong>1 de diciembre<\/strong>, <strong>todos los participantes<\/strong> podr\u00e1n tomar partido en la acci\u00f3n, ya que ser\u00e1n ellos mismos los que a finales de noviembre, peguen sus retratos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"668\" data-id=\"42763\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297896451-1024x668.jpg\" alt=\"\" class=\"wp-image-42763\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297896451-1024x668.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297896451-450x294.jpg 450w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297896451-768x501.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297896451-1536x1003.jpg 1536w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297896451-2048x1337.jpg 2048w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/1728297896451-1200x783.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Jorge en las grabaciones<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"723\" data-id=\"42764\" src=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/IMG_20240916_161701-1024x723.jpg\" alt=\"\" class=\"wp-image-42764\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/IMG_20240916_161701-1024x723.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/IMG_20240916_161701-450x318.jpg 450w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/IMG_20240916_161701-768x542.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/IMG_20240916_161701-1536x1084.jpg 1536w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/IMG_20240916_161701-2048x1446.jpg 2048w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/IMG_20240916_161701-1200x847.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">Proceso \u00abSomos Valdespartera\u00bb<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>Una experiencia muy enriquecedora y totalmente recomendable que te permitir\u00e1 conocer de cerca a la gente y los \u201cencantos\u201d del barrio.<\/p>\n\n\n\n<p>As\u00ed mismo, el <strong>3 de diciembre de 18 a 20H se inaugurar\u00e1 la exposici\u00f3n<\/strong> \u201cVoces y retratos de Valdespartera\u201d en el centro <a href=\"https:\/\/www.fundacioncai.es\/act\/somos-zaragoza-voces-y-retratos-de-valdespartera\">Centro Joaqu\u00edn Roncal<\/a><a href=\"https:\/\/www.fundacioncai.es\/page\/centro-joaquin-roncal\"> <\/a><strong> (<\/strong>C. de San Braulio, 5) que estar\u00e1 <strong>disponible hasta<\/strong> principios de<strong> enero.<\/strong><\/p>\n\n\n\n<p>Este proyecto requiere muchos meses de trabajo m\u00e1s all\u00e1 de la toma y edici\u00f3n de las fotos y audios, por eso si quieres aportar <strong>tu granito de arena<\/strong>, puedes hacer tu aportaci\u00f3n <a href=\"https:\/\/www.paypal.com\/donate\/?hosted_button_id=BY3CWXMF9BYJJ\">aqu\u00ed <\/a>o tambi\u00e9n es muy \u00fatil si <strong>conoces o dispones de un lugar gratuito<\/strong> en Valdespartera para <strong>organizar una comida comunitaria<\/strong> que una a todos los participantes para celebrar, tejer v\u00ednculos y crear nuevas sinergias despu\u00e9s de las exposiciones.<\/p>\n\n\n\n<p>\u00a1Agenda la fecha! Te recomiendo que no te pierdas <strong>la mirada que nos ofrecen Ingrid y Alejandro<\/strong> sobre <strong>este barrio de nueva construcci\u00f3n<\/strong> situado al sur de Zaragoza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSomos Zaragoza\u201d vuelve, pero en este caso son los vecinos, estudiantes, trabajadores y comercios de Valdespartera las caras protagonistas de esta acci\u00f3n fotogr\u00e1fica y sonora participativa \u00a1Una nueva mirada para conocer el barrio de Valdespartera! Se trata de una acci\u00f3n global creada por el estudio Fotosynthesis e Inside out. Contar\u00e1 con 2 exposiciones con al &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d\u00bb<\/span><\/a><\/p>\n","protected":false},"author":84,"featured_media":42769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[829,9,6,7,1],"tags":[28,1337,130,63,30],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d - Made in Zaragoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"\u201cSomos Zaragoza\u201d vuelve, pero en este caso son los vecinos, estudiantes, trabajadores y comercios de Valdespartera las caras protagonistas de esta acci\u00f3n fotogr\u00e1fica y sonora participativa \u00a1Una nueva mirada para conocer el barrio de Valdespartera! Se trata de una acci\u00f3n global creada por el estudio Fotosynthesis e Inside out. Contar\u00e1 con 2 exposiciones con al &hellip; Continuar leyendo &quot;Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T08:03:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-22T09:48:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-Zaragoza-retratos-y-voces-de-Valdespartera-fotoshyntesis-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nagore Delgado\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nagore Delgado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\"},\"author\":{\"name\":\"Nagore Delgado\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/9a0b249cbeeadd393f2fe8a350f05bae\"},\"headline\":\"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d\",\"datePublished\":\"2024-11-20T08:03:10+00:00\",\"dateModified\":\"2024-11-22T09:48:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\"},\"wordCount\":1435,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"creatividad\",\"Cultura\",\"emprendedores\",\"exposicion\",\"fotografia\"],\"articleSection\":[\"Cultura\",\"Econom\u00eda Creativa\",\"Gente\",\"Qu\u00e9 hacer\",\"Tendencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\",\"name\":\"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2024-11-20T08:03:10+00:00\",\"dateModified\":\"2024-11-22T09:48:46+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/9a0b249cbeeadd393f2fe8a350f05bae\",\"name\":\"Nagore Delgado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/e938711838316a554100b9066f648c31?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/e938711838316a554100b9066f648c31?s=96&d=mm&r=g\",\"caption\":\"Nagore Delgado\"},\"description\":\"Amante de la creatividad y de los proyectos con mucha alma. Mezclo mis dos pasiones, la fotograf\u00eda con el Marketing Digital. Creo y gestiono contenido y estrategias para las RRSS y blogs, a la vez que hago mis pinitos en el mundo del Dise\u00f1o Gr\u00e1fico. Imprescindible la comunicaci\u00f3n, en todas sus formas, pero siempre clara y transparente \u00a1Nos vemos en las redes!\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/nagoredelgado\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d - Made in Zaragoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/","og_locale":"es_ES","og_type":"article","og_title":"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d - Made in Zaragoza","og_description":"\u201cSomos Zaragoza\u201d vuelve, pero en este caso son los vecinos, estudiantes, trabajadores y comercios de Valdespartera las caras protagonistas de esta acci\u00f3n fotogr\u00e1fica y sonora participativa \u00a1Una nueva mirada para conocer el barrio de Valdespartera! Se trata de una acci\u00f3n global creada por el estudio Fotosynthesis e Inside out. Contar\u00e1 con 2 exposiciones con al &hellip; Continuar leyendo \"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d\"","og_url":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2024-11-20T08:03:10+00:00","article_modified_time":"2024-11-22T09:48:46+00:00","og_image":[{"width":2560,"height":1671,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2024\/11\/Somos-Zaragoza-retratos-y-voces-de-Valdespartera-fotoshyntesis-scaled.jpg","type":"image\/jpeg"}],"author":"Nagore Delgado","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Nagore Delgado","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/"},"author":{"name":"Nagore Delgado","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/9a0b249cbeeadd393f2fe8a350f05bae"},"headline":"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d","datePublished":"2024-11-20T08:03:10+00:00","dateModified":"2024-11-22T09:48:46+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/"},"wordCount":1435,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["creatividad","Cultura","emprendedores","exposicion","fotografia"],"articleSection":["Cultura","Econom\u00eda Creativa","Gente","Qu\u00e9 hacer","Tendencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/","url":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/","name":"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2024-11-20T08:03:10+00:00","dateModified":"2024-11-22T09:48:46+00:00","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/fotosynthesis-lanza-una-nueva-edicion-de-la-accion-colaborativa-somos-zaragoza-voces-y-retratos-de-valdespartera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Fotosynthesis lanza una nueva edici\u00f3n de la acci\u00f3n colaborativa; \u201cSomos Zaragoza: Voces y retratos de Valdespartera\u201d"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/9a0b249cbeeadd393f2fe8a350f05bae","name":"Nagore Delgado","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/e938711838316a554100b9066f648c31?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/e938711838316a554100b9066f648c31?s=96&d=mm&r=g","caption":"Nagore Delgado"},"description":"Amante de la creatividad y de los proyectos con mucha alma. Mezclo mis dos pasiones, la fotograf\u00eda con el Marketing Digital. Creo y gestiono contenido y estrategias para las RRSS y blogs, a la vez que hago mis pinitos en el mundo del Dise\u00f1o Gr\u00e1fico. Imprescindible la comunicaci\u00f3n, en todas sus formas, pero siempre clara y transparente \u00a1Nos vemos en las redes!","url":"http:\/\/madeinzaragoza.es\/blog\/author\/nagoredelgado\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/42754"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=42754"}],"version-history":[{"count":12,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/42754\/revisions"}],"predecessor-version":[{"id":42894,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/42754\/revisions\/42894"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/42769"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=42754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=42754"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=42754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}