{"id":36484,"date":"2022-11-10T23:35:00","date_gmt":"2022-11-10T22:35:00","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=36484"},"modified":"2022-11-21T23:37:09","modified_gmt":"2022-11-21T22:37:09","slug":"miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/","title":{"rendered":"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub"},"content":{"rendered":"\n<p>El proceso de trabajo con Luc\u00eda Rodr\u00edguez ha sido muy enriquecedor. Nos centramos en su propuesta de valor y en la estrategia que pod\u00edamos crear en torno a ella. Pusimos foco en sacar todo el partido al potencial del espacio <a href=\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-dasein-hub-un-espacio-unico-de-moda-y-creatividad-que-celebra-un-ano\/\">Dasein Hub<\/a>, la trayectoria y experiencia de Luc\u00eda, y a las <strong>acciones que pod\u00edamos generar para alinearnos con la estrategia.<\/strong><\/p>\n\n\n\n<p>Nuestro objetivo es ayudar a<strong> <\/strong>crecer y dar a conocer Dasein Hub, teniendo muy presente la actividad profesional de Luc\u00eda para que ambas l\u00edneas de actividad se nutran, complementen y enriquezcan.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/_Mc7qK4S1MpwTqQWWxH2D42rsmiMGYWo2f3eg9eu0lKqHdz6qx5vmfMm0sV-9UCgON-cHQu9edlphfYCSpLJarMF2pa0jAuKfb07siTZHdyNHbRJCQ70kGllh0dESYW193WlD3hCAdgKLArJhf4Px5ky-iM0-Vd2nnpM3eOBplJg64-bWdYutbmcE-pJ\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n\n\n<p>Una de las acciones clave tiene que ver con<strong> sacar partido al potencial del espacio<\/strong> y generar talleres y eventos con otros creadores para mantenerlo vivo sin que a Luc\u00eda le suponga invertir mucho tiempo y energ\u00eda (que necesita para lanzar sus colecciones).<\/p>\n\n\n\n<p>Por otro lado, poner en marcha la <strong>oferta de clases y actividades regulares<\/strong>, que llenar\u00e1n el espacio de vida. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Cuando se est\u00e1 al frente de un negocio siempre hay mucho por hacer y el tiempo pasa volando, por eso nos centramos en planificar y priorizar las actividades y revisar las tareas que es posible delegar.&nbsp;<\/p><\/blockquote>\n\n\n\n<p>En cuanto a la faceta profesional de Luc\u00eda, es clave fomentar las <strong>prendas personalizadas<\/strong>, tanto ropa casual como vestidos para eventos, dando a conocer este tipo de encargos.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Es importante definir bien la oferta de productos y comunicarla al mercado.&nbsp;<\/p><\/blockquote>\n\n\n\n<p>En las sesiones tambi\u00e9n revisamos los costes de los productos, porque es importante que la estrategia est\u00e9 alineada con el plan de viabilidad, conocer bien los m\u00e1rgenes y establecer los precios adecuados. Nos centramos en su producto estrella: la bomber personalizada. Evaluamos el proceso de comunicaci\u00f3n con la clientela que encarga este tipo de prendas y clarificamos las opciones de personalizaci\u00f3n en la web para <strong>optimizar tiempos y costes.&nbsp;<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/s7DZSnZ51ZIITiYkHYnMmpZEFeA1bMwqUm6IrS70fDvY_fnQ1R0bUh4UAqc4alLyqQlTIGM9nmh2XL9omOUT1_h6i9qHHxtNdt9WfVipW4aTDKdazqKQ7OqT3GuWobFEctdTfR227WXsPro69e6j4MheRmoIjIK4zWLtihMQy2ppkEPgPANL4CHXeBnc\" alt=\"\" width=\"641\" height=\"853\"\/><\/figure><\/div>\n\n\n\n<p>Dasein Hub es un espacio de reciente creaci\u00f3n que poco a poco despegar\u00e1 como referencia, es un lugar de fantas\u00eda para crear e inspirarse. Podr\u00e1s encontrar las prendas de Luc\u00eda que desprenden luz, alegr\u00eda, historias y ganas de comerse el mundo, adem\u00e1s de otros productos de dise\u00f1adores y creadores y una oferta innovadora de talleres creativos.&nbsp;<\/p>\n\n\n\n<p><strong>Dasein, \u201cser-en-el-mundo\u201d o el arte de vivir en el aqu\u00ed y ahora.<\/strong> Un espacio \u00fanico en la ciudad para potenciar encuentros creativos, diversos y multiculturales y crear una comunidad, apostando siempre por la moda sostenible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proceso de trabajo con Luc\u00eda Rodr\u00edguez ha sido muy enriquecedor. Nos centramos en su propuesta de valor y en la estrategia que pod\u00edamos crear en torno a ella. Pusimos foco en sacar todo el partido al potencial del espacio Dasein Hub, la trayectoria y experiencia de Luc\u00eda, y a las acciones que pod\u00edamos generar &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub\u00bb<\/span><\/a><\/p>\n","protected":false},"author":82,"featured_media":36485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1554],"tags":[28,2467,2543,2466,1884,1823,1910,2468,1614,2465,39],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Resultados de la asesor\u00eda de estrategia comercial realizada durante el Laboratorio de Innovaci\u00f3n Comercial al espacio de moda Dasein Hub.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Resultados de la asesor\u00eda de estrategia comercial realizada durante el Laboratorio de Innovaci\u00f3n Comercial al espacio de moda Dasein Hub.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T22:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T22:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/11\/IMG-20220318-WA0034.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miriam Almaz\u00e1n\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miriam Almaz\u00e1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\"},\"author\":{\"name\":\"Miriam Almaz\u00e1n\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2be127b852a0b08631b50fb4671faf1c\"},\"headline\":\"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub\",\"datePublished\":\"2022-11-10T22:35:00+00:00\",\"dateModified\":\"2022-11-21T22:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\"},\"wordCount\":428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"creatividad\",\"Dasein\",\"Dise\u00f1o\",\"estrategia empresarial\",\"Estrategia innovaci\u00f3n comercial\",\"laboratorio de innovaci\u00f3n comercial\",\"Laboratorio Innovaci\u00f3n Comercial\",\"Miriam Almaz\u00e1n\",\"MIZ-LAB\",\"mizlab7\",\"moda\"],\"articleSection\":[\"MIZ-Lab\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\",\"name\":\"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2022-11-10T22:35:00+00:00\",\"dateModified\":\"2022-11-21T22:37:09+00:00\",\"description\":\"Resultados de la asesor\u00eda de estrategia comercial realizada durante el Laboratorio de Innovaci\u00f3n Comercial al espacio de moda Dasein Hub.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2be127b852a0b08631b50fb4671faf1c\",\"name\":\"Miriam Almaz\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/c71735d28e0857558d07859b9bc0baef?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/c71735d28e0857558d07859b9bc0baef?s=96&d=mm&r=g\",\"caption\":\"Miriam Almaz\u00e1n\"},\"description\":\"Miriam Almaz\u00e1n es economista y consultora de negocio en Afiris, donde lidera proyectos con energ\u00eda y creatividad. Con m\u00e1s de 15 a\u00f1os de experiencia en asesor\u00eda y formaci\u00f3n, acompa\u00f1a a emprendedores y negocios locales en el Laboratorio de Innovaci\u00f3n Comercial de Made in Zaragoza (MIZ-Lab), ayud\u00e1ndoles a analizar y definir sus estrategias de negocio.\",\"sameAs\":[\"https:\/\/www.afiris.es\/\",\"https:\/\/www.linkedin.com\/in\/miriamelenaalmazan?originalSubdomain=es\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/miriamalmazan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub - Made in Zaragoza","description":"Resultados de la asesor\u00eda de estrategia comercial realizada durante el Laboratorio de Innovaci\u00f3n Comercial al espacio de moda Dasein Hub.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/","og_locale":"es_ES","og_type":"article","og_title":"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub - Made in Zaragoza","og_description":"Resultados de la asesor\u00eda de estrategia comercial realizada durante el Laboratorio de Innovaci\u00f3n Comercial al espacio de moda Dasein Hub.","og_url":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2022-11-10T22:35:00+00:00","article_modified_time":"2022-11-21T22:37:09+00:00","og_image":[{"width":2016,"height":1512,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/11\/IMG-20220318-WA0034.jpg","type":"image\/jpeg"}],"author":"Miriam Almaz\u00e1n","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Miriam Almaz\u00e1n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/"},"author":{"name":"Miriam Almaz\u00e1n","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2be127b852a0b08631b50fb4671faf1c"},"headline":"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub","datePublished":"2022-11-10T22:35:00+00:00","dateModified":"2022-11-21T22:37:09+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/"},"wordCount":428,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["creatividad","Dasein","Dise\u00f1o","estrategia empresarial","Estrategia innovaci\u00f3n comercial","laboratorio de innovaci\u00f3n comercial","Laboratorio Innovaci\u00f3n Comercial","Miriam Almaz\u00e1n","MIZ-LAB","mizlab7","moda"],"articleSection":["MIZ-Lab"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/","url":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/","name":"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2022-11-10T22:35:00+00:00","dateModified":"2022-11-21T22:37:09+00:00","description":"Resultados de la asesor\u00eda de estrategia comercial realizada durante el Laboratorio de Innovaci\u00f3n Comercial al espacio de moda Dasein Hub.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/miz-lab-7-resultados-de-la-asesoria-de-estrategia-con-dasein-hub\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"MIZ-Lab 7: Resultados de la asesor\u00eda de estrategia con Dasein Hub"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2be127b852a0b08631b50fb4671faf1c","name":"Miriam Almaz\u00e1n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/c71735d28e0857558d07859b9bc0baef?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/c71735d28e0857558d07859b9bc0baef?s=96&d=mm&r=g","caption":"Miriam Almaz\u00e1n"},"description":"Miriam Almaz\u00e1n es economista y consultora de negocio en Afiris, donde lidera proyectos con energ\u00eda y creatividad. Con m\u00e1s de 15 a\u00f1os de experiencia en asesor\u00eda y formaci\u00f3n, acompa\u00f1a a emprendedores y negocios locales en el Laboratorio de Innovaci\u00f3n Comercial de Made in Zaragoza (MIZ-Lab), ayud\u00e1ndoles a analizar y definir sus estrategias de negocio.","sameAs":["https:\/\/www.afiris.es\/","https:\/\/www.linkedin.com\/in\/miriamelenaalmazan?originalSubdomain=es"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/miriamalmazan\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/36484"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=36484"}],"version-history":[{"count":6,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/36484\/revisions"}],"predecessor-version":[{"id":36693,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/36484\/revisions\/36693"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/36485"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=36484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=36484"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=36484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}