{"id":28969,"date":"2020-07-21T18:49:00","date_gmt":"2020-07-21T17:49:00","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=28969"},"modified":"2020-07-24T11:08:33","modified_gmt":"2020-07-24T10:08:33","slug":"dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/","title":{"rendered":"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior"},"content":{"rendered":"\n<p>La pandemia de la COVID-19 nos ha hecho conectar con nuestra casa y buscar nuevas formas de disfrutarla en esta <em>nueva normalida<\/em>d. Para disfrutar de ella, todos estamos buscando la forma de hacer nuestras casas m\u00e1s habitables, y sin duda, llenar la casa de plantas (tanto en el interior como en balcones y terrazas) es una de las formas m\u00e1s r\u00e1pidas para conectar con la naturaleza y conseguir hogares m\u00e1s confortables. <\/p>\n\n\n\n<p>Para ayudarte en esta tarea, hemos preparado una selecci\u00f3n de plantas que podr\u00e1s tener en casa para dar vida a <a href=\"http:\/\/madeinzaragoza.es\/blog\/5-ideas-para-poner-bonita-tu-terraza-o-balcon-este-verano\/\" class=\"yoast-seo-link\">balcones y terrazas<\/a>, y tambi\u00e9n para los interiores. Y seguro que en florister\u00edas de la red MIZ como,<a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=269\" class=\"yoast-seo-link\"> G\u00e1lvez Floristas<\/a> (Las Fuentes), <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=377\" class=\"yoast-seo-link\">Flores Ohana<\/a> (Centro),  <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=346\" class=\"yoast-seo-link\">El Ed\u00e9n<\/a> (Valdespartera), o <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=199\" class=\"yoast-seo-link\">Flores Le<\/a> y <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=305\" class=\"yoast-seo-link\">Flores Elena<\/a> (Delicias) os ayudar\u00e1n a transformar vuestra casa para darle un toque verde.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plantas para la terraza o el balc\u00f3n<\/h2>\n\n\n\n<p>Para elegir tus plantas para exterior es fundamental ver las horas de insolaci\u00f3n, si es orientaci\u00f3n norte o sur, el color que quieres que domine, si prefieres plantas verdes o con flor&#8230; En tu florister\u00eda de confianza seguro que estar\u00e1n encantados de asesorarte.<\/p>\n\n\n\n<ul><li><strong>Geranios. <\/strong>Son un cl\u00e1sico en ventanas, terrazas y balcones. Y no nos pueden gustar m\u00e1s. En tonos rosados, rojos&#8230; los geranios son una planta muy resistente que aguantan perfectamente el sol zaragozano y que con unos cuidados tambi\u00e9n pueden superar el fr\u00edo y durar hasta el a\u00f1o siguiente. <\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/flowers-5277837_960_720.jpg\" alt=\"\" class=\"wp-image-28975\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/flowers-5277837_960_720.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/flowers-5277837_960_720-300x200.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/flowers-5277837_960_720-768x512.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure><\/div>\n\n\n\n<ul><li><strong>Petunias.<\/strong> Esta planta con flor en forma de trompeta tambi\u00e9n es una especie todoterreno que aguanta muy bien tanto el calor como el fr\u00edo. Rosas, blancas, moradas, rojas&#8230; hay petunias de un mont\u00f3n de colores.<\/li><li><strong>Hiedra<\/strong>. El juego que da la hiedra para recubrir una pared, dejar que cuelgue desde la ventana&#8230; Esta especie trepadora crece pr\u00e1cticamente sola, y tambi\u00e9n resiste perfectamente al invierno, lo que nos permite tener verde durante todo el a\u00f1o.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/ivy-4230809_960_720.jpg\" alt=\"\" class=\"wp-image-28976\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/ivy-4230809_960_720.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/ivy-4230809_960_720-300x200.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/ivy-4230809_960_720-768x512.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<ul><li><strong>Plantas arom\u00e1ticas<\/strong>. Si adem\u00e1s de verde, te apetece tener el balc\u00f3n con aromas y que tambi\u00e9n te sirvan como ingrediente para cocinar, las plantas arom\u00e1ticas como el tomillo o el romero son una estupenda opci\u00f3n. Puedes tenerlas en  macetas, o incluso preparar con ellas un peque\u00f1o jard\u00edn vertical en una de las paredes de tu terraza o balc\u00f3n para.<\/li><li><strong>Claveles<\/strong>. Esta flor es un cl\u00e1sico que adem\u00e1s est\u00e1 en este momento s\u00faper de moda gracias a sus variedades crom\u00e1ticas, m\u00e1s all\u00e1 de los tradicionales rojos, blancos, rosas o amarillos. <\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"685\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/striped-carnation-3822767_960_720.jpg\" alt=\"\" class=\"wp-image-28977\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/striped-carnation-3822767_960_720.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/striped-carnation-3822767_960_720-300x214.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/striped-carnation-3822767_960_720-768x548.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<ul><li><strong>Margaritas<\/strong>. \u00bfHay algo m\u00e1s sencillo y bonito que una margarita? Resisten el sol sin problema, y sus flores blancas dar\u00e1n luminosidad a tu terraza. <\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Flores para interior<\/h2>\n\n\n\n<p>Tras el confinamiento, las casas se han llenado de plantas. Hemos descubierto que necesitamos estar en contacto con la naturaleza y que adem\u00e1s,nos ayudan a relajarnos y dulcifican y hacen confortable cualquier espacio. Pero al margen del tema est\u00e9tico, las plantas de interior ayudan a reducir los niveles de di\u00f3xido de carbono, incrementan la humedad del aire.   <\/p>\n\n\n\n<ul><li><strong>Cinta<\/strong>. Una planta colgante que es de las que llevan fama de duraderas. Adem\u00e1s, si tienes una maceta, podr\u00e1s reproducirlas gracias a los hijuelos que salen de algunos de sus tallos.<\/li><li><strong>Anthurium<\/strong>. Esta es una planta de interior s\u00faper resistente, y su flor es muy caracter\u00edstica, ya que es como una espiga rodeada de una hoja de color intenso en forma de coraz\u00f3n. Pero adem\u00e1s del rojo, tambi\u00e9n puedes encontrarlos en otros colores como el p\u00farpura, o el blanco.  <\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/anthurium-flamingo-flower-2507743_960_720.jpg\" alt=\"\" class=\"wp-image-28973\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/anthurium-flamingo-flower-2507743_960_720.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/anthurium-flamingo-flower-2507743_960_720-300x200.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/anthurium-flamingo-flower-2507743_960_720-768x512.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<ul><li><strong>Tronco de Brasil.<\/strong> Esta especie queda siempre espectacular aprovechando cualquier rinc\u00f3n. Sus grandes hojas presentan distintas tonalidades de verdes.<\/li><li><strong>Crasas<\/strong>. Una planta muy instagrameable por su efecto decorativo. M\u00e1s conocidas como suculentas, esta planta tampoco requiere demasiados cuidados. Aunque contra m\u00e1s las riegues, m\u00e1s carnosas ser\u00e1n sus hojas.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/succulent-plants-2045388_960_720.jpg\" alt=\"\" class=\"wp-image-28972\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/succulent-plants-2045388_960_720.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/succulent-plants-2045388_960_720-300x225.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/succulent-plants-2045388_960_720-768x576.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<ul><li><strong>Palmera de Sal\u00f3n.<\/strong> Su nombre cient\u00edfico es Chamadeora Elegans, y es una planta muy elegante que nos permite darle un aire tropical al sal\u00f3n. Es una planta resistente que no requiere de demasiados cuidados. <\/li><li><strong>C\u00e1ctus.<\/strong> Est\u00e1n cada vez m\u00e1s de moda (no hay m\u00e1s que echar un vistazo a redes sociales como Instagram), y adem\u00e1s, son resistentes y de f\u00e1cil mantenimiento. Adem\u00e1s de la luz solar, tan solo necesitan evitar las corrientes de aire y regarlas de forma moderada dependiendo de la \u00e9poca del a\u00f1o.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/abstract-1869217_960_720.jpg\" alt=\"\" class=\"wp-image-28974\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/abstract-1869217_960_720.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/abstract-1869217_960_720-300x200.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/abstract-1869217_960_720-768x512.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<ul><li><strong>Sansevieria.<\/strong> Como la cinta, esta especie es perfecta para los que quieren iniciarse en el arte de tener plantas en casa. Adem\u00e1s, diversos estudios se\u00f1alan que es una de las plantas m\u00e1s efectivas para eliminar t\u00f3xicos del aire. <\/li><li><strong>Poto<\/strong>. Otra especie muy agradecida es el poto, una planta colgante ideal para colocar en una cesta colgante o sobre un mueble. Esta especie tambi\u00e9n ayuda a purificar el aire.  <\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Macetas<\/h2>\n\n\n\n<p>Y ya que estamos, si vamos a llenar la casa de plantas acudiendo a las florister\u00edas de la red MIZ, vamos a buscar tambi\u00e9n macetas diferentes. Como las que podemos encontrar en el estudio de cer\u00e1mica <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=84\" class=\"yoast-seo-link\">SEHAHECHOTRIZAS<\/a>.  Tambi\u00e9n puedes encontrar macetas molonas en <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=117\">Shuave Shop<\/a>, en <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=71\">Lilou Sucursal de felicidad <\/a>o en <a href=\"http:\/\/madeinzaragoza.es\/comercios\/comercio.php?id=129\">Horst<\/a>, tal y como pod\u00e9is ver en estas fotos que os dejamos por aqu\u00ed.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/31961174_1702260439881928_7529910279363100672_n.jpg\" alt=\"\" class=\"wp-image-28979\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/31961174_1702260439881928_7529910279363100672_n.jpg 720w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/31961174_1702260439881928_7529910279363100672_n-225x300.jpg 225w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption>SEHAHECHOTRIZAS<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/101679990_3189168291149644_4170539151382282240_o-1024x1024.jpg\" alt=\"\" class=\"wp-image-28981\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/101679990_3189168291149644_4170539151382282240_o-1024x1024.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/101679990_3189168291149644_4170539151382282240_o-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/101679990_3189168291149644_4170539151382282240_o-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/101679990_3189168291149644_4170539151382282240_o-768x768.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/101679990_3189168291149644_4170539151382282240_o-1200x1200.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/101679990_3189168291149644_4170539151382282240_o.jpg 1440w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption>Shuave Shop<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"658\" height=\"540\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/lilou.png\" alt=\"\" class=\"wp-image-28982\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/lilou.png 658w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/lilou-300x246.png 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption>Lilou Sucursal de felicidad<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"408\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/horst.png\" alt=\"\" class=\"wp-image-28983\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/horst.png 618w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/horst-300x198.png 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><figcaption>Horst<\/figcaption><\/figure>\n\n\n\n<p>\u00bfTe animas a llenar tu casa con flores y plantas para darle un toque mucho m\u00e1s natural a tu hogar? \u00a1Esperamos que s\u00ed! Porque adem\u00e1s, si llenamos terrazas, balcones y ventanas de flores, la ciudad estar\u00e1 mucho m\u00e1s bonita. Y ah\u00ed, ganamos todos en calidad de vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pandemia de la COVID-19 nos ha hecho conectar con nuestra casa y buscar nuevas formas de disfrutarla en esta nueva normalidad. Para disfrutar de ella, todos estamos buscando la forma de hacer nuestras casas m\u00e1s habitables, y sin duda, llenar la casa de plantas (tanto en el interior como en balcones y terrazas) es &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior\u00bb<\/span><\/a><\/p>\n","protected":false},"author":11,"featured_media":28970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[821,1508],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Decora tu casa este verano con preciosas plantas y macetas de interior y exterior. Te recomendamos floristerias y espacios de decoraci\u00f3n en Zaragoza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Decora tu casa este verano con preciosas plantas y macetas de interior y exterior. Te recomendamos floristerias y espacios de decoraci\u00f3n en Zaragoza.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"nachovinauena\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-21T17:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-24T10:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/photo-1502672260266-1c1ef2d93688.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"818\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nacho Vinau\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@nachoena\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Vinau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\"},\"author\":{\"name\":\"Nacho Vinau\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/c75168076287255954a1350e1bc702aa\"},\"headline\":\"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior\",\"datePublished\":\"2020-07-21T17:49:00+00:00\",\"dateModified\":\"2020-07-24T10:08:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\"},\"wordCount\":987,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"Decoraci\u00f3n del hogar\",\"Florister\u00edas\"],\"articleSection\":[\"Tendencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\",\"name\":\"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2020-07-21T17:49:00+00:00\",\"dateModified\":\"2020-07-24T10:08:33+00:00\",\"description\":\"Decora tu casa este verano con preciosas plantas y macetas de interior y exterior. Te recomendamos floristerias y espacios de decoraci\u00f3n en Zaragoza.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/c75168076287255954a1350e1bc702aa\",\"name\":\"Nacho Vinau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/0929336b01b6c352d95fd32182921ca3?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/0929336b01b6c352d95fd32182921ca3?s=96&d=mm&r=g\",\"caption\":\"Nacho Vinau\"},\"description\":\"Blogger, organizador de bodas y eventos personalizados en La Lola se va de Boda. Generador de contenidos en COM&amp;COM, amante de mi ciudad, del arte, la moda, y de los peque\u00f1os placeres que nos da la vida.\",\"sameAs\":[\"http:\/\/nachovinauena.wordpress.com\",\"nachovinauena\",\"https:\/\/twitter.com\/nachoena\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/nacho-vinau\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior - Made in Zaragoza","description":"Decora tu casa este verano con preciosas plantas y macetas de interior y exterior. Te recomendamos floristerias y espacios de decoraci\u00f3n en Zaragoza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/","og_locale":"es_ES","og_type":"article","og_title":"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior - Made in Zaragoza","og_description":"Decora tu casa este verano con preciosas plantas y macetas de interior y exterior. Te recomendamos floristerias y espacios de decoraci\u00f3n en Zaragoza.","og_url":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"nachovinauena","article_published_time":"2020-07-21T17:49:00+00:00","article_modified_time":"2020-07-24T10:08:33+00:00","og_image":[{"width":1100,"height":818,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/07\/photo-1502672260266-1c1ef2d93688.jpg","type":"image\/jpeg"}],"author":"Nacho Vinau","twitter_card":"summary","twitter_creator":"@nachoena","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Nacho Vinau","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/"},"author":{"name":"Nacho Vinau","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/c75168076287255954a1350e1bc702aa"},"headline":"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior","datePublished":"2020-07-21T17:49:00+00:00","dateModified":"2020-07-24T10:08:33+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/"},"wordCount":987,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["Decoraci\u00f3n del hogar","Florister\u00edas"],"articleSection":["Tendencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/","url":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/","name":"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2020-07-21T17:49:00+00:00","dateModified":"2020-07-24T10:08:33+00:00","description":"Decora tu casa este verano con preciosas plantas y macetas de interior y exterior. Te recomendamos floristerias y espacios de decoraci\u00f3n en Zaragoza.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/dale-un-toque-verde-a-tu-casa-este-verano-seleccion-de-plantas-y-macetas-para-interior-y-exterior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Dale un toque verde a tu casa este verano: selecci\u00f3n de plantas (y macetas) para interior y exterior"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/c75168076287255954a1350e1bc702aa","name":"Nacho Vinau","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/0929336b01b6c352d95fd32182921ca3?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/0929336b01b6c352d95fd32182921ca3?s=96&d=mm&r=g","caption":"Nacho Vinau"},"description":"Blogger, organizador de bodas y eventos personalizados en La Lola se va de Boda. Generador de contenidos en COM&amp;COM, amante de mi ciudad, del arte, la moda, y de los peque\u00f1os placeres que nos da la vida.","sameAs":["http:\/\/nachovinauena.wordpress.com","nachovinauena","https:\/\/twitter.com\/nachoena"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/nacho-vinau\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28969"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=28969"}],"version-history":[{"count":8,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28969\/revisions"}],"predecessor-version":[{"id":29040,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28969\/revisions\/29040"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/28970"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=28969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=28969"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=28969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}