{"id":28354,"date":"2020-04-28T13:02:00","date_gmt":"2020-04-28T12:02:00","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=28354"},"modified":"2022-10-09T14:51:53","modified_gmt":"2022-10-09T13:51:53","slug":"ideas-de-regalos-dia-de-la-madre-en-cuarentena","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/","title":{"rendered":"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia"},"content":{"rendered":"<p>Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed.<\/p>\n<p>A la hora de elegir un regalo \u00fanico y especial, te proponemos que eches un vistazo a las sugerencias de los comercios de la red de emprendedores creativos Made in Zaragoza.<\/p>\n<p>Adem\u00e1s, no es necesario que nos desplacemos hasta nuestro comercio Made in Zaragoza favorito, <strong>podemos hacer el pedido a trav\u00e9s de su web o redes sociales<\/strong> y ellos se ocupan de llevarlo a casa de tu madre. As\u00ed, adem\u00e1s <strong>ayudas al comercio local<\/strong>.<\/p>\n<h2>Una tote bag sostenible de Una Oca Loca<\/h2>\n<p>Dentro de su filosof\u00eda de recuperaci\u00f3n textil <a href=\"https:\/\/www.facebook.com\/UnaOcaLOca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Unaocaloca<\/a> nos propone una <em><strong>tote bag realizada con sacos de caf\u00e9 reutilizados<\/strong><\/em>. Un detalle pr\u00e1ctico, \u00fatil y sostenible.\u00a0 \u00abEstamos en un momento de cambio e incertidumbre, no se le escapa a nadie, pero lo que tenemos que tomar conciencia es que nosotros podemos formar parte del cambio, con nuestras acciones y nuestra apuesta de valor, juntos sumamos para mejorar todas esas acciones, que antes no nos gustaban, y unir fuerzas para mejorar y poner en valor lo local, cercano y sostenible\u00bb. &#x1f49a;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28390\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/94748108_1482865231892821_1246142674549866496_o.jpg\" alt=\"tote bad sostenible unaocaloca\" width=\"960\" height=\"960\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/94748108_1482865231892821_1246142674549866496_o.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/94748108_1482865231892821_1246142674549866496_o-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/94748108_1482865231892821_1246142674549866496_o-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/94748108_1482865231892821_1246142674549866496_o-768x768.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<h2>Un diario de embarazo de My retro box<\/h2>\n<p>Las mam\u00e1s que todav\u00eda est\u00e1n embarazadas tambi\u00e9n pueden tener un detalle por el d\u00eda de la madre, y por eso desde <a href=\"https:\/\/www.myretrobox.com\/capsula-del-tiempo-regalo-original-bebe\/\" target=\"_blank\" rel=\"noopener noreferrer\">MyRetrobox<\/a> proponen su <em><strong>diario de embarazo \u00abBeb\u00e9 a bordo\u00bb<\/strong><\/em>, un \u00e1lbum ilustrado en el que guardar todos los recuerdos de esa etapa tan especial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28391\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Capsula-del-tiempo-bebe-baby-retrobox.jpg\" alt=\"Capsula del Tiempo Retrobox\" width=\"900\" height=\"900\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Capsula-del-tiempo-bebe-baby-retrobox.jpg 900w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Capsula-del-tiempo-bebe-baby-retrobox-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Capsula-del-tiempo-bebe-baby-retrobox-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Capsula-del-tiempo-bebe-baby-retrobox-768x768.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<h2>Un grabado exclusivo de Fabiola Gil Estudio<\/h2>\n<p>Si tu madre es una amante del arte, entonces le encantar\u00e1 un detalle como el grabado de\u00a0<a href=\"https:\/\/www.fabiolagil.com\/\">Fabiola Gil Studio<\/a>. Fabiola es una artista afincada en Zaragoza, especialista en xilograf\u00eda japonesa &#8211; mokuhanga.<\/p>\n<div align=\"center\">\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/B_kqLAqJBlz\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"12\">\n<div style=\"padding: 16px;\">\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/B_kqLAqJBlz\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener noreferrer\">Una publicaci\u00f3n compartida por Fabiola Gil Mokuhanga Studio (@fabiola_gil_estudio)<\/a> el <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2020-04-29T17:16:56+00:00\">29 de Abr de 2020 a las 10:16 PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<\/div>\n<h2>Una cuidada selecci\u00f3n de flores<\/h2>\n<p>\u00bfY qu\u00e9 ser\u00eda un d\u00eda de la madre sin flores? Para el d\u00eda de la Madre, <a href=\"https:\/\/www.floreselena.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Flores Elena<\/a> propone una bonita selecci\u00f3n de ramos. Adem\u00e1s,\u00a0ofrece reparto gratuito en Zaragoza capital. Haz tu pedido a trav\u00e9s de su web y ellos se ocupan de llev\u00e1rtelo a casa &#x1f490;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28396\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Embrujo-1021x1024.jpg\" alt=\"\" width=\"840\" height=\"842\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Embrujo-1021x1024.jpg 1021w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Embrujo-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Embrujo-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Embrujo-768x770.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Embrujo.jpg 1097w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>Adem\u00e1s, si quieres un dise\u00f1o floral espec\u00edfico tambi\u00e9n puedes hacer tus encargos a G\u00e0lvez Floristas.<\/p>\n<h2><\/h2>\n<h2>Dulces Catalina<\/h2>\n<p><a href=\"https:\/\/www.dulcescatalina.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dulces Catalina<\/a> nos ofrece chucher\u00edas, o laminer\u00edas, de toda la vida. Esas que probablemente te encantaban cuando eras peque y que no hab\u00edas vuelto a ver. Desde caramelos supervariados a cigarrillos o sardinas de chocolate.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31605 size-full\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2021\/04\/DSC_0020-768x510-1.jpg\" alt=\"\" width=\"768\" height=\"510\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2021\/04\/DSC_0020-768x510-1.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2021\/04\/DSC_0020-768x510-1-300x199.jpg 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>En Dulces Catalina tambi\u00e9n tienen una amplia (y deliciosa) variedad de dulces artesanos made in Arag\u00f3n, con art\u00edculos como las Frutas de Arag\u00f3n, guirlaches, turrones, guindas al marrasquino, o adoquines, entre otros productos.<\/p>\n<h2>Tratamientos y cuidados con Leila Hammam<\/h2>\n<p>Despu\u00e9s de tantos d\u00edas en casa, seguro que tu madre acoge con muchas ganas la propuesta de <a href=\"http:\/\/leilahammam.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Leila Hammam<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28398\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/92952917_2599974360288351_6201242565589598208_o.jpg\" alt=\"\" width=\"960\" height=\"960\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/92952917_2599974360288351_6201242565589598208_o.jpg 960w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/92952917_2599974360288351_6201242565589598208_o-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/92952917_2599974360288351_6201242565589598208_o-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/92952917_2599974360288351_6201242565589598208_o-768x768.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<h2>Un accesorio lleno de color de By Frida<\/h2>\n<p>Pod\u00e9is recurrir a regalos cl\u00e1sicos y \u00fatiles, como unos pendientes o una cartera&#8230; Si tiene el sello <a href=\"https:\/\/byfrida.es\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em><strong>\u00abBy Frida\u00bb<\/strong><\/em><\/a>, el accesorio que elijas destacar\u00e1 por su color.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28399\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/IMG_20200221_123051_resized_20200301_103013798-1024x1024.jpg\" alt=\"\" width=\"840\" height=\"840\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/IMG_20200221_123051_resized_20200301_103013798-1024x1024.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/IMG_20200221_123051_resized_20200301_103013798-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/IMG_20200221_123051_resized_20200301_103013798-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/IMG_20200221_123051_resized_20200301_103013798-768x768.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/IMG_20200221_123051_resized_20200301_103013798-1200x1200.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/IMG_20200221_123051_resized_20200301_103013798.jpg 1488w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>\u00bfTe gustan las propuestas del peque\u00f1o comercio Made in Zaragoza? Haz que tu madre se sienta m\u00e1s especial que nunca este domingo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed. A la hora de elegir un regalo \u00fanico y especial, te proponemos que eches un vistazo a las sugerencias de los comercios de la red de emprendedores creativos Made in Zaragoza. Adem\u00e1s, no es necesario &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abIdeas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":28400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed. Estas son nuestras ideas de regalo Made in Zaragoza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed. Estas son nuestras ideas de regalo Made in Zaragoza.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"misstechin\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-28T12:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-09T13:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/regalos-dias-de-la-madre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Gim\u00e9nez\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@misstechin\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Gim\u00e9nez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\"},\"author\":{\"name\":\"Monica Gim\u00e9nez\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/7f474fda5b3cfb05e3d9963093971cca\"},\"headline\":\"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia\",\"datePublished\":\"2020-04-28T12:02:00+00:00\",\"dateModified\":\"2022-10-09T13:51:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\"},\"wordCount\":588,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"articleSection\":[\"Tendencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\",\"name\":\"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2020-04-28T12:02:00+00:00\",\"dateModified\":\"2022-10-09T13:51:53+00:00\",\"description\":\"Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed. Estas son nuestras ideas de regalo Made in Zaragoza.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/7f474fda5b3cfb05e3d9963093971cca\",\"name\":\"Monica Gim\u00e9nez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/bdd60894f529a2929832a56d3c3eb2f2?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/bdd60894f529a2929832a56d3c3eb2f2?s=96&d=mm&r=g\",\"caption\":\"Monica Gim\u00e9nez\"},\"description\":\"Coordinadora del blog de Made in Zaragoza. Trabajo en comunicaci\u00f3n y marketing digital, posicionamiento de marca y proyectos digitales. Fan del teatro, los c\u00f3mics, el sushi y de historias que hacen \u00fanica a Zaragoza.\",\"sameAs\":[\"https:\/\/misstechin.com\",\"misstechin\",\"https:\/\/twitter.com\/misstechin\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/moni\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia - Made in Zaragoza","description":"Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed. Estas son nuestras ideas de regalo Made in Zaragoza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/","og_locale":"es_ES","og_type":"article","og_title":"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia - Made in Zaragoza","og_description":"Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed. Estas son nuestras ideas de regalo Made in Zaragoza.","og_url":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"misstechin","article_published_time":"2020-04-28T12:02:00+00:00","article_modified_time":"2022-10-09T13:51:53+00:00","og_image":[{"width":1200,"height":706,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/regalos-dias-de-la-madre.jpg","type":"image\/jpeg"}],"author":"Monica Gim\u00e9nez","twitter_card":"summary","twitter_creator":"@misstechin","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Monica Gim\u00e9nez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/"},"author":{"name":"Monica Gim\u00e9nez","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/7f474fda5b3cfb05e3d9963093971cca"},"headline":"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia","datePublished":"2020-04-28T12:02:00+00:00","dateModified":"2022-10-09T13:51:53+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/"},"wordCount":588,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"articleSection":["Tendencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/","url":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/","name":"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2020-04-28T12:02:00+00:00","dateModified":"2022-10-09T13:51:53+00:00","description":"Se acerca el d\u00eda de la madre, un d\u00eda especial para agradecer a todas las madres que siempre est\u00e9n ah\u00ed. Estas son nuestras ideas de regalo Made in Zaragoza.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/ideas-de-regalos-dia-de-la-madre-en-cuarentena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Ideas de regalos Made in Zaragoza para un D\u00eda de la Madre en pandemia"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/7f474fda5b3cfb05e3d9963093971cca","name":"Monica Gim\u00e9nez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/bdd60894f529a2929832a56d3c3eb2f2?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/bdd60894f529a2929832a56d3c3eb2f2?s=96&d=mm&r=g","caption":"Monica Gim\u00e9nez"},"description":"Coordinadora del blog de Made in Zaragoza. Trabajo en comunicaci\u00f3n y marketing digital, posicionamiento de marca y proyectos digitales. Fan del teatro, los c\u00f3mics, el sushi y de historias que hacen \u00fanica a Zaragoza.","sameAs":["https:\/\/misstechin.com","misstechin","https:\/\/twitter.com\/misstechin"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/moni\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28354"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=28354"}],"version-history":[{"count":12,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28354\/revisions"}],"predecessor-version":[{"id":36035,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28354\/revisions\/36035"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/28400"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=28354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=28354"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=28354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}