{"id":28274,"date":"2020-05-14T08:28:32","date_gmt":"2020-05-14T07:28:32","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=28274"},"modified":"2020-05-14T08:30:16","modified_gmt":"2020-05-14T07:30:16","slug":"en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/","title":{"rendered":"En casa&#8230; \u00a1que siga el juego!"},"content":{"rendered":"\n<p>\u00ab\u00a1Te como y me cuento veinte!\u00bb \u00bfQui\u00e9n no ha o\u00eddo esta frase alguna vez? Una de las frases m\u00e1s temidas cuando juegas al parch\u00eds.<\/p>\n\n\n\n<p><br>En esta cuarentena no nos ha quedado m\u00e1s remedio que recluirnos en nuestras casas, pasar el tiempo lo mejor que podamos, si tenemos la suerte de estar sanos, ejercitarnos en la paciencia y\u2026 \u00bfpor qu\u00e9 no? <strong>volver a jugar.<\/strong><\/p>\n\n\n\n<p><br>Tanto si este periodo lo pasas con ni\u00f1os como si no, jugar ayuda a pasar el rato, te mantiene activo, y con un poco de suerte aprendes algo nuevo. Aprender es un estimulante natural que nos ayuda a mantenernos alerta y con talante positivo y juguet\u00f3n. Algo muy necesario en estos momentos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Juegos on line<\/h2>\n\n\n\n<p><br><br>La oferta de juegos online es ilimitada, de esto saben bien en <a href=\"https:\/\/cincoreinos.com\/\">Cinco Reinos<\/a><br>Son especialistas en wargames, juegos de rol, juegos de mesa y cartas y c\u00f3mics. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/wayne-low-OvN4OkhkTLo-unsplash-magic-1024x683.jpg\" alt=\"Juegos en cuarentena\" class=\"wp-image-28280\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/wayne-low-OvN4OkhkTLo-unsplash-magic-1024x683.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/wayne-low-OvN4OkhkTLo-unsplash-magic-300x200.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/wayne-low-OvN4OkhkTLo-unsplash-magic-768x512.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/wayne-low-OvN4OkhkTLo-unsplash-magic-1536x1024.jpg 1536w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/wayne-low-OvN4OkhkTLo-unsplash-magic-2048x1365.jpg 2048w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/wayne-low-OvN4OkhkTLo-unsplash-magic-1200x800.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<p>Javier Bacarizo nos cuenta por tel\u00e9fono que su idea es proseguir, en lo posible, con algunos torneos y eventos programados para estas semanas y hacerlo de forma on line. En concreto todo lo relativo al fascinante mundo de <strong>Magic<\/strong>, as\u00ed que si est\u00e1is interesados poneros en contacto a trav\u00e9s de su web para conocer m\u00e1s detalles de las <strong>novedades que nos trae mayo<\/strong>.<\/p>\n\n\n\n<p><br>Si la edad de los ni\u00f1os no permite a\u00fan este tipo de juegos y quieres que puedan moverse lo suficiente para calmarlos sin tener que molestar a tu vecino de abajo, Tom\u00e1s Cabeza de <a href=\"http:\/\/www.juegostradicionales.es\">Juegos Tradicionales<\/a>  nos da ideas y en su blog encontrar\u00e9is muchas m\u00e1s.<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Juegos caseros al alcance de todos<\/h2>\n\n\n\n<p><br><\/p>\n\n\n\n<p>Muchos juegos os sonar\u00e1n porque son cl\u00e1sicos que nunca fallan. Por eso precisamente no deber\u00edamos olvidarlos.<\/p>\n\n\n\n<p><br>Tom\u00e1s nos recomienda, que se puedan hacer en casa, entre otros:<\/p>\n\n\n\n<p><br>&#8211; Juego de <strong>bolos con botellines:<\/strong> con botellines ya usados, los llenamos de agua para que pesen y los disponemos a modo de bolos. Marcamos una distancia prudencial y con una pelota peque\u00f1a, de tenis o similar a tirar y \u00a1lograr un pleno! <br>&#8211; Con vasos de pl\u00e1stico, un trozo de lana o cordel y una pelotita peque\u00f1a hacemos un <strong>juego de boliche <\/strong>tradicional. Si no tenemos bola peque\u00f1a con papel de aluminio podemos hacer una.<br>&#8211; <strong>Tres en raya<\/strong>: con chapas de botell\u00edn y dibujando en un folio el famoso cuadrado del 3 en raya. M\u00e1s sencillo imposible.<br><br>Las posibilidades son infinitas. A veces con los que m\u00e1s disfrutan los ni\u00f1os es con la preparaci\u00f3n del juego en s\u00ed. Luego hace falta tener un poco de suerte o habilidad\u2026 <br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Boliche-JT-1024x1024.jpg\" alt=\"Juegos en cuarentena\" class=\"wp-image-28279\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Boliche-JT-1024x1024.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Boliche-JT-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Boliche-JT-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Boliche-JT-768x768.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/Boliche-JT.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Juegos de mesa de toda la vida<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Esta enumeraci\u00f3n de juegos no estar\u00eda completa si no comenz\u00e1ramos por esos juegos que no se olvidan, pero que podemos cambiar un poco para ir variando la f\u00f3rmula original:<\/p>\n\n\n\n<p><br>&#8211; <strong>Parch\u00eds<\/strong>, organizar peque\u00f1os torneos de parch\u00eds o cambiar las reglas para que las partidas sean m\u00e1s cortas y emocionantes, solo con dos fichas por ejemplo. Sugerencias para jugadores no estrictos.<\/p>\n\n\n\n<p><br>&#8211; <strong>Oca<\/strong>, qu\u00e9 gusto da que te toque la oca, y decir \u00abde oca en oca y tiro porque\u2026\u00bb Hay cosas que no cambian\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"774\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/tim-foster-y6uilkrSyMs-unsplash-1024x774.jpg\" alt=\"Juegos en cuarentena\" class=\"wp-image-28281\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/tim-foster-y6uilkrSyMs-unsplash-1024x774.jpg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/tim-foster-y6uilkrSyMs-unsplash-300x227.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/tim-foster-y6uilkrSyMs-unsplash-768x580.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/tim-foster-y6uilkrSyMs-unsplash-1536x1161.jpg 1536w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/tim-foster-y6uilkrSyMs-unsplash-2048x1548.jpg 2048w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/tim-foster-y6uilkrSyMs-unsplash-1200x907.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<p><br>&#8211; Cartas, <strong>ajedrez, domin\u00f3..<\/strong>. Es hora tambi\u00e9n de volver a los cl\u00e1sicos juegos de cartas, cuando acabe esta cuarentena seguro que han surgido nuevos forofos del <strong>mus y el gui\u00f1ote <\/strong>que tiran \u00f3rdagos y cantan las cuarenta a la m\u00ednima ocasi\u00f3n. <\/p>\n\n\n\n<p><br>&#8211; <strong>Jugar a las pel\u00edculas<\/strong>, para facilitar y hacer m\u00e1s r\u00e1pido el adivinar lo ideal es pensar entre todos primero las pel\u00edculas, anotarlas en papelitos y al azar ir abriendo seg\u00fan te toque. Es muy divertido comprobar las dotes de mimo de cada uno y ver como vamos de imaginaci\u00f3n para conectar los t\u00edtulos de las pel\u00edculas. Se pueden tambi\u00e9n adivinar series.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8211; Juegos de mesa que ya se han vuelto cl\u00e1sicos, como el <strong>Monopoly, el Trivial, el Risk o el Tab\u00fa<\/strong> a los que se han unido juegos tan especiales como el <strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Dixit_(juego_de_mesa)\">Dixit,<\/a><\/strong> que ya ha recibido numerosos premios y se ha editado varias extensiones de sus enigm\u00e1ticas cartas.<\/p>\n\n\n\n<p><br><br>Como veis, el que no juega en esta cuarentena es porque no quiere, \u00a1elige tu juego!<\/p>\n\n\n\n<p><br>Y recuerda, cuando esto acabe, <strong>estar\u00e1n <a href=\"http:\/\/madeinzaragoza.es\/comercios\/buscador.php\">tus tiendas<\/a> de juegos esper\u00e1ndote<\/strong>.<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fotos <a href=\"https:\/\/unsplash.com\/s\/photos\/games?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Unsplash<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a1Te como y me cuento veinte!\u00bb \u00bfQui\u00e9n no ha o\u00eddo esta frase alguna vez? Una de las frases m\u00e1s temidas cuando juegas al parch\u00eds. En esta cuarentena no nos ha quedado m\u00e1s remedio que recluirnos en nuestras casas, pasar el tiempo lo mejor que podamos, si tenemos la suerte de estar sanos, ejercitarnos en la &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEn casa&#8230; \u00a1que siga el juego!\u00bb<\/span><\/a><\/p>\n","protected":false},"author":66,"featured_media":28283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[829,7,8],"tags":[1583,231],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En casa... \u00a1que siga el juego! - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"En la cuarentena o fase 1, sin excusas para jugar: juegos on line, juegos tradicionales o juegos de mesa, elige tu opci\u00f3n y disfruta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En casa... \u00a1que siga el juego! - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"En la cuarentena o fase 1, sin excusas para jugar: juegos on line, juegos tradicionales o juegos de mesa, elige tu opci\u00f3n y disfruta\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T07:28:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T07:30:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/michal-parzuchowski-geNNFqfvw48-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina Castejon\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@cdecontar\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristina Castejon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\"},\"author\":{\"name\":\"Cristina Castejon\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/f6a3e33e7bb103b00b0f9321931cc3ea\"},\"headline\":\"En casa&#8230; \u00a1que siga el juego!\",\"datePublished\":\"2020-05-14T07:28:32+00:00\",\"dateModified\":\"2020-05-14T07:30:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\"},\"wordCount\":749,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"Juegos Tradicionales\",\"videojuegos\"],\"articleSection\":[\"Cultura\",\"Qu\u00e9 hacer\",\"Red MIZ\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\",\"name\":\"En casa... \u00a1que siga el juego! - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2020-05-14T07:28:32+00:00\",\"dateModified\":\"2020-05-14T07:30:16+00:00\",\"description\":\"En la cuarentena o fase 1, sin excusas para jugar: juegos on line, juegos tradicionales o juegos de mesa, elige tu opci\u00f3n y disfruta\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En casa&#8230; \u00a1que siga el juego!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/f6a3e33e7bb103b00b0f9321931cc3ea\",\"name\":\"Cristina Castejon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/2915f57f02d0a7f564ca0bdd8e3ea1cb?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/2915f57f02d0a7f564ca0bdd8e3ea1cb?s=96&d=mm&r=g\",\"caption\":\"Cristina Castejon\"},\"description\":\"De letras hasta la m\u00e9dula, siempre he pensado que la narrativa es el pastel, no la guinda. Da igual que sea en un libro o una peli, las buenas historias siempre nos enganchan. Escribo para mi blog www.cdecontar.com y para todo aquel que necesite poner alma a su marca o servicio. Me encanta mirar escaparates, contemplar fachadas y descubrir rincones escondidos. Creo que Zaragoza est\u00e1 plagada de buenas historias: ziudadanos curiosos, \u00a1callejeemos para darles caza!\",\"sameAs\":[\"http:\/\/www.cdecontar.com\",\"https:\/\/twitter.com\/cdecontar\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/cristina-castejon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En casa... \u00a1que siga el juego! - Made in Zaragoza","description":"En la cuarentena o fase 1, sin excusas para jugar: juegos on line, juegos tradicionales o juegos de mesa, elige tu opci\u00f3n y disfruta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/","og_locale":"es_ES","og_type":"article","og_title":"En casa... \u00a1que siga el juego! - Made in Zaragoza","og_description":"En la cuarentena o fase 1, sin excusas para jugar: juegos on line, juegos tradicionales o juegos de mesa, elige tu opci\u00f3n y disfruta","og_url":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2020-05-14T07:28:32+00:00","article_modified_time":"2020-05-14T07:30:16+00:00","og_image":[{"width":2560,"height":1701,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2020\/04\/michal-parzuchowski-geNNFqfvw48-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Cristina Castejon","twitter_card":"summary","twitter_creator":"@cdecontar","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Cristina Castejon","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/"},"author":{"name":"Cristina Castejon","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/f6a3e33e7bb103b00b0f9321931cc3ea"},"headline":"En casa&#8230; \u00a1que siga el juego!","datePublished":"2020-05-14T07:28:32+00:00","dateModified":"2020-05-14T07:30:16+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/"},"wordCount":749,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["Juegos Tradicionales","videojuegos"],"articleSection":["Cultura","Qu\u00e9 hacer","Red MIZ"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/","url":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/","name":"En casa... \u00a1que siga el juego! - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2020-05-14T07:28:32+00:00","dateModified":"2020-05-14T07:30:16+00:00","description":"En la cuarentena o fase 1, sin excusas para jugar: juegos on line, juegos tradicionales o juegos de mesa, elige tu opci\u00f3n y disfruta","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/en-la-cuarentena-que-siga-el-juego-recomendaciones-y-sugerencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"En casa&#8230; \u00a1que siga el juego!"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/f6a3e33e7bb103b00b0f9321931cc3ea","name":"Cristina Castejon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/2915f57f02d0a7f564ca0bdd8e3ea1cb?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/2915f57f02d0a7f564ca0bdd8e3ea1cb?s=96&d=mm&r=g","caption":"Cristina Castejon"},"description":"De letras hasta la m\u00e9dula, siempre he pensado que la narrativa es el pastel, no la guinda. Da igual que sea en un libro o una peli, las buenas historias siempre nos enganchan. Escribo para mi blog www.cdecontar.com y para todo aquel que necesite poner alma a su marca o servicio. Me encanta mirar escaparates, contemplar fachadas y descubrir rincones escondidos. Creo que Zaragoza est\u00e1 plagada de buenas historias: ziudadanos curiosos, \u00a1callejeemos para darles caza!","sameAs":["http:\/\/www.cdecontar.com","https:\/\/twitter.com\/cdecontar"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/cristina-castejon\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28274"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=28274"}],"version-history":[{"count":8,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28274\/revisions"}],"predecessor-version":[{"id":28500,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/28274\/revisions\/28500"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/28283"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=28274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=28274"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=28274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}