{"id":22092,"date":"2018-11-07T00:07:45","date_gmt":"2018-11-06T23:07:45","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=22092"},"modified":"2018-11-05T00:08:34","modified_gmt":"2018-11-04T23:08:34","slug":"meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/","title":{"rendered":"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial"},"content":{"rendered":"<p>Los dj\u2019s aragoneses Henry Ots y Dei Mill\u00e1n, conocidos como Meganimals, vuelven a la carga con Perspectives, su primer LP con 10 canciones de m\u00fasica Electr\u00f3nica Dance Comercial, que saldr\u00e1 a la venta en noviembre. Si bien, ya est\u00e1 disponible el videoclip de su primer single, Hold out, en todas las plataformas musicales actuales. Y en la sesi\u00f3n que era imposible no bailar durante su presentaci\u00f3n en Zaragoza, tambi\u00e9n pincharon su todos sus temazos y desvelaron qui\u00e9nes han participado en los remixes.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22098\" aria-describedby=\"caption-attachment-22098\" style=\"width: 918px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22098\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_448.jpg\" alt=\"\" width=\"918\" height=\"918\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_448.jpg 918w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_448-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_448-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_448-768x768.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption id=\"caption-attachment-22098\" class=\"wp-caption-text\">Meganimals, durante la presentaci\u00f3n en el plat\u00f3 de Mediapr\u00f3 a cargo de Luis Cebri\u00e1n.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Aquellas maravillosas d\u00e9cadas de los 90 y 2000 en las que la m\u00fasica Electr\u00f3nica Dance Comercial (EDC) copaba las salas y las discotecas de toda Espa\u00f1a pasaron a peor vida, pese a lo cual, todav\u00eda quedan djs vocacionales y totalmente apasionados por este g\u00e9nero que se lanzan a reflotarla m\u00e1s all\u00e1 de las tendencias, porque creen en ello y lo defienden, independientemente de lo comercial que pueda llegar a resultar.<\/p>\n<p>&nbsp;<\/p>\n<p>Innovador y raro en el panorama musical espa\u00f1ol en general y aragon\u00e9s en particular, pues en los \u00faltimos a\u00f1os se han ido sacando singles, EP\u2019s de cuatro canciones&#8230; pero no un LP con 10 temas de m\u00fasica Electr\u00f3nica Dance Comercial, es decir, que le guste a la mayor parte del p\u00fablico, como es obvio en la foto.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22102\" aria-describedby=\"caption-attachment-22102\" style=\"width: 840px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22102 size-large\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-28-at-19.48.54-1024x682.jpeg\" alt=\"\" width=\"840\" height=\"559\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-28-at-19.48.54-1024x682.jpeg 1024w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-28-at-19.48.54-300x200.jpeg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-28-at-19.48.54-768x512.jpeg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-28-at-19.48.54-1200x800.jpeg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-28-at-19.48.54.jpeg 1600w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption id=\"caption-attachment-22102\" class=\"wp-caption-text\">Ba\u00f1o de multitudes de Henry Ots durante la presentaci\u00f3n de Perspectives, by Swag Group.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Y es que sus encuestas desvelan que el 85% de los consultados prefiere este estilo musical, a pesar de que apenas se programa en nuestro pa\u00eds desde que estall\u00f3 la burbuja de la electr\u00f3nica all\u00e1 por 2017. La historia de Meganimals se remonta a 2012, cuando la EDC sonaba por todos lados, en la cresta de la ola, y todos los dj\u2019s que la pinchaban estaban triunfando. Pero aquello explot\u00f3, como todas las burbujas, porque el tarjet objetivo, m\u00e1s bien joven, ten\u00eda pocas posibilidades econ\u00f3micas de permitirse esas fiestas y festivales cada fin de semana, de forma que optaron por otros g\u00e9neros como el trap o el urban.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22099\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_449.jpg\" alt=\"\" width=\"918\" height=\"918\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_449.jpg 918w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_449-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_449-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_449-768x768.jpg 768w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Desde entonces, lamenta Henry Ots, la m\u00fasica electr\u00f3nica ya no se programa en la mayor\u00eda de las salas en Espa\u00f1a, salvo en Bilbao, o, en todo caso en los <em>fabrics<\/em>, los festivales electr\u00f3nicos, las fiestas de los pueblos y poco m\u00e1s. Los dj\u2019s entraron en dique seco, as\u00ed como las promotoras de EDC, pero resulta que el p\u00fablico siempre le demuestra a Meganimals que se viene arriba cada vez que la pinchan en sus sesiones de Animalclub en Zaragoza, donde fueron cabeza de cartel en el Oasis; en la macrofiesta de San Pepe en el Parque de Atracciones, donde miles de personas coreraron y bailaron sus propuestas; y en cada sesi\u00f3n del #TardeoZaragoza de Copacabana.<\/p>\n<p>&nbsp;<\/p>\n<p>Hasta el punto de que ambos llegaron a la conclusi\u00f3n de que el dance comercial no s\u00f3lo no est\u00e1 muerto, sino que es masivo, aunque est\u00e9 pasando \u201cpor un momento extra\u00f1o en nuestro territorio, que no en el resto del mundo\u201d, advierten. Y con ese convencimiento, despu\u00e9s de matarse mucho la cabeza cada uno por su lado, como describe su <a href=\"https:\/\/www.youtube.com\/watch?v=RYhVeym1PV8\">videoclip Hold out<\/a>, decidieron hace tres a\u00f1os arriesgarse a hacer lo que quer\u00edan y les gustaba, para demostrar que la EDC sigue estando viva y a\u00fan queda mucho por hacer.<\/p>\n<p>&nbsp;<\/p>\n<p>Su intenci\u00f3n, b\u00e1sicamente, confiesa Henry Ots, \u201ces contar, a trav\u00e9s de la m\u00fasica, nuestra propia historia, que pasa por sufrir el baj\u00f3n generalizado pero mantener esta pasi\u00f3n y empezar de nuevo\u201d. A\u00fan sabiendo que no se van a hacer ricos, se han empe\u00f1ado en ello, asegura, \u201cporque nos hace ilusi\u00f3n y es nuestra manera de demostrarle a la gente qui\u00e9nes somos y que lo que hacemos es aut\u00e9ntico, no es una tendencia ni nos hemos subido a la ola f\u00e1cil, sino que es de coraz\u00f3n, independientemente de las circunstancias y de lo que podamos ganar por ello\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre los objetivos de Meganimals se cuenta el de demostrar que \u201cs\u00ed que se puede ser profeta en Arag\u00f3n\u201d. Porque cuando empezaron resultaba todo muy f\u00e1cil, pero cuando han venido mal dadas no se han rendido, ni han colgado los cascos ni se han retirado, pese a las cr\u00edticas de la competencia en la regi\u00f3n, que, por desgracia, \u201ccuando eres comercial te quieren poner el estigma de falta de calidad, o de venderte\u201d.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 840px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-22092-1\" width=\"840\" height=\"473\" poster=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/Video-1-m4v-image.jpg\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/Video-1.m4v?_=1\" \/><a href=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/Video-1.m4v\">http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/Video-1.m4v<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>Pero hete aqu\u00ed que la gente responde fenomenal, que es lo que les llena: \u201cVer que se vuelven locos cuando le damos al play a una canci\u00f3n y acertamos con en el momento adecuado en el que justo la esperaban, todos con las manos arriba, cantando\u2026 Eso lo es todo\u201d. Ahora, adem\u00e1s de escucharles pinchar y de bailarles, los amantes del dance podr\u00e1n encontrar las 10 canciones seleccionadas de las 15 que hab\u00edan creado para Perspectives en Spotify, eTunes, Deezer, Apple Music, Soundcloud, Youtube&#8230;\u00a0 Y lo \u00fanico que desean es que las disfruten y, en un futuro cercano, la m\u00fasica EDC vuelva a recuperar su esplendor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los dj\u2019s aragoneses Henry Ots y Dei Mill\u00e1n, conocidos como Meganimals, vuelven a la carga con Perspectives, su primer LP con 10 canciones de m\u00fasica Electr\u00f3nica Dance Comercial, que saldr\u00e1 a la venta en noviembre. Si bien, ya est\u00e1 disponible el videoclip de su primer single, Hold out, en todas las plataformas musicales actuales. Y &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMeganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial\u00bb<\/span><\/a><\/p>\n","protected":false},"author":60,"featured_media":22099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[78],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial - Made in Zaragoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Los dj\u2019s aragoneses Henry Ots y Dei Mill\u00e1n, conocidos como Meganimals, vuelven a la carga con Perspectives, su primer LP con 10 canciones de m\u00fasica Electr\u00f3nica Dance Comercial, que saldr\u00e1 a la venta en noviembre. Si bien, ya est\u00e1 disponible el videoclip de su primer single, Hold out, en todas las plataformas musicales actuales. Y &hellip; Continuar leyendo &quot;Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-06T23:07:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-04T23:08:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_449.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"918\" \/>\n\t<meta property=\"og:image:height\" content=\"918\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisabeth G Iborra\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisabeth G Iborra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\"},\"author\":{\"name\":\"Elisabeth G Iborra\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c\"},\"headline\":\"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial\",\"datePublished\":\"2018-11-06T23:07:45+00:00\",\"dateModified\":\"2018-11-04T23:08:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\"},\"wordCount\":952,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"m\u00fasica\"],\"articleSection\":[\"Gente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\",\"name\":\"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2018-11-06T23:07:45+00:00\",\"dateModified\":\"2018-11-04T23:08:34+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c\",\"name\":\"Elisabeth G Iborra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g\",\"caption\":\"Elisabeth G Iborra\"},\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/elisabethgiborra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial - Made in Zaragoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/","og_locale":"es_ES","og_type":"article","og_title":"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial - Made in Zaragoza","og_description":"Los dj\u2019s aragoneses Henry Ots y Dei Mill\u00e1n, conocidos como Meganimals, vuelven a la carga con Perspectives, su primer LP con 10 canciones de m\u00fasica Electr\u00f3nica Dance Comercial, que saldr\u00e1 a la venta en noviembre. Si bien, ya est\u00e1 disponible el videoclip de su primer single, Hold out, en todas las plataformas musicales actuales. Y &hellip; Continuar leyendo \"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial\"","og_url":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_published_time":"2018-11-06T23:07:45+00:00","article_modified_time":"2018-11-04T23:08:34+00:00","og_image":[{"width":918,"height":918,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/10\/IMG_20181024_211704_449.jpg","type":"image\/jpeg"}],"author":"Elisabeth G Iborra","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"Elisabeth G Iborra","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/"},"author":{"name":"Elisabeth G Iborra","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c"},"headline":"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial","datePublished":"2018-11-06T23:07:45+00:00","dateModified":"2018-11-04T23:08:34+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/"},"wordCount":952,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["m\u00fasica"],"articleSection":["Gente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/","url":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/","name":"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2018-11-06T23:07:45+00:00","dateModified":"2018-11-04T23:08:34+00:00","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/meganimals-presenta-su-lp-perspectives-con-10-temazos-de-electronica-dance-comercial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Meganimals presenta su LP Perspectives con 10 temazos de Electr\u00f3nica Dance Comercial"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/6a4863d6589c583d59e18346910a023c","name":"Elisabeth G Iborra","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/79eaa76ada7c6991ca823fda477e731f?s=96&d=mm&r=g","caption":"Elisabeth G Iborra"},"url":"http:\/\/madeinzaragoza.es\/blog\/author\/elisabethgiborra\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/22092"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=22092"}],"version-history":[{"count":7,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/22092\/revisions"}],"predecessor-version":[{"id":22136,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/22092\/revisions\/22136"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/22099"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=22092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=22092"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=22092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}