{"id":19240,"date":"2018-02-23T10:04:13","date_gmt":"2018-02-23T09:04:13","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=19240"},"modified":"2018-03-16T14:00:07","modified_gmt":"2018-03-16T13:00:07","slug":"miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/","title":{"rendered":"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs"},"content":{"rendered":"<p><strong>Made in Zaragoza<\/strong> es un proyecto colaborativo municipal impulsado por\u00a0 Zaragoza Activa.\u00a0Naci\u00f3 hace m\u00e1s de 6 a\u00f1os con el objetivo de <strong>crear una red de econom\u00eda creativa\u00a0(artesanxs, artistas, makers, dise\u00f1adores, tenderxs innovadores\u2026)<\/strong> que uniera a todos\u00a0estos proyectos que generan un potente impacto econ\u00f3mico, social y cultural en la ciudad.<\/p>\n<p>&nbsp;<\/p>\n<p>Su misi\u00f3n es <strong>poner en valor los proyectos emprendedores m\u00e1s innovadores de Zaragoza\u00a0<\/strong>para visibilizar la vida creativa de la misma, como parte fundamental de la identidad de\u00a0una urbe que se reinventa a s\u00ed misma y se reivindica en su condici\u00f3n de enclave de\u00a0caminos y culturas.<\/p>\n<p>&nbsp;<\/p>\n<p>Casi 200 iniciativas emprendedoras se integran en Made in Zaragoza, un proyecto que se\u00a0encuentra en constante cambio y renovaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<h2>Una nueva secci\u00f3n en el blog abierta a lxs ciudadanxs<\/h2>\n<p>&nbsp;<\/p>\n<p>El objetivo principal del blog de Made in Zaragoza es <strong>abarcar temas que habitualmente no\u00a0son tratados por los medios y promover la participaci\u00f3n colaborativa de lxs ciudadanxs\u00a0<\/strong>para contar historias de sus barrios y emprendedores locales.<\/p>\n<p>&nbsp;<\/p>\n<p>Por esa raz\u00f3n, ahora ponemos en marcha <strong>MIZiudadanxs<\/strong>, una nueva secci\u00f3n a trav\u00e9s\u00a0de la que fomentar el periodismo ciudadano aplicado al \u00e1mbito de intervenci\u00f3n de\u00a0Made in Zaragoza, el de la creatividad y el talento local.<\/p>\n<p>&nbsp;<\/p>\n<p>Queremos dar voz a todas\u00a0las personas que cada d\u00eda hac\u00e9is Zaragoza trabajando, creando, dise\u00f1ando,\u00a0participando&#8230; <strong>Buscamos reporterxs que nos muestren la \u201cotra ciudad\u201d que existe y\u00a0que no se conoce.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2>\u00bfQu\u00e9 contenidos puedes enviarnos?<\/h2>\n<p>Nuestra intenci\u00f3n es combinar el trabajo profesional de nuestro equipo de redactores con\u00a0el de todxs lxs vecinxs que quieran participar activamente en la labor informativa de lo que\u00a0ocurre en sus barrios y zonas m\u00e1s cercanas. Siempre <strong>a la caza de la \u00abOtra Zaragoza\u00bb<\/strong>, una Zaragoza creativa, cultural y llena de historias inspiradoras.<\/p>\n<p>&nbsp;<\/p>\n<p>Estas son algunas ideas de contenidos que puedes enviarnos:<\/p>\n<ul>\n<li>Informaci\u00f3n de <strong>un evento creativo o social<\/strong> que va a realizarse y que todo<br \/>\nZaragoza deber\u00eda conocer.<\/li>\n<li>Un art\u00edculo en el que nos muestres <strong>c\u00f3mo ha sido ese evento al que has asistido<\/strong> y\u00a0te ha encantado.<\/li>\n<li>Informaci\u00f3n sobre un<strong> grupo o colectivo que est\u00e1 haciendo cosas incre\u00edbles<\/strong><br \/>\n<strong>en tu barrio<\/strong>.<\/li>\n<li>Un art\u00edculo sobre ese c<strong>omercio creativo de tu barrio<\/strong> que tiene miles de<br \/>\nhistorias para contar.<\/li>\n<li>Un art\u00edculo sobre ese<strong> emprendedor\/a que hay en tu calle y org<\/strong><strong>aniza<\/strong><br \/>\n<strong>actividades diferentes<\/strong> para dinamizar la zona.<\/li>\n<li>Una entrevista a una <strong>persona original y creativa<\/strong>.<\/li>\n<li><strong>\u00a1Y todo aquello que hable sobre la vida cultural y creativa de Zaragoza!<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>\u00bfC\u00f3mo enviar los contenidos?<\/h2>\n<ul>\n<li>Prepara tu texto e im\u00e1genes en un email o un Word. As\u00ed como tu nombre, apellido y una breve descripci\u00f3n sobre ti en el caso de que quieras firmar el art\u00edculo.<\/li>\n<li>Env\u00eda tus contenidos a <a href=\"mailto:madeinzgz@zaragoza.es\">madeinzgz@zaragoza.es<\/a><\/li>\n<li>Los contenidos recibidos en la secci\u00f3n MIZiudadanx ser\u00e1n publicados<br \/>\nsemanalmente. La secci\u00f3n ser\u00e1 publicada cada jueves, por lo que necesitamos que nos env\u00edes los contenidos el viernes anterior como l\u00edmite.<\/li>\n<li>En todos los casos se dar\u00e1 el cr\u00e9dito correspondiente al\/la autor\/a.<\/li>\n<li>El equipo de Made in Zaragoza se reserva el derecho de solicitar informaci\u00f3n<br \/>\nadicional para completar la publicaci\u00f3n.<\/li>\n<li>Made in Zaragoza compartir\u00e1 los contenidos a trav\u00e9s de sus redes sociales.<\/li>\n<li>Cualquier duda o consulta realizarla al correo electr\u00f3nico: madeinzgz@zaragoza.es<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>No te lo pienses m\u00e1s, \u00a1\u00e9sta es tu oportunidad! \u201cMade in Zaragoza\u201d te est\u00e1<\/strong><br \/>\n<strong>esperando.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Made in Zaragoza es un proyecto colaborativo municipal impulsado por\u00a0 Zaragoza Activa.\u00a0Naci\u00f3 hace m\u00e1s de 6 a\u00f1os con el objetivo de crear una red de econom\u00eda creativa\u00a0(artesanxs, artistas, makers, dise\u00f1adores, tenderxs innovadores\u2026) que uniera a todos\u00a0estos proyectos que generan un potente impacto econ\u00f3mico, social y cultural en la ciudad. &nbsp; Su misi\u00f3n es poner en &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs\u00bb<\/span><\/a><\/p>\n","protected":false},"author":22,"featured_media":19241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Una nueva secci\u00f3n en el blog de Made in Zaragoza abierta a lxs ciudadanxs. Buscamos periodismo ciudadano. Buscamos periodistas de barrio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Una nueva secci\u00f3n en el blog de Made in Zaragoza abierta a lxs ciudadanxs. Buscamos periodismo ciudadano. Buscamos periodistas de barrio.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"LasArmasZAC\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-23T09:04:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-16T13:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/pexels-photo-733856.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MadeinZGZ\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MadeinZGZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\"},\"author\":{\"name\":\"MadeinZGZ\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\"},\"headline\":\"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs\",\"datePublished\":\"2018-02-23T09:04:13+00:00\",\"dateModified\":\"2018-03-16T13:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\"},\"wordCount\":615,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"articleSection\":[\"Red MIZ\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\",\"name\":\"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2018-02-23T09:04:13+00:00\",\"dateModified\":\"2018-03-16T13:00:07+00:00\",\"description\":\"Una nueva secci\u00f3n en el blog de Made in Zaragoza abierta a lxs ciudadanxs. Buscamos periodismo ciudadano. Buscamos periodistas de barrio.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\",\"name\":\"MadeinZGZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"caption\":\"MadeinZGZ\"},\"description\":\"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.\",\"sameAs\":[\"LasArmasZAC\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs - Made in Zaragoza","description":"Una nueva secci\u00f3n en el blog de Made in Zaragoza abierta a lxs ciudadanxs. Buscamos periodismo ciudadano. Buscamos periodistas de barrio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/","og_locale":"es_ES","og_type":"article","og_title":"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs - Made in Zaragoza","og_description":"Una nueva secci\u00f3n en el blog de Made in Zaragoza abierta a lxs ciudadanxs. Buscamos periodismo ciudadano. Buscamos periodistas de barrio.","og_url":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"LasArmasZAC","article_published_time":"2018-02-23T09:04:13+00:00","article_modified_time":"2018-03-16T13:00:07+00:00","og_image":[{"width":1500,"height":1001,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/02\/pexels-photo-733856.jpeg","type":"image\/jpeg"}],"author":"MadeinZGZ","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"MadeinZGZ","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/"},"author":{"name":"MadeinZGZ","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32"},"headline":"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs","datePublished":"2018-02-23T09:04:13+00:00","dateModified":"2018-03-16T13:00:07+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/"},"wordCount":615,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"articleSection":["Red MIZ"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/","url":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/","name":"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2018-02-23T09:04:13+00:00","dateModified":"2018-03-16T13:00:07+00:00","description":"Una nueva secci\u00f3n en el blog de Made in Zaragoza abierta a lxs ciudadanxs. Buscamos periodismo ciudadano. Buscamos periodistas de barrio.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/miziudadanxs-blog-made-in-zaragoza-se-abre-los-ciudadanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"MIZiudadanxs: el blog de Made in Zaragoza se abre a los ciudadanxs"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32","name":"MadeinZGZ","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","caption":"MadeinZGZ"},"description":"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.","sameAs":["LasArmasZAC","https:\/\/twitter.com\/madeinzaragoza"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/19240"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=19240"}],"version-history":[{"count":7,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/19240\/revisions"}],"predecessor-version":[{"id":19456,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/19240\/revisions\/19456"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/19241"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=19240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=19240"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=19240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}