{"id":18825,"date":"2018-01-29T17:27:24","date_gmt":"2018-01-29T16:27:24","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=18825"},"modified":"2022-10-09T14:51:09","modified_gmt":"2022-10-09T13:51:09","slug":"directorio-slow-fashion-en-aragon-by-made-in-good","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/","title":{"rendered":"Directorio Slow Fashion en Arag\u00f3n by Made in good"},"content":{"rendered":"<p>La sostenibilidad ha dejado de ser una moda para convertirse en una necesidad.<br \/>\nSin embargo, a veces se utiliza simplemente como gancho para vender, y muchas marcas incluyen un plan aparentemente sostenible para convencer a los clientes de que sigan consumiendo.<\/p>\n<p>Cuando o\u00ed hablar del proyecto de Made in good \u00a0no ten\u00eda duda de que era necesario en esta ciudad.\u00a0 El consumidor tiene una tendencia natural al consumo \u00abslow\u00bb y de cercan\u00eda, y de eso en Made in Zaragoza sabemos bastante&#8230;<\/p>\n<p><a href=\"http:\/\/madeinzaragoza.es\/blog\/made-in-good-creatividad-consciente-diseno-responsable\/\">Aqu\u00ed ya os descubrimos este proyecto\u00a0<\/a>defini\u00e9ndolo como un proyecto de\u00a0 creatividad consciente para un consumo responsable. Ahora os queremos presentar su gu\u00eda DESECLIPSANDO en la que se incluyen los comercios \u00abslow fashion\u00bb en Arag\u00f3n y que Made in good present\u00f3 el pasado mes de diciembre.<\/p>\n<p>Con un dise\u00f1o minimalista y atractivo, este directorio es gratuito y digital y lo puedes descargar en su web. Aqu\u00ed te descubrimos sus claves:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18944\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/desesclipsando-redes.jpg\" alt=\"\" width=\"600\" height=\"420\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/desesclipsando-redes.jpg 549w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/desesclipsando-redes-300x210.jpg 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfQu\u00e9 tiene que tener una marca \u00abSlow\u00bb para incluirse en esta gu\u00eda?<\/strong><\/p>\n<p style=\"font-weight: 400\">Tiene que cumplir los tres par\u00e1metros del dise\u00f1o Slow:<\/p>\n<ol>\n<li style=\"font-weight: 400\">SOSTENIBLE: Prendas fabricadas con materiales reciclados, org\u00e1nicos\/ecol\u00f3gicos y que no usen t\u00f3xicos que contaminen en su producci\u00f3n y manipulaci\u00f3n.<\/li>\n<li style=\"font-weight: 400\">SOCIAL: Que todas las personas implicadas en la cadena de dise\u00f1o, producci\u00f3n, distribuci\u00f3n y venta tengan unas condiciones laborales \u00f3ptimas.<\/li>\n<li style=\"font-weight: 400\">LOCAL: Comercio de proximidad <em>Km0<\/em>, fomentando el uso y aprovechamiento de recursos locales, recuperando oficios tradicionales y su valor artesanal, y reduciendo el impacto de la huella de carbono.<\/li>\n<\/ol>\n<p style=\"font-weight: 400\"><strong>\u00bfCu\u00e1les son las etiquetas o certificaciones que se requiere a los comercios adjuntos?<\/strong><\/p>\n<p style=\"font-weight: 400\">En las prendas que realmente podemos considerar sostenibles, siempre utilizan textiles con sellos y certificaciones oficiales. El directorio DESECLIPSANDO no especifica que sellos corresponden a cada marca, principalmente porque dentro de cada una de ella, se cuenta con diferentes textiles certificados. Entre los sellos m\u00e1s conocidos podemos encontrar Fairtrade, GOTS, STeP by OEKO-TEX, Ecolabel, Cradle to Cradle, ISO, Bluesign o Fair Wear Foundation.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfQu\u00e9 comercios incluye esta gu\u00eda?<\/strong><\/p>\n<p style=\"font-weight: 400\">A Made in Good le interesa todo el \u00e1mbito creativo que sea <em>Slow<\/em>. En este caso concreto y para el directorio DESECLIPSANDO nos centramos en Moda, pues es uno de los reclamos m\u00e1s potentes del consumidor actual. Cada vez estamos m\u00e1s concienciados y sabemos que la industria del textil es la segunda mayor contaminante del planeta. Los compradores de prendas m\u00e1s sostenibles, sociales y respetuosas, demandaban informaci\u00f3n de d\u00f3nde encontrarlas. Por este motivo decidimos hacer un directorio de moda Slow en Arag\u00f3n. Lo cierto es que podr\u00eda ampliarse a otro tipo de comercios, que aunque no sean de moda, pudieran compartir filosof\u00eda Slow. Pero por el momento, no es algo que hayamos planteado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18943\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/dirctorio.jpg\" alt=\"\" width=\"600\" height=\"480\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/dirctorio.jpg 340w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/dirctorio-300x240.jpg 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p style=\"font-weight: 400\"><strong>A veces es dif\u00edcil seleccionar los proveedores para crear una marca\u00a0<em>Slow<\/em>. \u00bfQu\u00e9 recomendaciones dar\u00edas a los emprendedores que quieren unirse a esta filosof\u00eda?<\/strong><\/p>\n<p style=\"font-weight: 400\">Todas las peque\u00f1as marcas de moda tienen un problema relativo a los proveedores. Si adem\u00e1s sumamos la complejidad de los materiales sostenibles, la cuesti\u00f3n se complica a\u00fan m\u00e1s. Normalmente se venden tejidos o se imprimen las telas a gran escala. El mercado no est\u00e1 dise\u00f1ado para que sea sostenible, sino para que se produzca de manera industrial y a gran escala. Eso supone el encarecimiento de los precios y por esta raz\u00f3n a\u00fan tiene m\u00e1s valor estas marcas. Es nuestra responsabilidad apoyarlas y decidir comprar apostando por estos negocios minoritarios. Como consejo pr\u00e1ctico para los emprendedores, les dir\u00eda que para realizar el esfuerzo que requiere, es importante estar plenamente convencido y de acuerdo con esta filosof\u00eda. Si no, es muy probable abandonar a mitad camino por la frustraci\u00f3n. Tambi\u00e9n que se haga de poco a poco, introduciendo los materiales en medida que haya beneficios. Y sobre todo, que busquen una red de apoyo local con la que compartir esfuerzos y energ\u00edas en pro del objetivo. Una buena idea es comprar tejidos entre varias marcas, para que el suponga un ahorro en la compra. Despu\u00e9s se pueden estampar, te\u00f1ir y por supuesto dise\u00f1ar con estilos totalmente diferentes.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfQu\u00e9 diferencia esta gu\u00eda de otras?<\/strong><\/p>\n<p style=\"font-weight: 400\">Existen dos \u00fanicas diferencias a otras gu\u00edas que ya existen, como por ejemplo el directorio de Slow Fashion Next de su fundadora Gema G\u00f3mez, qui\u00e9n vino a presentar y ofrecer una charla al evento presentaci\u00f3n de nuestra gu\u00eda.<\/p>\n<p style=\"font-weight: 400\">Una de las diferencias es que nuestro directorio es a nivel local. Es un directorio exclusivamente de Arag\u00f3n.<\/p>\n<p style=\"font-weight: 400\">La segunda es que no solo incluye marcas, sino tambi\u00e9n tiendas multimarca que venden marcas sostenibles. Este es un directorio de marcas y tiendas Slow Fashion, cuyo objetivo era dar a conocer a los consumidores de Arag\u00f3n d\u00f3nde encontrar prendas sostenibles.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfVas a incluir m\u00e1s Comunidades?\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400\">No, porque ya entrar\u00edamos en conflicto con otros directorios nacionales que se han planteado compa\u00f1eros anteriormente. Lo interesante realmente ser\u00eda que este directorio fuera creciendo a nivel auton\u00f3mico, con m\u00e1s marcas y tiendas multimarca que surgieran en Arag\u00f3n.<\/p>\n<p style=\"font-weight: 400\">En el interior de este directorio encontramos ya varias tiendas conocidas, as\u00ed que desde Made in Zaragoza hacemos un llamamiento a todas aquellas marcas y comercios que tambi\u00e9n quieran unirse a esta filosof\u00eda.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sostenibilidad ha dejado de ser una moda para convertirse en una necesidad. Sin embargo, a veces se utiliza simplemente como gancho para vender, y muchas marcas incluyen un plan aparentemente sostenible para convencer a los clientes de que sigan consumiendo. Cuando o\u00ed hablar del proyecto de Made in good \u00a0no ten\u00eda duda de que &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDirectorio Slow Fashion en Arag\u00f3n by Made in good\u00bb<\/span><\/a><\/p>\n","protected":false},"author":34,"featured_media":18942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,1],"tags":[1275],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Directorio Slow Fashion en Arag\u00f3n by Made in good - Made in Zaragoza<\/title>\n<meta name=\"description\" content=\"Descubre el directorio de tiendas Slow Fashion en Arag\u00f3n creado por Made in good, una iniciativa que transmite la necesidad de la sostenibilidad en la moda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Directorio Slow Fashion en Arag\u00f3n by Made in good - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Descubre el directorio de tiendas Slow Fashion en Arag\u00f3n creado por Made in good, una iniciativa que transmite la necesidad de la sostenibilidad en la moda.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ElBlogdeCruella\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-29T16:27:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-09T13:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/DIRCTORIO-imprimir-3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2262\" \/>\n\t<meta property=\"og:image:height\" content=\"1895\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LeticiaStream\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LeticiaStream\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LeticiaStream\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\"},\"author\":{\"name\":\"LeticiaStream\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2d153776ff66f85c905df1d12e5f768d\"},\"headline\":\"Directorio Slow Fashion en Arag\u00f3n by Made in good\",\"datePublished\":\"2018-01-29T16:27:24+00:00\",\"dateModified\":\"2022-10-09T13:51:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\"},\"wordCount\":913,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"moda ecol\u00f3gica\"],\"articleSection\":[\"Red MIZ\",\"Tendencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\",\"name\":\"Directorio Slow Fashion en Arag\u00f3n by Made in good - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2018-01-29T16:27:24+00:00\",\"dateModified\":\"2022-10-09T13:51:09+00:00\",\"description\":\"Descubre el directorio de tiendas Slow Fashion en Arag\u00f3n creado por Made in good, una iniciativa que transmite la necesidad de la sostenibilidad en la moda.\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Directorio Slow Fashion en Arag\u00f3n by Made in good\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2d153776ff66f85c905df1d12e5f768d\",\"name\":\"LeticiaStream\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/e4848b4dd377e888d97d486ceb7ad560?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/e4848b4dd377e888d97d486ceb7ad560?s=96&d=mm&r=g\",\"caption\":\"LeticiaStream\"},\"description\":\"Blogger, emprendedora y so\u00f1adora. Enamorada de la vida y de la moda. Fiel creyente en el Karma, busco el zapato adecuado para conquistar el mundo. Si no puedo hacer algo, es porque todav\u00eda no lo he intentado.\",\"sameAs\":[\"http:\/\/www.elblogdecruella.com\",\"https:\/\/www.facebook.com\/ElBlogdeCruella\",\"http:\/\/www.linkedin.com\/in\/leticiaarroyo\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/LeticiaStream\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/leticiastream\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Directorio Slow Fashion en Arag\u00f3n by Made in good - Made in Zaragoza","description":"Descubre el directorio de tiendas Slow Fashion en Arag\u00f3n creado por Made in good, una iniciativa que transmite la necesidad de la sostenibilidad en la moda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/","og_locale":"es_ES","og_type":"article","og_title":"Directorio Slow Fashion en Arag\u00f3n by Made in good - Made in Zaragoza","og_description":"Descubre el directorio de tiendas Slow Fashion en Arag\u00f3n creado por Made in good, una iniciativa que transmite la necesidad de la sostenibilidad en la moda.","og_url":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"https:\/\/www.facebook.com\/ElBlogdeCruella","article_published_time":"2018-01-29T16:27:24+00:00","article_modified_time":"2022-10-09T13:51:09+00:00","og_image":[{"width":2262,"height":1895,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2018\/01\/DIRCTORIO-imprimir-3-1.jpg","type":"image\/jpeg"}],"author":"LeticiaStream","twitter_card":"summary","twitter_creator":"@https:\/\/twitter.com\/LeticiaStream","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"LeticiaStream","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/"},"author":{"name":"LeticiaStream","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2d153776ff66f85c905df1d12e5f768d"},"headline":"Directorio Slow Fashion en Arag\u00f3n by Made in good","datePublished":"2018-01-29T16:27:24+00:00","dateModified":"2022-10-09T13:51:09+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/"},"wordCount":913,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["moda ecol\u00f3gica"],"articleSection":["Red MIZ","Tendencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/","url":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/","name":"Directorio Slow Fashion en Arag\u00f3n by Made in good - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2018-01-29T16:27:24+00:00","dateModified":"2022-10-09T13:51:09+00:00","description":"Descubre el directorio de tiendas Slow Fashion en Arag\u00f3n creado por Made in good, una iniciativa que transmite la necesidad de la sostenibilidad en la moda.","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/directorio-slow-fashion-en-aragon-by-made-in-good\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Directorio Slow Fashion en Arag\u00f3n by Made in good"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2d153776ff66f85c905df1d12e5f768d","name":"LeticiaStream","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/e4848b4dd377e888d97d486ceb7ad560?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/e4848b4dd377e888d97d486ceb7ad560?s=96&d=mm&r=g","caption":"LeticiaStream"},"description":"Blogger, emprendedora y so\u00f1adora. Enamorada de la vida y de la moda. Fiel creyente en el Karma, busco el zapato adecuado para conquistar el mundo. Si no puedo hacer algo, es porque todav\u00eda no lo he intentado.","sameAs":["http:\/\/www.elblogdecruella.com","https:\/\/www.facebook.com\/ElBlogdeCruella","http:\/\/www.linkedin.com\/in\/leticiaarroyo","https:\/\/twitter.com\/https:\/\/twitter.com\/LeticiaStream"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/leticiastream\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/18825"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=18825"}],"version-history":[{"count":6,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/18825\/revisions"}],"predecessor-version":[{"id":35959,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/18825\/revisions\/35959"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/18942"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=18825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=18825"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=18825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}