{"id":13843,"date":"2016-12-26T00:46:10","date_gmt":"2016-12-25T23:46:10","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=13843"},"modified":"2022-04-04T22:24:23","modified_gmt":"2022-04-04T21:24:23","slug":"catalogo-de-objetos-lorena-cosba","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/","title":{"rendered":"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba"},"content":{"rendered":"<p><strong>Lorena Capdevila<\/strong>, m\u00e1s conocida como <a href=\"http:\/\/www.lorenacosba.com\/\">Lorena Cosba<\/a>,\u00a0estudi\u00f3 fotograf\u00eda art\u00edstica en la Escuela de Arte de Huesca, formaci\u00f3n que complement\u00f3\u00a0con cursos\u00a0especializados en iluminaci\u00f3n, procesos fotogr\u00e1ficos antiguos, y\u00a0monogr\u00e1ficos con fot\u00f3grafos de la talla de\u00a0Humberto Rivas,\u00a0Jos\u00e9 Manuel Navia, Eduardo Mome\u00f1e o Miguel Oriola.<\/p>\n<p>&nbsp;<\/p>\n<p>Desde 2006 hasta la fecha, ejerce como fot\u00f3grafa en su propio estudio\u00a0<a href=\"http:\/\/www.mascotastudio.com\/\">Mascotastudio Fotograf\u00eda de Mascotas<\/a>, as\u00ed como de fot\u00f3grafa freelance en publicidad, producto y retrato.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n ha participado en exposiciones individuales y colectivas en el Centro de Historias de Zaragoza, el C\u00edrculo de Bellas Artes de Lleida, la sala Xaudar\u00f3 de Monz\u00f3n, el Matadero de Huesca o el Espacio en Blanco de la Universidad San Jorge de Zaragoza.<\/p>\n<p>&nbsp;<\/p>\n<p>Y forma parte, junto a otras tres fot\u00f3grafas aragonesas (Judith Prat, Tamara Marb\u00e1n y Lara Albuixech), del Colectivo 4F, que desarrolla actividad formativa y de difusi\u00f3n de la cultura fotogr\u00e1fica en Arag\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>En su nueva exposici\u00f3n\u00a0\u201cCat\u00e1logo de objetos (que estaban tristes)\u201d, que puede\u00a0verse hasta el 15\u00a0de enero\u00a0en el <a href=\"http:\/\/www.espaciohorst.com\/\">Espacio Horst<\/a> (calle San Jorge 26), Lorena nos muestra una deliciosa y poderosa colecci\u00f3n de objetos encontrados, intervenidos\u00a0y devueltos\u00a0a la vida.\u00a0Son objetos que le\u00a0sirven para hablar de conceptos universales, que nos afectan a todos.<\/p>\n<p>&nbsp;<\/p>\n<p>Hay\u00a0transferencias fotogr\u00e1ficas, adoquines que se encontr\u00f3 en una acera, baldosas alteradas con elementos naturales, libros cosidos con hilos que van uniendo palabras, collages de fotograf\u00edas, cajas de cerillas intervenidas\u00a0con im\u00e1genes\u00a0coloreadas, zapatos con elementos naturales y hasta arena de playa y botes con l\u00e1grimas.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13900\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba1.jpg\" alt=\"\" width=\"1200\" height=\"988\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba1.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba1-300x247.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba1-768x632.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba1-1024x843.jpg 1024w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13884\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/exposicion-lorena-cosba.jpg\" alt=\"\" width=\"620\" height=\"540\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/exposicion-lorena-cosba.jpg 620w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/exposicion-lorena-cosba-300x261.jpg 300w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 es \u201cCat\u00e1logo de objetos (que estaban tristes)\u201d?<\/strong><br \/>\nLiteralmente, un cat\u00e1logo de cosas que me he ido encontrando\u00a0a lo largo de los a\u00f1os\u00a0y que he ido reutilizando e interviniendo poco a poco.\u00a0Hace unos meses decid\u00ed darles un orden y convertirlos en algo que se pudiera exhibir. Como la muestra no ten\u00eda un hilo conductor, a no ser que fuera\u00a0po\u00e9tico, el formato de cat\u00e1logo le ven\u00eda muy bien.<\/p>\n<p>Las obras que ver\u00e9is son el trabajo\u00a0de muchos a\u00f1os de ir rescatando\u00a0y transformando objetos olvidado.\u00a0Tengo una gran facilidad para encontrarme cosas por la calle, era un don que ten\u00eda\u00a0mi padre y que yo he heredado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 te inspir\u00f3 para comenzar con este proyecto?<\/strong><br \/>\nTodo lo que rodea. Por ejemplo, el ir andando por la calle, encontrar cosas que la gente abandona\u00a0y pensar, \u00bfcomo pueden tirar esto?.<\/p>\n<p>Me interesa\u00a0el\u00a0<strong>arte del objeto encontrado<\/strong>\u00a0(en ingl\u00e9s, found art o ready-made), un t\u00e9rmino que describe el arte realizado mediante el uso de objetos que normalmente no se consideran art\u00edsticos, a menudo porque tienen una funci\u00f3n no art\u00edstica, sin ocultar su origen, pero a menudo modificados. <a href=\"https:\/\/es.wikipedia.org\/wiki\/Marcel_Duchamp\">Marcel Duchamp<\/a> fue uno de los pioneros de su establecimiento a inicios del siglo XX.<\/p>\n<p>Tambi\u00e9n me fascina\u00a0la <strong>poes\u00eda visual<\/strong>,\u00a0una forma po\u00e9tica experimental en la que la imagen, el elemento pl\u00e1stico, en todas sus facetas, t\u00e9cnicas y soportes, predomina sobre el resto de los componentes.<\/p>\n<p>Tengo miles de\u00a0influencias, desde canciones a pel\u00edculas&#8230; estoy todo el d\u00eda con los ojos bien abiertos, atenta a\u00a0los est\u00edmulos\u00a0que recibo de mi\u00a0entorno.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 has querido mostrar en los objetos que componen esta exposici\u00f3n?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Que todo objeto tiene un trasfondo po\u00e9tico.\u00a0Los objetos tienen vida propia, s\u00f3lo es necesario despertarles el alma.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfHay alguna obra de \u201cCat\u00e1logo de objetos (que estaban tristes)\u201d que sea realmente especial para ti?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Todas son especiales, pero si tengo que elegir una, me quedo con la fotograf\u00eda de mi abuela colocada en una caja que encontr\u00e9 en su casa.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13866\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/lorela-lacosba-2.jpg\" alt=\"\" width=\"1200\" height=\"1316\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/lorela-lacosba-2.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/lorela-lacosba-2-274x300.jpg 274w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/lorela-lacosba-2-768x842.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/lorela-lacosba-2-934x1024.jpg 934w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13908\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba.jpg\" alt=\"\" width=\"1200\" height=\"1028\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba-300x257.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba-768x658.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba-1024x877.jpg 1024w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfCual fue tu primera c\u00e1mara?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Una <a href=\"https:\/\/www.xatakafoto.com\/guias\/camaras-clasicas-kodak-instamatic\">Kodak Instamatic<\/a>\u00a0que todav\u00eda\u00a0conservo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQue sientes al ver tus primeras fotograf\u00edas?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Que descubr\u00ed una herramienta muy\u00a0potente con la que pod\u00eda hacer cosas incre\u00edbles. La primera fotograf\u00eda que hice fue una doble exposici\u00f3n, se me olvid\u00f3 pasar\u00a0el carrete y se montaron dos im\u00e1genes\u00a0en una. Cuando la revel\u00e9 me encant\u00f3 el resultado, era magia, \u00a1un locur\u00f3n!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfCual es el \u00e1mbito de la fotograf\u00eda que m\u00e1s te gusta?\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El retrato sin duda.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bf<strong>Qu\u00e9 te ayuda a ser m\u00e1s creativa<\/strong>?<\/p>\n<p>&nbsp;<\/p>\n<p>La m\u00fasica y sobre todo la lectura; Soy una lectora compulsiva. Todos mis libros est\u00e1n subrayados y todos los rincones de mi casa est\u00e1n repletos de ideas que voy apuntando\u00a0en los espejos y las mesas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfHacia donde se mueve tu fotograf\u00eda?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>A seguir investigando. Voy haciendo lo que me pide el cuerpo, no lo pienso. Soy puro instinto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 se puede esperar el que visite \u201cCat\u00e1logo de objetos (que estaban tristes)\u201d?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Espero que encuentren esa cierta poes\u00eda que hay en lo cotidiano, y que descubran que cualquier objeto\u00a0puede tener alma y contener un mensaje interesante.<\/p>\n<p>Puedes seguir\u00a0la actividad de Lorena Cosba\u00a0a trav\u00e9s de <a href=\"http:\/\/www.lorenacosba.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">su p\u00e1gina web<\/a> o redes sociales como Instagram\u00a0y <a href=\"https:\/\/twitter.com\/lacosba\">Twitter<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13903\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba2.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba2.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba2-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba2-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba2-768x768.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba2-1024x1024.jpg 1024w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13910\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba3.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba3.jpg 1200w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba3-150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba3-300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba3-768x768.jpg 768w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/cosba3-1024x1024.jpg 1024w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Exposici\u00f3n \u201cCat\u00e1logo de objetos (que estaban tristes)\u201d<br \/>\nHasta el 15 de\u00a0Enero de 2017<br \/>\nLugar<\/strong>: Espacio Horst (Calle San Jorge 26)<\/em><br \/>\n<em><strong>Tel\u00e9fono<\/strong>: 876 705 661<\/em><br \/>\n<em><strong>Sitio web<\/strong>: <a href=\"http:\/\/www.espaciohorst.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.espaciohorst.com\/<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorena Capdevila, m\u00e1s conocida como Lorena Cosba,\u00a0estudi\u00f3 fotograf\u00eda art\u00edstica en la Escuela de Arte de Huesca, formaci\u00f3n que complement\u00f3\u00a0con cursos\u00a0especializados en iluminaci\u00f3n, procesos fotogr\u00e1ficos antiguos, y\u00a0monogr\u00e1ficos con fot\u00f3grafos de la talla de\u00a0Humberto Rivas,\u00a0Jos\u00e9 Manuel Navia, Eduardo Mome\u00f1e o Miguel Oriola. &nbsp; Desde 2006 hasta la fecha, ejerce como fot\u00f3grafa en su propio estudio\u00a0Mascotastudio Fotograf\u00eda de &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":13857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[829,6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba - Made in Zaragoza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba - Made in Zaragoza\" \/>\n<meta property=\"og:description\" content=\"Lorena Capdevila, m\u00e1s conocida como Lorena Cosba,\u00a0estudi\u00f3 fotograf\u00eda art\u00edstica en la Escuela de Arte de Huesca, formaci\u00f3n que complement\u00f3\u00a0con cursos\u00a0especializados en iluminaci\u00f3n, procesos fotogr\u00e1ficos antiguos, y\u00a0monogr\u00e1ficos con fot\u00f3grafos de la talla de\u00a0Humberto Rivas,\u00a0Jos\u00e9 Manuel Navia, Eduardo Mome\u00f1e o Miguel Oriola. &nbsp; Desde 2006 hasta la fecha, ejerce como fot\u00f3grafa en su propio estudio\u00a0Mascotastudio Fotograf\u00eda de &hellip; Continuar leyendo &quot;El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"zaragoza.guia.2\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-25T23:46:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T21:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/lorela-lacosba-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Gimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@zgzguia\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Gimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\"},\"author\":{\"name\":\"David Gimenez\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48\"},\"headline\":\"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba\",\"datePublished\":\"2016-12-25T23:46:10+00:00\",\"dateModified\":\"2022-04-04T21:24:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\"},\"wordCount\":929,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"articleSection\":[\"Cultura\",\"Gente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\",\"name\":\"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba - Made in Zaragoza\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2016-12-25T23:46:10+00:00\",\"dateModified\":\"2022-04-04T21:24:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48\",\"name\":\"David Gimenez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g\",\"caption\":\"David Gimenez\"},\"description\":\"Apasionado de internet y de los geniales rincones que ofrece la ciudad de Zaragoza. Mi objetivo es compartir con vosotros mi inquietud por descubrir lugares, personas y eventos especiales.\",\"sameAs\":[\"http:\/\/zaragozaguia.com\",\"zaragoza.guia.2\",\"https:\/\/twitter.com\/zgzguia\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/david\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba - Made in Zaragoza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/","og_locale":"es_ES","og_type":"article","og_title":"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba - Made in Zaragoza","og_description":"Lorena Capdevila, m\u00e1s conocida como Lorena Cosba,\u00a0estudi\u00f3 fotograf\u00eda art\u00edstica en la Escuela de Arte de Huesca, formaci\u00f3n que complement\u00f3\u00a0con cursos\u00a0especializados en iluminaci\u00f3n, procesos fotogr\u00e1ficos antiguos, y\u00a0monogr\u00e1ficos con fot\u00f3grafos de la talla de\u00a0Humberto Rivas,\u00a0Jos\u00e9 Manuel Navia, Eduardo Mome\u00f1e o Miguel Oriola. &nbsp; Desde 2006 hasta la fecha, ejerce como fot\u00f3grafa en su propio estudio\u00a0Mascotastudio Fotograf\u00eda de &hellip; Continuar leyendo \"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba\"","og_url":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"zaragoza.guia.2","article_published_time":"2016-12-25T23:46:10+00:00","article_modified_time":"2022-04-04T21:24:23+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/12\/lorela-lacosba-1.jpg","type":"image\/jpeg"}],"author":"David Gimenez","twitter_card":"summary","twitter_creator":"@zgzguia","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"David Gimenez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#article","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/"},"author":{"name":"David Gimenez","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48"},"headline":"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba","datePublished":"2016-12-25T23:46:10+00:00","dateModified":"2022-04-04T21:24:23+00:00","mainEntityOfPage":{"@id":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/"},"wordCount":929,"commentCount":1,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"articleSection":["Cultura","Gente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/","url":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/","name":"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba - Made in Zaragoza","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2016-12-25T23:46:10+00:00","dateModified":"2022-04-04T21:24:23+00:00","breadcrumb":{"@id":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/madeinzaragoza.es\/blog\/catalogo-de-objetos-lorena-cosba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"El cat\u00e1logo de objetos encontrados e intervenidos de Lorena Cosba"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/2ac8fd02012df8dffd581d7caebbde48","name":"David Gimenez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/7950630cc84266afd7cef6f01b2c17dc?s=96&d=mm&r=g","caption":"David Gimenez"},"description":"Apasionado de internet y de los geniales rincones que ofrece la ciudad de Zaragoza. Mi objetivo es compartir con vosotros mi inquietud por descubrir lugares, personas y eventos especiales.","sameAs":["http:\/\/zaragozaguia.com","zaragoza.guia.2","https:\/\/twitter.com\/zgzguia"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/david\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/13843"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=13843"}],"version-history":[{"count":76,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/13843\/revisions"}],"predecessor-version":[{"id":34336,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/13843\/revisions\/34336"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/13857"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=13843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=13843"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=13843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}