{"id":11985,"date":"2016-07-12T15:53:20","date_gmt":"2016-07-12T14:53:20","guid":{"rendered":"http:\/\/madeinzaragoza.es\/blog\/?p=11985"},"modified":"2016-07-12T15:53:20","modified_gmt":"2016-07-12T14:53:20","slug":"mercado-del-13-cierra-2-edicion-liga-miz","status":"publish","type":"post","link":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/","title":{"rendered":"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ"},"content":{"rendered":"<p>La sostenibilidad, la creatividad y la econom\u00eda colaborativa est\u00e1n cada vez m\u00e1s presentes en nuestros d\u00edas. Los ciudadanos son conscientes de ello, por esa raz\u00f3n, cada vez m\u00e1s, las empresas apuestan por impulsar pol\u00edticas de RSC en sus planes estrat\u00e9gicos. As\u00ed pues, nacen iniciativas como el <a title=\"Mercado del 13\" href=\"http:\/\/mercadodel13.com\" target=\"_blank\">Mercado del 13<\/a>.<\/p>\n<h2>Mercado del 13<\/h2>\n<p>Mercado del 13, impulsado por su fundadora, Eva del Ruste, organiza <strong>mercados itinerantes<\/strong> y transitorios, as\u00ed como <strong>talleres creativos de arte, moda y gastronom\u00eda<\/strong> en espacios peculiares. En Mercado del 13 organizan eventos sostenibles y colaborativos donde <strong>potencian\u00a0la econom\u00eda circular<\/strong>, es decir, no tirando nada, y <strong>aplicando\u00a0las 3R<\/strong>: Reducir, Reutilizar y Reciclar.<\/p>\n<p><a title=\"Mercado del 13\" href=\"http:\/\/mercadodel13.com\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11988 size-full\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/mercado-del-13.jpg\" alt=\"Mercado del 13\" width=\"600\" height=\"405\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/mercado-del-13.jpg 600w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/mercado-del-13-300x202.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/mercado-del-13-163x109.jpg 163w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/mercado-del-13-105x70.jpg 105w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/mercado-del-13-180x121.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/mercado-del-13-350x236.jpg 350w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p>Asimismo, <strong>Mercado del 13<\/strong> tambi\u00e9n quiere dar <strong>visibilidad a muchas enfermedades raras<\/strong>, #ER, las grandes olvidadas. Esta valiosa iniciativa dise\u00f1a experiencias, sobre todo, para dar impulso y potenciar los productos locales, de km 0, ecol\u00f3gicos y artesanales.<\/p>\n<p><strong>El arte, el reciclaje y la solidaridad son los pilares de Mercado del 13<\/strong>. As\u00ed que si te apasiona esta filosof\u00eda, no te pierdas el espacio que se abrir\u00e1 el <strong>s\u00e1bado 9 de julio y el domingo 10<\/strong> en la ciudad de <strong>Huesca<\/strong>, y pr\u00f3ximamente en m\u00e1s puntos del territorio nacional.<\/p>\n<h2>Reto Hexagonal<\/h2>\n<p>El logo del Mercado del 13 es un hex\u00e1gono que representa una tuerca, que a su vez representa esfuerzo, creatividad y buen humor. Asimismo, tambi\u00e9n emula a una colmena, s\u00edmbolo del trabajo en equipo y la cooperaci\u00f3n.<\/p>\n<p>Como no pod\u00eda ser de otra manera, Mercado del 13, te reta junto a <a title=\"Hunteet\" href=\"http:\/\/hunteet.com\" target=\"_blank\">Hunteet <\/a>a que participes en la <a title=\"Liga Made in ZGZ\" href=\"http:\/\/hunteet.com\/liga\/made-in-zgz-16\" target=\"_blank\">liga Made in ZGZ<\/a> con el <a title=\"Reto Hexagonal \" href=\"http:\/\/hunteet.com\/reto\/hexagonal\" target=\"_blank\">Reto Hexagonal<\/a>. Se trata de <strong>captar en una foto un hex\u00e1gono<\/strong> que veas en tu entorno.<\/p>\n<p><a title=\"Reto Hexagonal \" href=\"http:\/\/hunteet.com\/reto\/hexagonal\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11987\" src=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal-.jpg\" alt=\"Reto Hexagonal del Mercado del 13\" width=\"600\" height=\"600\" srcset=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal-.jpg 650w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--150x150.jpg 150w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--300x300.jpg 300w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--160x160.jpg 160w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--40x40.jpg 40w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--70x70.jpg 70w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--625x625.jpg 625w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--180x180.jpg 180w, http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal--350x350.jpg 350w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p>La mejor foto se llevar\u00e1 una caja en forma de hex\u00e1gono llena de sorpresas en su interior.<\/p>\n<p><strong>\u00a1An\u00edmate a participar con Mercado del 13, Hunteet y Made in ZGZ!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sostenibilidad, la creatividad y la econom\u00eda colaborativa est\u00e1n cada vez m\u00e1s presentes en nuestros d\u00edas. Los ciudadanos son conscientes de ello, por esa raz\u00f3n, cada vez m\u00e1s, las empresas apuestan por impulsar pol\u00edticas de RSC en sus planes estrat\u00e9gicos. As\u00ed pues, nacen iniciativas como el Mercado del 13. Mercado del 13 Mercado del 13, &hellip; <a href=\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMercado del 13 cierra la II edici\u00f3n de la liga MIZ\u00bb<\/span><\/a><\/p>\n","protected":false},"author":22,"featured_media":11987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[612],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mercado del 13 cierra la II edici\u00f3n de la liga MIZ 16<\/title>\n<meta name=\"description\" content=\"Mercado del 13, te reta junto a Hunteet a que participes en la liga Made in ZGZ con el Reto Hexagonal. Capta en una foto un hex\u00e1gono que veas en tu entorno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ 16\" \/>\n<meta property=\"og:description\" content=\"Mercado del 13, te reta junto a Hunteet a que participes en la liga Made in ZGZ con el Reto Hexagonal. Capta en una foto un hex\u00e1gono que veas en tu entorno\" \/>\n<meta property=\"og:url\" content=\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\" \/>\n<meta property=\"og:site_name\" content=\"Made in Zaragoza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\" \/>\n<meta property=\"article:author\" content=\"LasArmasZAC\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-12T14:53:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MadeinZGZ\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:site\" content=\"@madeinzaragoza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MadeinZGZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\"},\"author\":{\"name\":\"MadeinZGZ\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\"},\"headline\":\"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ\",\"datePublished\":\"2016-07-12T14:53:20+00:00\",\"dateModified\":\"2016-07-12T14:53:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"keywords\":[\"mercado\"],\"articleSection\":[\"Red MIZ\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\",\"url\":\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\",\"name\":\"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ 16\",\"isPartOf\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\"},\"datePublished\":\"2016-07-12T14:53:20+00:00\",\"dateModified\":\"2016-07-12T14:53:20+00:00\",\"description\":\"Mercado del 13, te reta junto a Hunteet a que participes en la liga Made in ZGZ con el Reto Hexagonal. Capta en una foto un hex\u00e1gono que veas en tu entorno\",\"breadcrumb\":{\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/madeinzaragoza.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#website\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"name\":\"Made in Zaragoza\",\"description\":\"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#organization\",\"name\":\"Made In Zaragoza\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/madeinzaragoza.es\/\",\"https:\/\/www.facebook.com\/madeinzaragoza.es\/\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"contentUrl\":\"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png\",\"width\":193,\"height\":176,\"caption\":\"Made In Zaragoza\"},\"image\":{\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32\",\"name\":\"MadeinZGZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g\",\"caption\":\"MadeinZGZ\"},\"description\":\"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.\",\"sameAs\":[\"LasArmasZAC\",\"https:\/\/twitter.com\/madeinzaragoza\"],\"url\":\"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ 16","description":"Mercado del 13, te reta junto a Hunteet a que participes en la liga Made in ZGZ con el Reto Hexagonal. Capta en una foto un hex\u00e1gono que veas en tu entorno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/","og_locale":"es_ES","og_type":"article","og_title":"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ 16","og_description":"Mercado del 13, te reta junto a Hunteet a que participes en la liga Made in ZGZ con el Reto Hexagonal. Capta en una foto un hex\u00e1gono que veas en tu entorno","og_url":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/","og_site_name":"Made in Zaragoza","article_publisher":"https:\/\/www.facebook.com\/madeinzaragoza.es\/","article_author":"LasArmasZAC","article_published_time":"2016-07-12T14:53:20+00:00","og_image":[{"width":650,"height":650,"url":"http:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2016\/07\/reto-hexagonal-.jpg","type":"image\/jpeg"}],"author":"MadeinZGZ","twitter_card":"summary","twitter_creator":"@madeinzaragoza","twitter_site":"@madeinzaragoza","twitter_misc":{"Escrito por":"MadeinZGZ","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#article","isPartOf":{"@id":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/"},"author":{"name":"MadeinZGZ","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32"},"headline":"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ","datePublished":"2016-07-12T14:53:20+00:00","dateModified":"2016-07-12T14:53:20+00:00","mainEntityOfPage":{"@id":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"keywords":["mercado"],"articleSection":["Red MIZ"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/","url":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/","name":"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ 16","isPartOf":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#website"},"datePublished":"2016-07-12T14:53:20+00:00","dateModified":"2016-07-12T14:53:20+00:00","description":"Mercado del 13, te reta junto a Hunteet a que participes en la liga Made in ZGZ con el Reto Hexagonal. Capta en una foto un hex\u00e1gono que veas en tu entorno","breadcrumb":{"@id":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/madeinzaragoza.es\/blog\/mercado-del-13-cierra-2-edicion-liga-miz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/madeinzaragoza.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Mercado del 13 cierra la II edici\u00f3n de la liga MIZ"}]},{"@type":"WebSite","@id":"https:\/\/madeinzaragoza.es\/blog\/#website","url":"https:\/\/madeinzaragoza.es\/blog\/","name":"Made in Zaragoza","description":"Blog de MadeinZGZ, Red de Econom\u00eda Creativa de Zaragoza","publisher":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madeinzaragoza.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madeinzaragoza.es\/blog\/#organization","name":"Made In Zaragoza","url":"https:\/\/madeinzaragoza.es\/blog\/","sameAs":["https:\/\/www.instagram.com\/madeinzaragoza.es\/","https:\/\/www.facebook.com\/madeinzaragoza.es\/","https:\/\/twitter.com\/madeinzaragoza"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/madeinzaragoza.es\/blog\/wp-content\/uploads\/2022\/05\/logo.png","width":193,"height":176,"caption":"Made In Zaragoza"},"image":{"@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/59f4073cf7e7bc2b2f33b48241478a32","name":"MadeinZGZ","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madeinzaragoza.es\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/23c2456a35687aa268b52997d8f142d1?s=96&d=mm&r=g","caption":"MadeinZGZ"},"description":"Red de comercios y emprendedores creativos de Zaragoza impulsada por ZGZ Activa.","sameAs":["LasArmasZAC","https:\/\/twitter.com\/madeinzaragoza"],"url":"http:\/\/madeinzaragoza.es\/blog\/author\/madeinzgz\/"}]}},"_links":{"self":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/11985"}],"collection":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/comments?post=11985"}],"version-history":[{"count":4,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/11985\/revisions"}],"predecessor-version":[{"id":12028,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/posts\/11985\/revisions\/12028"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media\/11987"}],"wp:attachment":[{"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/media?parent=11985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/categories?post=11985"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/madeinzaragoza.es\/blog\/wp-json\/wp\/v2\/tags?post=11985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}